{"id":58444,"date":"2017-03-03T00:00:00","date_gmt":"2017-03-03T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20170303\/regresan-al-tribunal-taxistas-y-uber\/"},"modified":"2025-07-22T23:50:37","modified_gmt":"2025-07-22T23:50:37","slug":"regresan-al-tribunal-taxistas-y-uber","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170303\/regresan-al-tribunal-taxistas-y-uber\/","title":{"rendered":"Regresan al tribunal taxistas y Uber"},"content":{"rendered":"<p>El portavoz del grupo Puerto Rico Operadores Tur\u00edsticos, Gu\u00edas y Excursionistas (PROTGE), Jose Poupal, inform\u00f3 el viernes que se radic\u00f3 una demanda contra el Departamento de Transportaci\u00f3n y Obras P\u00fablicas y la Compa\u00f1\u00eda de Turismo de Puerto Rico, por supuesto incumplimiento a Ley 282.<\/p>\n<p>&#8216;En todo momento los transportistas hemos actuado de buena fe y hemos agotado los recursos necesarios para defender nuestros derechos. Ya fuimos en una ocasi\u00f3n al tribunal y hay una sentencia a nuestro favor que cay\u00f3 en o\u00eddos sordos, pues ya es hora que regresemos a este foro para defender el trabajo de los transportistas. No descansaremos hasta que se nos haga justicia&#8217;, expres\u00f3 Poupal en declaraciones escritas.<\/p>\n<p>Poupal mencion\u00f3 que la demanda fue radicada por el licenciado \u00c1ngel Marrero en el Tribunal de San Juan, y que ya se recibi\u00f3 la fecha de la citaci\u00f3n de las partes para el pr\u00f3ximo jueves, 9 de marzo. La Federaci\u00f3n de Taxis de Puerto Rico y la Uni\u00f3n de Transporte y Ramas Anexas son parte demandante.<\/p><div class=\"notic-content-middle\" id=\"notic-702066827\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>En la demanda se incluy\u00f3 al Departamento de Transportaci\u00f3n y Obras P\u00fablicas, porque dicha agencia emiti\u00f3 un reglamento para permitir que las Empresas de Redes de Transporte como Uber brinden servicios, inclusive en las zonas tur\u00edsticas.<\/p>\n<p>&#8216;Claramente, ning\u00fan reglamento puede ir sobre la ley, y ellos lo est\u00e1n haciendo. Hay mucha desinformaci\u00f3n en la calle, y es lamentable, que esa falta de conocimiento comience en las mismas agencias que nos regulan&#8217;, agreg\u00f3.<\/p>\n<p>Se\u00f1al\u00f3 que hubo un acuerdo con funcionarios de La Fortaleza para fiscalizar las zonas tur\u00edsticas que al momento no se ha cumplido.<\/p>","protected":false},"excerpt":{"rendered":"<p>El portavoz del grupo Puerto Rico Operadores Tur\u00edsticos, Gu\u00edas y Excursionistas (PROTGE), Jose Poupal, inform\u00f3 el viernes que se radic\u00f3 una demanda contra el Departamento de Transportaci\u00f3n y Obras P\u00fablicas y la Compa\u00f1\u00eda de Turismo de Puerto Rico, por supuesto incumplimiento a Ley 282. &#8216;En todo momento los transportistas hemos actuado de buena fe y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":560965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-58444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/58444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=58444"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/58444\/revisions"}],"predecessor-version":[{"id":560966,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/58444\/revisions\/560966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/560965"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=58444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=58444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=58444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}