{"id":57955,"date":"2015-09-24T00:00:00","date_gmt":"2015-09-24T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20150924\/facebook-sufre-averia-a-nivel-mundial\/"},"modified":"2025-07-26T17:35:47","modified_gmt":"2025-07-26T17:35:47","slug":"facebook-sufre-averia-a-nivel-mundial","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20150924\/facebook-sufre-averia-a-nivel-mundial\/","title":{"rendered":"Facebook sufre aver\u00eda a nivel mundial"},"content":{"rendered":"<p>Est\u00e1s en Facebook y de momento: &#8216;Perd\u00f3n, algo sali\u00f3 mal. Error&#8217;. Refrescas la p\u00e1gina, vuelves a escribir la direcci\u00f3n de la red social, pero nada.<\/p>\n<p>Aunque ya parece haber regresado a la normalidad, la red social Facebook sufri\u00f3 una ca\u00edda a nivel mundial en la que todos su usuarios vieron el mismo mensaje citado arriba.<\/p><div class=\"notic-content-middle\" id=\"notic-2532830554\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>A\u00fan Facebook no ha hecho expresiones sobre el suceso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Est\u00e1s en Facebook y de momento: &#8216;Perd\u00f3n, algo sali\u00f3 mal. Error&#8217;. Refrescas la p\u00e1gina, vuelves a escribir la direcci\u00f3n de la red social, pero nada. Aunque ya parece haber regresado a la normalidad, la red social Facebook sufri\u00f3 una ca\u00edda a nivel mundial en la que todos su usuarios vieron el mismo mensaje citado arriba. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":584383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-57955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57955"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57955\/revisions"}],"predecessor-version":[{"id":584406,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57955\/revisions\/584406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/584383"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}