{"id":57823,"date":"2015-12-09T00:00:00","date_gmt":"2015-12-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20151209\/merkel-persona-del-ano-segun-time\/"},"modified":"2025-07-25T09:56:28","modified_gmt":"2025-07-25T09:56:28","slug":"merkel-persona-del-ano-segun-time","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20151209\/merkel-persona-del-ano-segun-time\/","title":{"rendered":"Merkel, persona del a\u00f1o seg\u00fan Time"},"content":{"rendered":"<p>La revista estadounidense Time eligi\u00f3 hoy, miercoles, como persona del a\u00f1o a la canciller alemana, Angela Merkel, que recibi\u00f3 el premio por el que tambien estaban nominados, entre otros, el magnate Donald Trump, el presidente de Rusia, Vladimir Putin, o el l\u00edder del Estado Isl\u00e1mico, Abu Bakr al-Baghdadi, que qued\u00f3 segundo.<\/p>\n<p>Time escogi\u00f3 a Merkel por su gesti\u00f3n de la crisis europea, la actitud de Alemania para acoger a refugiados y por &#8216;mantenerse firme ante la tiran\u00eda y el oportunismo y por proporcionar un liderazgo moral inalterable en un mundo donde escasea&#8217;, explic\u00f3 la revista.<\/p>\n<p>La editora del semanario, Nancy Gibbs, explic\u00f3 hoy en el programa The Today Show, de la cadena de televisi\u00f3n NBC, que la canciller merece este premio porque &#8216;nadie fue puesta a prueba como ella&#8217;, y record\u00f3 la crisis econ\u00f3mica en Europa, la vuelta del terrorismo al viejo continente y la gesti\u00f3n de los refugiados.<\/p>\n<p>&#8216;Controla la cuarta mayor econom\u00eda del mundo y este a\u00f1o se ha distinguido de los dem\u00e1s l\u00edderes mundiales&#8217;, explic\u00f3 Gibbs.<\/p>\n<p>Seg\u00fan la publicaci\u00f3n, Merkel desempe\u00f1\u00f3 este a\u00f1o un rol &#8216;indispensable&#8217; en la gesti\u00f3n de la crisis de la deuda griega y &#8216;lider\u00f3&#8217; la respuesta de Occidente ante el &#8216;robo&#8217; del presidente ruso, Vladimir Putin, en Ucrania.<\/p>\n<p>La pol\u00edtica alemana se convierte as\u00ed en la cuarta mujer en recibir el singular galard\u00f3n de la revista Time. Antes lo fueron la Duquesa de Windsor, Wallis Simpson (1936), la reina de Inglaterra Elizabeth II (1952) y la pol\u00edtica filipina Coraz\u00f3n &#8216;Cory&#8217; Aquino (1986).<\/p>\n<p>Frente al &#8216;pasado nacionalista, genocida y militarista&#8217; de Alemania, la canciller &#8216;blandi\u00f3 un conjunto diferente de valores -humanidad, generosidad, tolerancia- para demostrar c\u00f3mo la gran fortaleza de Alemania puede ser usada para salvar, en lugar de para destruir&#8217;, enfatiz\u00f3 Time.<\/p><div class=\"notic-content-middle\" id=\"notic-1342078998\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Antes de Merkel, s\u00f3lo tres alemanes hab\u00edan sido elegidos como &#8216;hombre del a\u00f1o&#8217; por la revista, t\u00edtulo que destaca la influencia de un personaje sobre el acontecer mundial, ya sea &#8216;por lo mejor&#8217; o &#8216;por lo peor&#8217;, record\u00f3 Gibbs, por lo que el primer alem\u00e1n en recibir esta distinci\u00f3n, en 1938, fue Adolf Hitler, nacido en Austria, por someter a Alemania y haber cambiado Europa.<\/p>\n<p>El podio lo completan el l\u00edder del grupo terrorista Estado Isl\u00e1mico (EI), Abu Bakr al-Baghdadi, en segunda posici\u00f3n, y el pol\u00e9mico magnate estadounidense Donald Trump, que qued\u00f3 tercero.<\/p>\n<p>Nancy Gibbs explic\u00f3 que Abu Bakr al-Baghdadi &#8216;transform\u00f3 un poder regional en una franquicia terrorista internacional&#8217;, pero destac\u00f3 que el l\u00edder del EI &#8216;fue oportunista&#8217; porque &#8216;\u00e9l no creo la anarqu\u00eda en Oriente Medio ni Internet&#8217;, solo &#8216;sac\u00f3 partido&#8217; del contexto actual.<\/p>\n<p>Por otro lado, Gibbs inst\u00f3 a Trump a &#8216;ganarse el galard\u00f3n con votos&#8217; el pr\u00f3ximo a\u00f1o, aunque la respuesta del magnate no se hizo esperar en Twitter, d\u00f3nde dijo que &#8216;pese a ser el gran favorito, Time nunca le escoger\u00eda como Persona del a\u00f1o&#8217; y que, por contra, &#8216;eligieron a la persona que est\u00e1 arruinando Alemania&#8217;.<\/p>\n<p>El galard\u00f3n, llamado &#8216;Hombre del a\u00f1o&#8217; hasta 1999, premi\u00f3 en 2014 a los profesionales que lucharon contra la epidemia de \u00e9bola en \u00c1frica Occidental, &#8216;por arriesgar, por persistir, por sacrificar y por salvar vidas&#8217;.<\/p>\n<p>En los \u00faltimos a\u00f1os la distinci\u00f3n fue entregada, entre otros, al Papa Francisco (2013), el presidente de Estados Unidos, Barack Obama (2012), a la figura del &#8216;manifestante&#8217; en 2011 o al fundador de Facebook, Mark Zuckerberg, en 2010.<\/p>","protected":false},"excerpt":{"rendered":"<p>La revista estadounidense Time eligi\u00f3 hoy, miercoles, como persona del a\u00f1o a la canciller alemana, Angela Merkel, que recibi\u00f3 el premio por el que tambien estaban nominados, entre otros, el magnate Donald Trump, el presidente de Rusia, Vladimir Putin, o el l\u00edder del Estado Isl\u00e1mico, Abu Bakr al-Baghdadi, que qued\u00f3 segundo. Time escogi\u00f3 a Merkel [&hellip;]<\/p>","protected":false},"author":0,"featured_media":572737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-57823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57823"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57823\/revisions"}],"predecessor-version":[{"id":572752,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57823\/revisions\/572752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/572737"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}