{"id":57801,"date":"2014-12-11T00:00:00","date_gmt":"2014-12-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/en-serio\/la-calle\/20141211\/roban-miles-de-cajas-de-huevos\/"},"modified":"2025-08-17T06:57:06","modified_gmt":"2025-08-17T06:57:06","slug":"roban-miles-de-cajas-de-huevos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20141211\/roban-miles-de-cajas-de-huevos\/","title":{"rendered":"Roban miles de cajas de huevos"},"content":{"rendered":"<p>Las autoridades investigan varios incidentes reportados el miercoles por separado en el \u00e1rea policiaca de Bayam\u00f3n, entre los que est\u00e1 el robo de varios contenedores con huevos, un asalto a la empleada de una tienda a punta de jeringuilla y el escalamiento de dos escuelas.<\/p>\n<p>Seg\u00fan el informe policiaco, el primer escalamiento ocurri\u00f3, a las 5:28 de la madrugada, cuando se aleg\u00f3 que delincuentes rompieron el candado del port\u00f3n principal del almac\u00e9n Egg Market, en Bayam\u00f3n. Del lugar se apropiaron de tres contenedores refrigerados con 2,606 cajas de huevos, valoradas en 148,542 d\u00f3lares.<\/p>\n<p>La Polic\u00eda indic\u00f3 que en horas de la ma\u00f1ana del jueves localizaron en la Zona Portuaria en San Juan uno de los vagones con huevos que fueron robados, pero no as\u00ed los contenedores de huevos.<\/p>\n<p>Por otro lado, la Polic\u00eda indico que cerca de la 1:04 de la tarde, se alert\u00f3 a las autoridades sobre una agresi\u00f3n en la tienda All Ways 99 que ubica en el centro comercial Centro Grand Caribe Mall en Vega Baja. La gerente del establecimiento de 41 a\u00f1os, fue agredida con una jeringuilla por una mujer conocida como &#8216;la muda&#8217;. La agresora le ocasion\u00f3 una herida punzante con dicho objeto para apropiarse de tres cajas de bombillitas de navidad. Luego huy\u00f3 del establecimiento y se desconoce su paradero.<\/p><div class=\"notic-content-middle\" id=\"notic-2169637617\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Por otro lado, las autoridades indicaron que a eso de las 3:29 de la tarde, se report\u00f3 otro escalamiento en la escuela Miguel Cervantes en Bayam\u00f3n. Individuos escalaron varios salones del plantel escolar y se robaron un proyector y varios uniformes.<\/p>\n<p>Por \u00faltimo, la Uniformada indic\u00f3 que cerca de las 9:51 de la noche, se report\u00f3 a las autoridades que desconocidos forzaron el port\u00f3n de acceso al segundo nivel de la Escuela Juan Ram\u00f3n Jim\u00e9nez en Bayam\u00f3n. Del lugar se apropiaron de una computadora port\u00e1til y vandalizaron varios salones regulares y de tecnolog\u00eda. En ninguno de estos dos casos, se estim\u00f3 el valor de la propiedad.<\/p>\n<p>Se exhorta a la ciudadan\u00eda a comunicarse con la Polic\u00eda de manera confidencial si conocen de la comisi\u00f3n de un delito, o posee informaci\u00f3n que ayude a esclarecerlo. Deben llamar al 787-343-2020 o acceder el portal www.3432020.com y la aplicaci\u00f3n BastayaPR.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las autoridades investigan varios incidentes reportados el miercoles por separado en el \u00e1rea policiaca de Bayam\u00f3n, entre los que est\u00e1 el robo de varios contenedores con huevos, un asalto a la empleada de una tienda a punta de jeringuilla y el escalamiento de dos escuelas. Seg\u00fan el informe policiaco, el primer escalamiento ocurri\u00f3, a las [&hellip;]<\/p>","protected":false},"author":0,"featured_media":855299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-57801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57801"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57801\/revisions"}],"predecessor-version":[{"id":855363,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57801\/revisions\/855363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/855299"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}