{"id":57671,"date":"2014-03-23T00:00:00","date_gmt":"2014-03-23T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20140323\/satelite-frances-aporta-nuevas-imagenes-de-objetos-en-busqueda-de-avion-mal\/"},"modified":"2025-08-20T06:45:25","modified_gmt":"2025-08-20T06:45:25","slug":"satelite-frances-aporta-nuevas-imagenes-de-objetos-en-busqueda-de-avion-mal","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140323\/satelite-frances-aporta-nuevas-imagenes-de-objetos-en-busqueda-de-avion-mal\/","title":{"rendered":"Sat\u00e9lite franc\u00e9s aporta nuevas im\u00e1genes de objetos en b\u00fasqueda de avi\u00f3n mal"},"content":{"rendered":"<p>Kuala Lumpur &#8211; Un satelite frances hall\u00f3 nuevas im\u00e1genes de objetos en el oceano \u00cdndico que podr\u00edan pertenecer al avi\u00f3n de Malaysia Airlines desaparecido, confirmaron hoy las autoridades de Malasia.<\/p>\n<p>Esta es la tercera ocasi\u00f3n, en menos de una semana, en la que se aportan im\u00e1genes sobre posibles restos de la aeronave que desapareci\u00f3 con 239 personas a bordo el pasado 8 de marzo.<\/p>\n<p>El ministro malasio de Transporte, Hishammuddin Hussein, indic\u00f3 en un comunicado que esta nueva pista fue &#8216;inmediatamente&#8217; transmitida al organismo australiano que coordina el rescate en el vector sur.<\/p>\n<p>Hishammuddin, no obstante, no aport\u00f3 detalles sobre el tama\u00f1o o la localizaci\u00f3n exacta de estos nuevos objetos.<\/p>\n<p>El pasado jueves, el primer ministro de Australia, Tony Abbott, anunci\u00f3 ante el Parlamento de su pa\u00eds el hallazgo de dos objetos, uno de 24 metros y otro de 5, a unos 2,500 kil\u00f3metros al suroeste de la ciudad australiana de Perth.<\/p>\n<p>Desde entonces, la Autoridad Australiana de Seguridad Mar\u00edtima se ha encargado de coordinar el operativo internacional de aviones y barcos que peinan la regi\u00f3n.<\/p>\n<p>En la b\u00fasqueda participan efectivos de Australia, China, Estados Unidos, Jap\u00f3n, Nueva Zelanda y Reino Unido.<\/p>\n<p>Ayer, el Gobierno de Pek\u00edn anunci\u00f3 el hallazgo de im\u00e1genes tambi\u00e9n v\u00eda sat\u00e9lite de un objeto de 22 metros de largo por 13 de ancho a unos 120 kil\u00f3metros del primer lugar.<\/p>\n<p>Este domingo, ocho aviones -cuatro militares y cuatro civiles- y varios barcos rastrearon sin \u00e9xito por cuarto d\u00eda la enorme regi\u00f3n que el organismo australiano extendi\u00f3 a 59,000 kil\u00f3metros cuadrados ante la posibilidad de que los objetos fueran arrastrados por las corrientes marinas.<\/p>\n<p>Un avi\u00f3n civil que participa en el operativo avist\u00f3 ayer una serie de objetos peque\u00f1os en la zona, entre ellos una tarima de madera, que a\u00fan no se ha confirmado si pertenece al Boeing 777-200 desaparecido.<\/p><div class=\"notic-content-middle\" id=\"notic-2338577804\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Evidentemente antes de dar detalles, necesitamos recuperar este material porque a\u00fan es demasiado pronto para hacer un comentario definitivo&#8217;, declar\u00f3 esta jornada Abbott desde Pap\u00faa Nueva Guinea.<\/p>\n<p>Sin embargo, oficiales australianos informaron hoy a Malasia que no han encontrado nuevas se\u00f1ales del avi\u00f3n, asegur\u00f3 el ministro malasio de Transporte.<\/p>\n<p>Un experto australiano en misiones de rescate remarc\u00f3 al canal ABC las dificultades de la zona donde se busca, entre la isla ant\u00e1rtica Heard y Perth, que posee un marcado fuerte oleaje y cambios s\u00fabitos en las condiciones meteorol\u00f3gicas.<\/p>\n<p>A esto hay que a\u00f1adir &#8216;la corriente circumpolar, que va de oeste a este alrededor de la Ant\u00e1rtica, y que pasa por debajo de Australia, marcando su clima&#8217;, subray\u00f3 el experto<\/p>\n<p>Esta corriente ant\u00e1rtica se mueve a una velocidad media de 1.8 kil\u00f3metros por hora, as\u00ed que en un per\u00edodo de cuatro d\u00edas, seg\u00fan el tama\u00f1o de los restos y c\u00f3mo son arrastrados por el agua, podr\u00eda desplazarlos unos 200 kil\u00f3metros.<\/p>\n<p>El avi\u00f3n de Malaysia Airlines desapareci\u00f3 del radar unos 40 minutos despu\u00e9s de despegar de Kuala Lumpur con destino a Pekin el pasado 8 de marzo con 239 personas a bordo y desde entonces no se sabe nada de \u00e9l, ni se han encontrado sus restos.<\/p>\n<p>Lo que s\u00ed se conoce es que el avi\u00f3n cambi\u00f3 de rumbo y lleg\u00f3 al Estrecho de Malaca, pero nada m\u00e1s con certeza a partir de ah\u00ed.<\/p>\n<p>Los militares Erica Ross y Francis Enriquez, que forman parte de la tripulaci\u00f3n del P3 Orion de las Fuerzas A\u00e9reas de Estados Unidos en las tareas de rescate, aseguraron a la agencia malasia Bernama que no cejar\u00e1n en su intento por encontrar el avi\u00f3n.<\/p>\n<p>&#8216;Nosotros vamos a estar aqu\u00ed tanto tiempo como sea necesario&#8217;, declar\u00f3 Enriquez.<\/p>","protected":false},"excerpt":{"rendered":"<p>Kuala Lumpur &#8211; Un satelite frances hall\u00f3 nuevas im\u00e1genes de objetos en el oceano \u00cdndico que podr\u00edan pertenecer al avi\u00f3n de Malaysia Airlines desaparecido, confirmaron hoy las autoridades de Malasia. Esta es la tercera ocasi\u00f3n, en menos de una semana, en la que se aportan im\u00e1genes sobre posibles restos de la aeronave que desapareci\u00f3 con [&hellip;]<\/p>","protected":false},"author":0,"featured_media":880055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-57671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57671"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57671\/revisions"}],"predecessor-version":[{"id":880095,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57671\/revisions\/880095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/880055"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}