{"id":57361,"date":"2011-12-30T00:00:00","date_gmt":"2011-12-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20111230\/incendio-en-submarino-nuclear-ruso\/"},"modified":"2025-08-27T13:17:57","modified_gmt":"2025-08-27T13:17:57","slug":"incendio-en-submarino-nuclear-ruso","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20111230\/incendio-en-submarino-nuclear-ruso\/","title":{"rendered":"Incendio en submarino nuclear ruso"},"content":{"rendered":"<p>MOSC\u00da &#8211; Los bomberos tardaron poco m\u00e1s de nueve horas en controlar el incendio en el submarino nuclear ruso &#8216;Yekaterimburg&#8217;, que a\u00fan no ha sido sofocado, inform\u00f3 hoy el Ministerio de Rusia para Situaciones de Emergencia.<\/p>\n<p>&#8216;A las 01.40 hora de Mosc\u00fa (21.40 GMT del jueves) el incendio qued\u00f3 controlado&#8217;, anunci\u00f3 el titular de esa cartera, Sergu\u00e9i Shoigu, citado por las agencias rusas.<\/p>\n<p>Las autoridades rusas hab\u00edan informado de que el fuego se hab\u00eda declarado sobre las 12.20 GMT de ayer durante las labores de reparaci\u00f3n del sumergible nuclear en los astilleros de Rosliakovo, en Murmansk, en el noroeste del pa\u00eds.<\/p>\n<p>Aunque el siniestro est\u00e1 bajo control, los bomberos a\u00fan no consiguen apagar el fuego, que afecta a una superficie de 150 metros cuadrados, declar\u00f3 esta ma\u00f1ana un portavoz de Emergencia a la agencia oficial rusa RIA-N\u00f3vosti.<\/p>\n<p>Agreg\u00f3 que los mediciones efectuadas en la regi\u00f3n de Murmansk indican que los niveles de radiaci\u00f3n se encuentran dentro de los rangos normales.<\/p><div class=\"notic-content-middle\" id=\"notic-3106174736\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El Ministerio de Defensa comunic\u00f3 que el incendio comenz\u00f3 en los andamios de madera instalados junto al submarino para los trabajos de reparaci\u00f3n y se propag\u00f3 luego al casco exterior ligero del nav\u00edo.<\/p>\n<p>De acuerdo con el parte oficial, antes de que el submarino entrara en reparaciones fueron apagados sus dos reactores nucleares y desprovisto de todo su armamento, tal y como lo establece el reglamento.<\/p>\n<p>&#8216;No hay amenaza a la vida de las personas&#8217;, escribi\u00f3 hoy en su cuenta de Twitter el viceprimer ministro responsable de la industria militar, Dmitri Rogozin, quien comunic\u00f3 que el comandante en jefe de la Armada, Sergu\u00e9i Visotski, y otros altos mandos navales se desplazaron anoche a los astilleros de Rosliakovo.<\/p>\n<p>El &#8216;Yekaterimburg&#8217;, de 167 metros de eslora, entr\u00f3 en servicio en 1985 y tiene capacidad para portar 16 misiles intercontinentales de combustible l\u00edquido.<\/p>","protected":false},"excerpt":{"rendered":"<p>MOSC\u00da &#8211; Los bomberos tardaron poco m\u00e1s de nueve horas en controlar el incendio en el submarino nuclear ruso &#8216;Yekaterimburg&#8217;, que a\u00fan no ha sido sofocado, inform\u00f3 hoy el Ministerio de Rusia para Situaciones de Emergencia. &#8216;A las 01.40 hora de Mosc\u00fa (21.40 GMT del jueves) el incendio qued\u00f3 controlado&#8217;, anunci\u00f3 el titular de esa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":920189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-57361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57361"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57361\/revisions"}],"predecessor-version":[{"id":920207,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57361\/revisions\/920207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/920189"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}