{"id":57351,"date":"2012-08-12T00:00:00","date_gmt":"2012-08-12T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/baloncesto\/deportes\/20120812\/londres-12-oro-para-estados-unidos-en-baloncesto\/"},"modified":"2025-08-26T04:13:45","modified_gmt":"2025-08-26T04:13:45","slug":"londres-12-oro-para-estados-unidos-en-baloncesto","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120812\/londres-12-oro-para-estados-unidos-en-baloncesto\/","title":{"rendered":"Londres &#8217;12: Oro para Estados Unidos en baloncesto"},"content":{"rendered":"<p>Londres &#8211; Estados Unidos se adjudic\u00f3 la medalla de oro en el torneo ol\u00edmpico de baloncesto al ganar a Espa\u00f1a, que jug\u00f3 un grand\u00edsimo partido por 107-100, en una repetici\u00f3n de la final de hace cuatro a\u00f1os en Pek\u00edn.<\/p>\n<p>La selecci\u00f3n sali\u00f3 fiel a sus ideas y a lo comentado en la previa por t\u00e9cnicos y jugadores, en zona en defensa y con todo el descaro del mundo en ataque, con la idea de relajar el marcador cuanto fuese posible, pero los guarismos se dispararon desde el primer momento.<\/p>\n<p>Los norteamericanos tampoco renunciaron a su estilo de juego directo, pr\u00e1cticamente un uno contra uno, con poca elaboraci\u00f3n, pocos pases, muchos tiros y mucha efectividad.<\/p>\n<p>Pau Gasol y Juan Carlos Navarro fueron los primeros que se apuntaron a tirar del equipo y el capit\u00e1n volvi\u00f3 a demostrar su especial habilidad para ser decisivo en los grandes partidos. En los primeros cuatro minutos de final ol\u00edmpica firm\u00f3 diez de los doce puntos de Espa\u00f1a con tres triples lanzados y anotados.<\/p>\n<p>El equipo nacional jug\u00f3 un gran primer cuarto y a pesar de ello recibi\u00f3 35 puntos. Los 27 puntos de los espa\u00f1oles fue toda una declaraci\u00f3n de intenciones: jugar al baloncesto en el terreno que fuera.<\/p>\n<p>Michael Krzyewski, entrenador de la selecci\u00f3n USA, no pudo reservar nada. Tuvo que jugar con todos sus mejores efectivos, porque Espa\u00f1a no volvi\u00f3 la cara en ning\u00fan momento, al contrario, con cada ventaja estadounidense en el marcador volvi\u00f3 a apretar los pu\u00f1os y a recuperar el marcador.<\/p>\n<p>No import\u00f3 que Marc Gasol tuviera cuatro personales en el minuto trece de partido (43-42), o que se estuviera repitiendo la misma historia que en la final ol\u00edmpica de Pek\u00edn con el doble criterio arbitral, la selecci\u00f3n sigui\u00f3 a lo suyo, jugando, demostrando y demostr\u00e1ndose su gran nivel.<\/p>\n<p>Al descanso, 59-58, tras un segundo parcial de 24-31 para los espa\u00f1oles, con Navarro autor de 19 puntos por delante de Durant (17), y con Espa\u00f1a dominando en asistencias (7 por 11) y rebotes (19 por 21) a los jugadores USA.<\/p>\n<p>La entrada de Sergio Rodr\u00edguez en el primer cuarto dio ese punto canalla, en el mejor sentido de la palabra, que siempre se necesita en una final de estas caracter\u00edsticas y todo el equipo se sum\u00f3 a la nueva corriente.<\/p>\n<p>Pau Gasol firm\u00f3 el 64-67 con tres jugadas del m\u00e1s alto nivel (min. 27) y los estadounidenses comenzaron a mirarse incr\u00e9dulos. Tres contraataques seguidos de los norteamericanos amenazaron con romper el partido por la v\u00eda del descontrol, pero Espa\u00f1a sigui\u00f3 devolviendo golpe por golpe, triple por triple y manteniendo la igualdad en el marcador.<\/p>\n<p>Serge Ibaka consigui\u00f3 frenar en varias jugadas a Lebron James, mientras que Pau Gasol se hizo grande bajo los aros en ataque y defensa. El juego en conjunto de Espa\u00f1a mantuvo el pulso a la calidad de los mejores jugadores del mundo e Ibaka (min.28) empat\u00f3 el partido a 80.<\/p><div class=\"notic-content-middle\" id=\"notic-2570220967\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La selecci\u00f3n estadounidense acab\u00f3 el cuarto un punto arriba, 83-82, pero perdi\u00f3 el segundo cuarto (el rese\u00f1ado 24-31) y empat\u00f3 en el tercer periodo 24-24.<\/p>\n<p>Se acabaron las pocas rotaciones en los norteamericanos, que jugaron con los titulares en el inicio del \u00faltimo cuarto. Llevaban mucho tiempo viendo las orejas del lobo.<\/p>\n<p>El marcador comenz\u00f3 a desnivelarse, 93-86 (min. 34), pero el equipo espa\u00f1ol sigui\u00f3 manteniendo su apuesta por la fuerte defensa y el juego de calidad en ataque, aunque los tiros no entraran demasiado. Sigui\u00f3 jugando de t\u00fa a t\u00fa a los mejores y meti\u00e9ndoles el miedo en el cuerpo hasta el \u00faltimo segundo<\/p>\n<p>A dos minutos para el final los NBA comenzaron a respirar, 102-93, pero mirando el retrovisor porque ya no se fiaban de nadie.<\/p>\n<p>S\u00f3lo a 37 segundos para el final el seleccionador estadounidense se permiti\u00f3 dar entrada a los suplentes. Todo un dato.<\/p>\n<p>La selecci\u00f3n espa\u00f1ola firm\u00f3 una gran final, mejor que la de Pek\u00edn (perdi\u00f3 por 107-118), y consigui\u00f3 su segunda medalla de plata ol\u00edmpica consecutiva, una plata que brilla como el oro.<\/p>\n<p>. Ficha t\u00e9cnica:<\/p>\n<p>107 &#8211; Estados Unidos (35+24+24+24): Chandler (2), Durant (30), James (19), Bryant (17) y Paul (11) -equipo inicial-, Westbrook (3), Williams (6), Iguodala (0), Love (9), Harden (2), Davis (0) y Anthony (8).<\/p>\n<p>100 &#8211; Espa\u00f1a (27+24+24+18): Pau Gasol (24), Rudy Fern\u00e1ndez (14), Navarro (21), Calder\u00f3n (0) y Marc Gasol (17) -equipo inicial-, Sergio Rodr\u00edguez (7), Reyes (0), San Emeterio (0), Llull (5), Claver (0), Sada (0) e Ibaka (12).<\/p>\n<p>\u00c1rbitros: Cristiano Maranho (BRA), Christos Christodoulou (GRE) y Michael Aylen (). Rudy Fern\u00e1ndz fue eliminado por cinco personales en el minuto 40.<\/p>\n<p>Incidencias: Partido correspondiente a la final del torneo ol\u00edmpico de baloncesto disputado en el North Greenwich Arena ante 13.514 espectadores. La reina y los pr\u00edncipes de Espa\u00f1a, junto al secretario de Estado para el deporte Miguel Cardenal y el presidente del COE Alejandro Blanco, presenciaron el partido. Tambi\u00e9n asistieron el presidente del COI Jacques Rogge, el comisionado de la NBA David Stern y el futbolista ingl\u00e9s David Beckam entre otras personalidades.<\/p>","protected":false},"excerpt":{"rendered":"<p>Londres &#8211; Estados Unidos se adjudic\u00f3 la medalla de oro en el torneo ol\u00edmpico de baloncesto al ganar a Espa\u00f1a, que jug\u00f3 un grand\u00edsimo partido por 107-100, en una repetici\u00f3n de la final de hace cuatro a\u00f1os en Pek\u00edn. La selecci\u00f3n sali\u00f3 fiel a sus ideas y a lo comentado en la previa por t\u00e9cnicos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":913042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-57351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57351"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57351\/revisions"}],"predecessor-version":[{"id":913063,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57351\/revisions\/913063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/913042"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}