{"id":57239,"date":"2016-07-09T00:00:00","date_gmt":"2016-07-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/gobierno\/la-calle\/policia\/20160709\/amenaza-con-derribar-un-helicoptero-de-la-fura-acaba-en-arresto\/"},"modified":"2025-07-26T09:20:35","modified_gmt":"2025-07-26T09:20:35","slug":"amenaza-con-derribar-un-helicoptero-de-la-fura-acaba-en-arresto","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160709\/amenaza-con-derribar-un-helicoptero-de-la-fura-acaba-en-arresto\/","title":{"rendered":"Amenaza con derribar un helic\u00f3ptero de la FURA acaba en arresto"},"content":{"rendered":"<p>En medio de un operativo para diligenciar una orden de arresto contra un &#8216;bichote&#8217; en Manat\u00ed, ayer, viernes, en la ma\u00f1ana, se report\u00f3 una amenaza de derribar un helic\u00f3ptero de la Fuerzas Unidad de R\u00e1pida Acci\u00f3n (FURA) &#8216;ya que ten\u00edan personas posteadas en el techo con armas largas de alto poder&#8217;, precisa un informe policial.<\/p>\n<p>Sin embargo, el tenienteJos\u00e9 Rom\u00e1n Vega, Director de la Divisi\u00f3n de Drogas y Narc\u00f3ticos deArecibo, en uni\u00f3n a sus agentes, lograron arrestar a un joven de 19 a\u00f1os de edad, residente en el sector CerroGand\u00eda de dicho municipio, y se ocup\u00f3,una ametralladora,61 municionesde diferentes calibres, 5 tambores calibre .223, 3 cargadores, un chalecoantibalas, un radio &#8216;scanner&#8217;, 285bolsitasdemarihuana, 2 balanzas y $50.00 en efectivo.<\/p><div class=\"notic-content-middle\" id=\"notic-2065069241\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Un agente se encuentra consultando el caso con las agencias federales para la posible radicaci\u00f3n de los cargos correspondientes. En los pasados d\u00edas han ocurrido varios asesinatos en el \u00e1rea de Manat\u00ed, donde la Polic\u00eda del \u00e1rea de Areciboha establecido un Plan de Trabajo.<\/p>","protected":false},"excerpt":{"rendered":"<p>En medio de un operativo para diligenciar una orden de arresto contra un &#8216;bichote&#8217; en Manat\u00ed, ayer, viernes, en la ma\u00f1ana, se report\u00f3 una amenaza de derribar un helic\u00f3ptero de la Fuerzas Unidad de R\u00e1pida Acci\u00f3n (FURA) &#8216;ya que ten\u00edan personas posteadas en el techo con armas largas de alto poder&#8217;, precisa un informe policial. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":581322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,12,2],"tags":[],"class_list":["post-57239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=57239"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57239\/revisions"}],"predecessor-version":[{"id":581338,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/57239\/revisions\/581338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/581322"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=57239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=57239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=57239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}