{"id":55026,"date":"2013-10-02T00:00:00","date_gmt":"2013-10-02T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20131002\/encuentro-de-defensores-y-opositores-del-ivu-expandido-en-vista-publica\/"},"modified":"2025-08-22T14:15:24","modified_gmt":"2025-08-22T14:15:24","slug":"encuentro-de-defensores-y-opositores-del-ivu-expandido-en-vista-publica","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20131002\/encuentro-de-defensores-y-opositores-del-ivu-expandido-en-vista-publica\/","title":{"rendered":"Encuentro de defensores y opositores del IVU expandido en vista p\u00fablica"},"content":{"rendered":"<p>El exsecretario del Departamento de Hacienda, Juan Agosto Alicea, alert\u00f3 hoy que la estrategia del Gobierno de aumentar al 3.5% los recaudos del Impuesto a la Venta y Uso (IVU) que se destinan al Fondo de Interes Apremiante (FIA) para poder emitir bonos a traves de COFINA, representa un riesgo ya que se desconoce si se obtendr\u00e1 el rendimiento esperado.<\/p>\n<p>M\u00e1s a\u00fan, Agosto Alicea recomend\u00f3 a la presente administraci\u00f3n a tener planes alternos en caso de que esta medida falle.<\/p>\n<p>En su alocuci\u00f3n en la vista para discutir el proyecto de la C\u00e1mara 1425 para expandir el IVU, Agosto Alicea, hizo una radiograf\u00eda de la situaci\u00f3n fiscal del Gobierno, en la quearguy\u00f3 que si Puerto Rico cualificara para acogerse a la Ley de Quiebras Federal ya se estar\u00eda dando el proceso de reorganizaci\u00f3n bajo el Cap\u00edtulo 11.<\/p>\n<p>Este destac\u00f3 que desde el 1997, la Isla lleva 18 a\u00f1os consecutivos reflejando d\u00e9ficits operacionales, que han sido financiados.<\/p>\n<p>Como consecuencia, la deuda p\u00fablica de Puerto Rico alcanza los $78,456 millones.De la que destac\u00f3 que en solo 6 a\u00f1os, la deuda de COFINA creci\u00f3 $15, 982 millones, superando la de los bonos de obligaci\u00f3n general (GO) que alcanza los $10,100 millones.<\/p>\n<p>&#8216;Aqu\u00ed hay que traer sobre la mesa a Standard &amp; Poor&#8217;s (S&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;P), Moody&#8217;s y a Fitch, porque permitieron que se emitiera bonos a base de que el Impuesto (IVU) iba a subir todos los a\u00f1os un 4%&#8217;, puntualiz\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>Seg\u00fan, Agosto Aliceapara el 2041 se proyecta que Puerto Rico pueda estar pagando alrededor de $1,475 millones en pago al principal e intereses.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Se\u00f1ores, gravamos a nuestra generaci\u00f3n, para seguir pagando los gastos. Esa es la realidad, hay que dec\u00edrselo al pa\u00eds. Los rojos y los azules. Aqu\u00ed no hay colores. Aqu\u00ed hay que hablar de Puerto Rico&#8217;, sentenci\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>Otro problema que destaca el exsecretario es que los ingresos del Fondo General han mermado desde que se cre\u00f3 COFINA. Previo a esto el Gobierno recurr\u00eda al Banco Gubernamental de Fomento (BGF) para refinanciar deudas y gastos del presupuesto.\/p<\/p>\n<p>p<\/p>\n<p>Para Agosto Aliceael mercado de inversores de Wall Street est\u00e1 equivocado en su percepci\u00f3n sobre el valor de los bonos de obligaciones generales frente a los de COFINA, pues recuerda que los primeros son los \u00fanicos cuyos pagos est\u00e1n garantizados por la Constituci\u00f3n de Puerto Rico.\/p<\/p>\n<p>p<\/p>\n<p>No obstante, ante la volatilidad de los mercados y la merma en los recaudos del Fondo General, este reconoce que a la Isla se le hace &#8216;improbable&#8217; que pueda emitir bonos de obligaci\u00f3n general. De hecho, asegura que al momento los bonos de Puerto Rico se han estado valorando tres escalafones por debajo de la clasificaci\u00f3n de chatarra.\/p<\/p>\n<p>p<\/p>\n<p>En ese sentido, apunt\u00f3 que la percepci\u00f3n en Wall Street es que Puerto Rico pueda entrar en incumplimiento de pago tras la publicaci\u00f3n de la revista Barron&#8217;ssobre las finanzas gubernamentales.\/p<\/p>\n<p>p<\/p>\n<p>Es ah\u00ed donde para la administraci\u00f3n, la ampliaci\u00f3n del margen prestatario de COFINA se muestra como la alternativa para emitir deuda de $1,233 millones para aliviar la carga del Banco Gubernamental de Fomento (BGF) y de la banca privada, que financiaron $2,100 millones en deudas del Gobierno. Al mismo tiempo, el equipo fiscal de Garc\u00eda Padilla lo ve como una alternativa para financiar asuntos del presupuesto de este a\u00f1o fiscal, entre los que Melba Acosta, secretaria de Hacienda, resalt\u00f3 el Tren de Caguas y el Centro Comprensivo del C\u00e1ncer.\/p<\/p>\n<p>p<\/p>\n<p>Por otro lado, el presidente interino del BGF, Jos\u00e9 Pagan, plante\u00f3 que al usar COFINA para emitir bonos, en vez de GO, es que la Isla se est\u00e1 ahorrando entre $66 a $132 millones.\/p<\/p>\n<p>p<\/p>\n<p>Por otro lado, Acosta rechaz\u00f3 a este diario digital que la reciente revisi\u00f3n que hizo S&lt;&gt;&lt;&gt;P sobre los bonos de COFINA, provoque cambios en dicha estrategia.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;No la cambia para nada, porque la revisi\u00f3n que hizo SP es a COFINA 1 y 2, esto es COFINA 3, lo que estamos hablando. S&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;P lo que hizo es que reafirm\u00f3 el \u2018rating&#8217; no hizo un \u2018downgrade&#8217;. Puso una perspectiva negativa por las condiciones econ\u00f3micas, pero reafirm\u00f3 el \u2018rating&#8217; de COFINA 1 y 2. Lo que estamos hablando de COFINA 3, que es otra emisi\u00f3n distinta para la cual ya pedimos un rating y estamos esperando&#8217;, dijo.\/p<\/p>\n<p>p<\/p>\n<p>Sin embargo, Agosto Alicea trajo a la atenci\u00f3n que en el 2009 la administraci\u00f3n de Luis Fortu\u00f1o intent\u00f3 hacer una estrategia similar en la que se aument\u00f3 en un 1% los recaudos del IVU que se destinan al FIA, y la situaci\u00f3n fiscal en el pa\u00eds empeor\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>A su juicio, la situaci\u00f3n con la estrategia del Gobierno, es que mientras por un lado se le devuelve la liquidez al BGF, se est\u00e1 afectando al Fondo General.\/p<\/p>\n<p>p<\/p>\n<p>La Secretaria de Hacienda ha estimado que el Fondo General tendr\u00eda $200 millones menos en recaudos del IVU debido a esta estrategia. Sin embargo, argumenta que es un impacto que no se comenzar\u00eda a ver hasta dentro de 3 a\u00f1os.\/p<\/p>\n<p>p<\/p>\n<p>Para Agosto Aliceaes momento de que Puerto Rico comience a reorganizarse y preparar un plan nacional que atienda la situaci\u00f3n fiscal y econ\u00f3mica del pa\u00eds con proyecciones por los pr\u00f3ximos 4 a\u00f1os, para evitar que se incumpla con las obligaciones. Un trabajo que sostuvo se debe hacer antes de que una entidad federal lo haga.\/p<\/p>\n<p>p<\/p>\n<p>La aseveraci\u00f3n de Agosto Alicea se da en el contexto de informaci\u00f3n que ha circulado de que la Casa Blanca ha creado una especie de &#8216;tiger team&#8217; para atender la situaci\u00f3n fiscal de Puerto Rico.\/p<\/p>\n<p>p<\/p>\n<p>Pero al ser cuestionada por NotiCel de si esto se podr\u00eda considerar un tipo de sindicatura federal, Acosta lo neg\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>Por su parte, la secretaria de Hacienda afirm\u00f3 que la relaci\u00f3n del Gobierno local con este &#8216;tiger team&#8217; no se da en un contexto de imposici\u00f3n sino de colaboraci\u00f3n.\/p<\/p>\n<p>br \/<\/p>","protected":false},"excerpt":{"rendered":"<p>El exsecretario del Departamento de Hacienda, Juan Agosto Alicea, alert\u00f3 hoy que la estrategia del Gobierno de aumentar al 3.5% los recaudos del Impuesto a la Venta y Uso (IVU) que se destinan al Fondo de Interes Apremiante (FIA) para poder emitir bonos a traves de COFINA, representa un riesgo ya que se desconoce si [&hellip;]<\/p>","protected":false},"author":0,"featured_media":891428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-55026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/55026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=55026"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/55026\/revisions"}],"predecessor-version":[{"id":891474,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/55026\/revisions\/891474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/891428"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=55026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=55026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=55026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}