{"id":54976,"date":"2012-05-27T00:00:00","date_gmt":"2012-05-27T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20120527\/se-casa-alejandro-sanz\/"},"modified":"2025-08-27T07:06:30","modified_gmt":"2025-08-27T07:06:30","slug":"se-casa-alejandro-sanz","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20120527\/se-casa-alejandro-sanz\/","title":{"rendered":"Se casa Alejandro Sanz"},"content":{"rendered":"<p>Madrid &#8211; El cantante Alejandro Sanz y su pareja, Raquel Perera, se casaron el s\u00e1bado, el mismo d\u00eda en que bautizaron a su hijo, en su finca de Jarandilla de la Vera (C\u00e1ceres, oeste de Espa\u00f1a), inform\u00f3 hoy la revista Hola en su edici\u00f3n digital.<\/p>\n<p>Sanz y Perera citaron a sus familiares y amigos m\u00e1s cercanos para el bautizo de su hijo Dylan, pero, seg\u00fan la citada web, &#8216;tras m\u00e1s de cinco a\u00f1os juntos, la pareja quiso aprovechar ese d\u00eda tan especial para hacer una doble celebraci\u00f3n y compartir con los suyos la felicidad de haberse casado&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-2712428534\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Entre los invitados a la ceremonia estaban el padrino del ni\u00f1o, Paco de Luc\u00eda, y &#8216;grandes amigos&#8217; de la pareja como Paulina Rubio, Elena Tablada, Antonio Carmona o Fiona Ferrer.<\/p>\n<p>Hoy, en el Twitter de Alejandro Sanz figura un mensaje en el que puede leerse: &#8216;feliz domingo..domingo feliz. ;)&#8217;, mientras que en el de Paulina Rubio figura: &#8216;Ayer he sido c\u00f3mplice d la mayor muestra d amor, momentos q hacen la historia d una vida!!! I belive in love!!! Jarandilla!!!!&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Madrid &#8211; El cantante Alejandro Sanz y su pareja, Raquel Perera, se casaron el s\u00e1bado, el mismo d\u00eda en que bautizaron a su hijo, en su finca de Jarandilla de la Vera (C\u00e1ceres, oeste de Espa\u00f1a), inform\u00f3 hoy la revista Hola en su edici\u00f3n digital. Sanz y Perera citaron a sus familiares y amigos m\u00e1s [&hellip;]<\/p>","protected":false},"author":0,"featured_media":917249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-54976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=54976"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54976\/revisions"}],"predecessor-version":[{"id":917286,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54976\/revisions\/917286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/917249"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=54976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=54976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=54976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}