{"id":54934,"date":"2012-10-26T00:00:00","date_gmt":"2012-10-26T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/el-tiempo\/huracanes\/mundo\/20121026\/sandy-causa-21-muertos-en-el-caribe\/"},"modified":"2025-08-25T15:51:39","modified_gmt":"2025-08-25T15:51:39","slug":"sandy-causa-21-muertos-en-el-caribe","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20121026\/sandy-causa-21-muertos-en-el-caribe\/","title":{"rendered":"Sandy causa 21 muertos en el Caribe"},"content":{"rendered":"<p>Bogot\u00e1.- El hurac\u00e1n &#8216;Sandy&#8217; ha causado al menos 21 muertos a su paso por Hait\u00ed, Jamaica y Cuba, donde a\u00fan se registran fuertes lluvias y deslizamientos, en Rep\u00fablica Dominicana unas 12.581 personas fueron evacuadas, mientras que las Bahamas y la Florida permanecen en alerta.<\/p>\n<p>&#8216;Sandy&#8217; se mantiene como un cicl\u00f3n de categor\u00eda dos, inform\u00f3 el Centro Nacional de Huracanes (CNH) de EE.UU. en su bolet\u00edn de las 00.00 GMT, en el que detalla, adem\u00e1s, que perdi\u00f3 algo de intensidad en su recorrido por las Bahamas al bajar sus vientos m\u00e1ximos sostenidos a 160 kil\u00f3metros por hora.<\/p>\n<p>El d\u00e9cimo hurac\u00e1n de la temporada del Atl\u00e1ntico est\u00e1 localizado cerca de la latitud 24,8 grados norte y longitud 75,8 grados norte, a 55 kil\u00f3metros al sureste de Eleuthera y a 170 kil\u00f3metros al este de Nassau, en Bahamas.<\/p>\n<p>Los meteor\u00f3logos esperan que se debilite en las pr\u00f3ximas 48 horas, &#8216;pero que permanezca como hurac\u00e1n en los pr\u00f3ximos dos d\u00edas&#8217;.<\/p>\n<p>Est\u00e1 vigente un aviso de hurac\u00e1n (paso del sistema en 36 horas) para Bahamas y uno de tormenta tropical para la costa este de Florida, hasta Flagler Beach.<\/p><div class=\"notic-content-middle\" id=\"notic-2011294653\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>En las islas Bahamas colegios p\u00fablicos, edificios oficiales y aeropuertos permanecen cerrados, y negocios y tiendas particulares tambi\u00e9n han optado por no abrir hoy sus puertas despu\u00e9s de que las autoridades locales ordenaran ultimar los preparativos para hacer frente a este hurac\u00e1n.<\/p>\n<p>Por otro lado, la costa este de Florida (EE.UU.) tambi\u00e9n est\u00e1 en alerta y el sur sufre desde esta ma\u00f1ana intensas lluvias, rachas de viento, cortes puntuales del suministro el\u00e9ctrico, inundaciones aisladas y una intensa marejada.<\/p>\n<p>En gran parte de la costa este de Florida se han cancelado las clases del viernes, se ha pedido a los due\u00f1os de embarcaciones de recreo que se abstengan de salir al mar y los grandes barcos cruceros que tienen all\u00ed su puerto de salida y llegada observan con atenci\u00f3n la evoluci\u00f3n del temporal.<\/p>\n<p>Sin embargo, lo que m\u00e1s preocupa en EE.UU. no es Florida, sino los estados del norte de la costa este, ya que se prev\u00e9 que una vez el frente supere las Bahamas contin\u00fae su potente desplazamiento hacia el norte, con lo que podr\u00eda tocar tierra, en forma de tormenta tropical, en alg\u00fan punto de los estados de Nueva Jersey, Nueva York, Connecticut, Rhode Island y Maine, entre otros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1.- El hurac\u00e1n &#8216;Sandy&#8217; ha causado al menos 21 muertos a su paso por Hait\u00ed, Jamaica y Cuba, donde a\u00fan se registran fuertes lluvias y deslizamientos, en Rep\u00fablica Dominicana unas 12.581 personas fueron evacuadas, mientras que las Bahamas y la Florida permanecen en alerta. &#8216;Sandy&#8217; se mantiene como un cicl\u00f3n de categor\u00eda dos, inform\u00f3 el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":912597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[18,19,17],"tags":[],"class_list":["post-54934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-tiempo","category-huracanes","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=54934"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54934\/revisions"}],"predecessor-version":[{"id":912603,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54934\/revisions\/912603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/912597"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=54934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=54934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=54934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}