{"id":54861,"date":"2016-03-17T00:00:00","date_gmt":"2016-03-17T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20160317\/las-palabras-que-han-dado-de-que-hablar-en-el-congreso-de-la-lengua-docume\/"},"modified":"2025-08-16T06:11:45","modified_gmt":"2025-08-16T06:11:45","slug":"las-palabras-que-han-dado-de-que-hablar-en-el-congreso-de-la-lengua-docume","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160317\/las-palabras-que-han-dado-de-que-hablar-en-el-congreso-de-la-lengua-docume\/","title":{"rendered":"Las palabras que han dado de qu\u00e9 hablar en el Congreso de la Lengua (docume"},"content":{"rendered":"<p>Desde la &#8216;puertorrique\u00f1idad&#8217; de Luis Rafael S\u00e1nchez, que ya recibi\u00f3 la bendici\u00f3n de la Real Academia Espa\u00f1ola, hasta un rey que con sus palabras saca al Puerto Rico hispanohablante de Hispanoamerica para meterlo de lleno en Estados Unidos, los discursos de la sesi\u00f3n inaugural del Congreso Internacional de la Lengua han resonado alrededor del mundo.<\/p>\n<p>A continuaci\u00f3n, los discursos \u00edntegros, seg\u00fan entregados por los organizadores del Congreso.<\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/22\/8ed594414a23b80e9589933c7ec762b7_8153845_ver1.0.pdf\" target=\"_blank\"> Jean-Marie Le Cl\u00e9zio &#8211; NotiCel_17821<\/a><\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/22\/42c5dbe777a40716b4c5d9de553f15eb_8153846_ver1.0.pdf\" target=\"_blank\"> Gobernador Alejandro Garc\u00eda Padilla &#8211; NotiCel_17822<\/a><\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/22\/659b0731849b23da16c7ce63561314d9_8153847_ver1.0.pdf\" target=\"_blank\"> Luis Rafael S\u00e1nchez &#8211; NotiCel_17823<\/a><\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/22\/1eaabab6a839c8295bd84ef7af566528_8153848_ver1.0.pdf\" target=\"_blank\"> Rey Felipe VI &#8211; NotiCel_17824<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Desde la &#8216;puertorrique\u00f1idad&#8217; de Luis Rafael S\u00e1nchez, que ya recibi\u00f3 la bendici\u00f3n de la Real Academia Espa\u00f1ola, hasta un rey que con sus palabras saca al Puerto Rico hispanohablante de Hispanoamerica para meterlo de lleno en Estados Unidos, los discursos de la sesi\u00f3n inaugural del Congreso Internacional de la Lengua han resonado alrededor del mundo. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":847839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-54861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=54861"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54861\/revisions"}],"predecessor-version":[{"id":847877,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54861\/revisions\/847877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/847839"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=54861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=54861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=54861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}