{"id":54523,"date":"2016-07-08T00:00:00","date_gmt":"2016-07-08T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/lgbtt\/mundo\/20160708\/10-estados-mas-demandan-al-gobierno-de-ee-uu-por-banos-transgenero\/"},"modified":"2025-07-26T15:44:47","modified_gmt":"2025-07-26T15:44:47","slug":"10-estados-mas-demandan-al-gobierno-de-ee-uu-por-banos-transgenero","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160708\/10-estados-mas-demandan-al-gobierno-de-ee-uu-por-banos-transgenero\/","title":{"rendered":"10 estados m\u00e1s demandan al Gobierno de EE.UU. por ba\u00f1os transg\u00e9nero"},"content":{"rendered":"<p>Diez estados demandaron hoy, viernes, al Gobierno de EE.UU. por la directiva que exige a las escuelas p\u00fablicas que permitan a los alumnos transexuales elegir el ba\u00f1o que usan seg\u00fan el genero con el que se identifiquen, con lo que se suman a la moci\u00f3n presentada el lunes pasado por una coalici\u00f3n de 13 estados.<\/p>\n<p>La demanda, que alega que el Gobierno federal interfiere en competencias de los estados al regular sobre las escuelas p\u00fablicas, se present\u00f3 hoy en una Corte de Lincoln (Nebraska).<\/p>\n<p>La directiva, firmada en mayo por el presidente de Estados Unidos, Barack Obama, fue presentada por la Casa Blanca como un paso adelante en la defensa de los derechos de lesbianas, gais, bisexuales y transexuales (LGBT).<\/p>\n<p>Desde que entr\u00f3 en vigor, cuando un estudiante o sus progenitores notifiquen un cambio en el g\u00e9nero con el que el alumno se identificaba previamente, la escuela debe actuar en consecuencia y respetar esa nueva identidad.<\/p>\n<p>El fiscal general de Nebraska, Doug Peterson, lidera la nueva coalici\u00f3n de diez estados, que demanda a los departamentos de Educaci\u00f3n y de Justicia de EE.UU. por dicha directiva.<\/p>\n<p>La norma &#8216;se salta la ley establecida e ignora el proceso legislativo apropiado y necesario para cambiar una ley as\u00ed&#8217;, denunci\u00f3 Peterson, del Partido Republicano, en un comunicado.<\/p>\n<p>El documento instruido por el Gobierno de Obama se basa en el T\u00edtulo IX de las Enmiendas de Educaci\u00f3n de 1972, que determina que los centros educativos que reciben fondos federales no pueden discriminar por razones de sexo.<\/p>\n<p>Por eso, a pesar de que la directiva no tiene rango de ley, las escuelas que no la cumplan pueden verse abocadas a perder los fondos federales que reciben e incluso a enfrentar demandas gubernamentales.<\/p>\n<p>El fiscal general de Texas, Ken Paxton, present\u00f3 el lunes pasado otra demanda ante la Corte Federal de Texas en representaci\u00f3n de un total de 13 estados contra los departamentos de Educaci\u00f3n y de Justicia y contra las dem\u00e1s agencias gubernamentales implicadas en la directiva.<\/p>\n<p>Los estados que apoyaron a Texas en su demanda son Alabama, Arizona, Georgia, Kentucky, Maine, Misisipi, Oklahoma, Tennessee, Utah, Virginia Occidental, Wisconsin y Luisiana, el \u00fanico estado del grupo no gobernado por un republicano.<\/p>\n<p>La nueva coalici\u00f3n de estados liderada por Nebraska la integran Arkansas, Kansas, Michigan, Dakota del Norte, Dakota del Sur, Ohio, Carolina del Sur y Wyoming, todos ellos gobernados por republicanos, y Montana, el \u00fanico en el que el gobernador es dem\u00f3crata.<\/p>","protected":false},"excerpt":{"rendered":"<p>Diez estados demandaron hoy, viernes, al Gobierno de EE.UU. por la directiva que exige a las escuelas p\u00fablicas que permitan a los alumnos transexuales elegir el ba\u00f1o que usan seg\u00fan el genero con el que se identifiquen, con lo que se suman a la moci\u00f3n presentada el lunes pasado por una coalici\u00f3n de 13 estados. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":583714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17,2],"tags":[],"class_list":["post-54523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=54523"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54523\/revisions"}],"predecessor-version":[{"id":583728,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/54523\/revisions\/583728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/583714"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=54523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=54523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=54523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}