{"id":53874,"date":"2012-04-20T00:00:00","date_gmt":"2012-04-20T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20120420\/campeonas-las-jerezanas-en-el-futbol-de-la-lai\/"},"modified":"2025-07-24T04:15:46","modified_gmt":"2025-07-24T04:15:46","slug":"campeonas-las-jerezanas-en-el-futbol-de-la-lai","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120420\/campeonas-las-jerezanas-en-el-futbol-de-la-lai\/","title":{"rendered":"Campeonas las Jerezanas en el f\u00fatbol de la LAI"},"content":{"rendered":"<p>Ponce &#8211; Se proclaman campeonas del f\u00fatbol de la Liga Atl\u00e9tica Interuniversitaria las Jerezanas de la Universidad de Puerto Rico (UPR) Recinto de Rio Piedras, luego de vencer a las Gryphons de CaribbeanUniversity, en el partido celebrado en el Estadio Francisco ?Paquito? Montaner de Ponce.<\/p>\n<p>El marcador del partido culmin\u00f3 1-0 luego de que Karla Vives anotara el tan esperado gol que convertir\u00eda a las Jerezanas en las primeras campeonas del f\u00fatbol de la LAI. En tercer lugar quedaron las Toritas del Recinto Universitario de Cayey, al vencer 4-0 a las Juanas del Colegio de Mayag\u00fcez.<\/p>\n<p>En esta temporada 2012, participaron ocho equipos delos recintos de la UPR: siendo los mismos R\u00edo Piedras, Bayam\u00f3n, Cayey, Carolina y Mayag\u00fcez. Por las instituciones privadas participaron: CaribbeanUniversity, la Universidad del Turabo y la Universidad del Sagrado Coraz\u00f3n.<\/p>\n<p>Es el primer a\u00f1o que se hace oficial el deporte del f\u00fatbol en las Justas y el anuncio lo dio el comisionado de la LAI, Jos\u00e9 A. Arrar\u00e1s, durante la premiaci\u00f3n.<\/p>\n<p>&#8216;Con la participaci\u00f3n de ocho equipo este a\u00f1o. Demostrar entusiasmo, compromiso y pasi\u00f3n, declar\u00f3 por el poder que me confiere el Reglamento General de la LAI el evento del f\u00fatbol femenino oficial&#8217;, expres\u00f3 Arrar\u00e1s.<\/p>\n<p>Cada a\u00f1o son mas los deportes que son admitidos como oficiales en la justa atl\u00e9tica y mayor cantidad de universidades las que participan. Por tal raz\u00f3n superaron las expectativas y se cumplieron con todos los requisitos para que fuera posible el torneo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ponce &#8211; Se proclaman campeonas del f\u00fatbol de la Liga Atl\u00e9tica Interuniversitaria las Jerezanas de la Universidad de Puerto Rico (UPR) Recinto de Rio Piedras, luego de vencer a las Gryphons de CaribbeanUniversity, en el partido celebrado en el Estadio Francisco ?Paquito? Montaner de Ponce. El marcador del partido culmin\u00f3 1-0 luego de que Karla [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-53874","post","type-post","status-publish","format-standard","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=53874"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53874\/revisions"}],"predecessor-version":[{"id":568218,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53874\/revisions\/568218"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=53874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=53874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=53874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}