{"id":53387,"date":"2015-12-21T00:00:00","date_gmt":"2015-12-21T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/boxeo-caliente\/deportes\/20151221\/regresan-los-huracanes-boricuas-a-la-serie-mundial-de-boxeo-video\/"},"modified":"2025-07-29T10:37:43","modified_gmt":"2025-07-29T10:37:43","slug":"regresan-los-huracanes-boricuas-a-la-serie-mundial-de-boxeo-video","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20151221\/regresan-los-huracanes-boricuas-a-la-serie-mundial-de-boxeo-video\/","title":{"rendered":"Regresan los huracanes boricuas a la Serie Mundial de Boxeo (v\u00eddeo)"},"content":{"rendered":"<p>Los Puerto Rico Hurricanes oficializaron hoy con j\u00fabilo su segunda participaci\u00f3n en la Serie Mundial de Boxeo (WSB por sus siglas en ingles) que arranca el 15 enero de 2016 y contar\u00e1 con 16 equipos que fueron divididos en cuatro secciones.<\/p>\n<p>Puerto Rico pertenecer\u00e1 al grupo D, donde le tocar\u00e1 enfrentarse a franquicias competitivas como lo son el campe\u00f3n 2015, Astana Arlans de Kazajist\u00e1n. El grupo lo completan los Baku Fires de Azerbaiy\u00e1n que este a\u00f1o cerraron terceros y Uzbekist\u00e1n que debuta.<\/p>\n<p>El resto de los pa\u00edses participantes en la sexta edicion de la WSB son Argentina, China, Cuba, Estados Unidos, Inglaterra, Marruecos, M\u00e9xico, Polonia, Rusia, Turqu\u00eda, Ucrania, y Venezuela. En la pasada temporada los Puerto Rico Hurricanes no superaron la temporada regular y cerraron en la posici\u00f3n 11, entre 16 equipos.<\/p>\n<p>En el aspecto individual lograron clasificar al bayamon\u00e9s Jeyvier Cintr\u00f3n (52Kg) a los Juegos Ol\u00edmpicos R\u00edo de Janeiro 2016, mientras que el cag\u00fce\u00f1o Jos\u00e9 Rosario (60Kg) con la experiencia adquirida logr\u00f3 luego clasificar a los Juegos Panamericanos Toronto 2015, donde gan\u00f3 medalla de bronce.<\/p>\n<p>&#8216;Este evento nos hizo elevar el nivel competitivo y la confianza de boxeadores como Jos\u00e9 Rosario y Jan Rivera. Nos dimos a conocer mundialmente, y frente a la AIBA (International Boxing Association) demostramos que tenemos capacidad competitiva y organizativa.<\/p>\n<p>Adem\u00e1s se gener\u00f3 un entusiasmo general en el pa\u00eds y nuestros boxeadores ya ven la WSB como una opci\u00f3n adicional para su desarrollo&#8217;, dijo el entrenador de los Puerto Rico Hurricanes, Jos\u00e9 &#8216;Chiki&#8217; Laureano.<\/p>\n<p>El veterano l\u00edder a\u00f1adi\u00f3: &#8216;Nuestro objetivo es desarrollarnos y utilizar la mayor cantidad de atletas puertorrique\u00f1os. Es posible que un mismo boxeador no haga todas las peleas de su peso. Buscaremos que m\u00e1s boricuas se prueben en ese nivel&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-3111370719\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p><strong> Cambios en el calendario <\/strong><\/p>\n<p> De otra parte, el calendario de la WSB experiment\u00f3 una transformaci\u00f3n sustancial en su agenda, tras disminuir la serie regular de 14 carteleras en el 2015 a seis en la actualidad, \u00e9sto debido a la proximidad de las Olimpiadas 2016. Tres de estas carteleras ser\u00e1n locales para cada equipo, mientras que en las otras tres fungir\u00e1n como visitantes. <\/p>\n<p> Los Puerto Rico Hurricanes ser\u00e1n anfitriones los s\u00e1bados, 23 de enero (vs. Uzbekist\u00e1n), 6 de febrero (vs. Kazajist\u00e1n) y 2 de abril (vs. Azerbaiy\u00e1n). Mientras que visitar\u00e1n el viernes, 19 de febrero a Azerbaiy\u00e1n y los s\u00e1bados 5 de marzo y 19 de marzo a Uzbekist\u00e1n y Kazajist\u00e1n respectivamente. <\/p>\n<p> En un fin de semana pelear\u00e1n los cinco pesos de la categor\u00eda C1 (49kg, 56kg, 64kg, 75kg, 91kg), mientras que en el otro lo har\u00e1n los cinco pesos de la categor\u00eda C2 (52kg, 60kg, 69kg, 81kg, 90+kg). En la serie regular solo dos equipos de cada uno de los cuatro grupos pasar\u00e1n a la postemporada. De esas ocho franquicias, cuatro clasificar\u00e1n a la semifinal. <\/p>\n<p> Finalmente, el gerente general de los Puerto Rico Hurricanes, Miguel Sosa adelant\u00f3 que el listado final de los boxeadores se publicar\u00e1 esta semana y que el Coliseo Pedr\u00edn Zorrilla en San Juan ser\u00e1 una vez m\u00e1s el hogar de los boricuas. Para m\u00e1s informaci\u00f3n sobre los Puerto Rico Hurricaneslos interesados pueden visitar la p\u00e1gina web<\/p>\n<p><a href=\"http:\/\/www.worldseriesofboxing.com\/\"> www.worldseriesofboxing.com <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Los Puerto Rico Hurricanes oficializaron hoy con j\u00fabilo su segunda participaci\u00f3n en la Serie Mundial de Boxeo (WSB por sus siglas en ingles) que arranca el 15 enero de 2016 y contar\u00e1 con 16 equipos que fueron divididos en cuatro secciones. Puerto Rico pertenecer\u00e1 al grupo D, donde le tocar\u00e1 enfrentarse a franquicias competitivas como [&hellip;]<\/p>","protected":false},"author":0,"featured_media":607778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-53387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=53387"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53387\/revisions"}],"predecessor-version":[{"id":607795,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/53387\/revisions\/607795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/607778"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=53387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=53387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=53387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}