{"id":52720,"date":"2014-08-06T00:00:00","date_gmt":"2014-08-06T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20140806\/ayuda-para-cesanteados-general-electric\/"},"modified":"2025-08-19T17:34:32","modified_gmt":"2025-08-19T17:34:32","slug":"ayuda-para-cesanteados-general-electric","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140806\/ayuda-para-cesanteados-general-electric\/","title":{"rendered":"Ayuda para cesanteados General Electric"},"content":{"rendered":"<p>Sally L\u00f3pez Mart\u00ednez, administradora de la Administraci\u00f3n de Desarrollo Laboral (ADL), inform\u00f3 que a partir del 19 de agosto los trabajadores que ser\u00e1n cesanteados escalonadamente de la manufacturera General Electric en Puerto Rico recibir\u00e1n todos los servicios de Respuesta R\u00e1pida que provee la Unidad Estatal para Trabajadores Desplazados y Patronos (UETDP) de la agencia.<\/p>\n<p>La funcionaria indic\u00f3 que las ayudas se ofrecer\u00e1n en las instalaciones de la empresa en San Germ\u00e1n y Vega Baja.<\/p>\n<p>&#8216;Les vamos a ofrecer orientaci\u00f3n, alternativas laborales y apoyo durante la transici\u00f3n hacia un nuevo empleo durante los meses previos a las cesant\u00edas escalonadas que comienzan en noviembre 2014 y se extienden hasta diciembre 2015. Coordinamos con la direcci\u00f3n de Recursos Humanos de la empresa para establecer Centros de Apoyo en ambas facilidades, donde brindarles charlas de transici\u00f3n, t\u00e9cnicas de entrevistas de empleo, apoyo psicol\u00f3gico, servicios de empleo individualizados, redacci\u00f3n de resum\u00e9 y ofertas de empleo, entre otros servicios,&#8217; expres\u00f3 L\u00f3pez Mart\u00ednez en un comunicado de prensa.<\/p>\n<p>La administradora de la ADL explic\u00f3 que los 600 trabajadores afectados; 400 en San Germ\u00e1n y 200 en Vega Baja; tras el anunciado cierre de operaciones de General Electric en Puerto Rico debido a su traslado a la Rep\u00fablica Dominicana, cualifican para recibir los beneficios del programa Trade Adjustment Act (TAA).<\/p>\n<p>Detall\u00f3 que seg\u00fan dispone este programa, tambi\u00e9n conocido como Asistencia por Ajuste en el Comercio, los trabajadores cesanteados por empresas certificadas por TAA pueden obtener capacitaci\u00f3n, apoyo y recursos para reintegrarse al mercado laboral. Adem\u00e1s, podr\u00edan recibir hasta un m\u00e1ximo de 10,000 d\u00f3lares para estudios, 1,250 d\u00f3lares de compensaci\u00f3n por la b\u00fasqueda de empleo, 1,250 para gastos de relocalizaci\u00f3n laboral dentro y fuera de Puerto Rico, y un beneficio adicional de 10,000 d\u00f3lares a los cesanteados de 50 a\u00f1os o m\u00e1s, para pagar la diferencia en sueldos, si el nuevo salario es menor al anterior.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sally L\u00f3pez Mart\u00ednez, administradora de la Administraci\u00f3n de Desarrollo Laboral (ADL), inform\u00f3 que a partir del 19 de agosto los trabajadores que ser\u00e1n cesanteados escalonadamente de la manufacturera General Electric en Puerto Rico recibir\u00e1n todos los servicios de Respuesta R\u00e1pida que provee la Unidad Estatal para Trabajadores Desplazados y Patronos (UETDP) de la agencia. La [&hellip;]<\/p>","protected":false},"author":0,"featured_media":875264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-52720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/52720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=52720"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/52720\/revisions"}],"predecessor-version":[{"id":875321,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/52720\/revisions\/875321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/875264"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=52720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=52720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=52720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}