{"id":51949,"date":"2013-12-28T00:00:00","date_gmt":"2013-12-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20131228\/cuba-recibe-mas-de-2-5-millones-de-turistas-mas-de-un-tercio-del-canada\/"},"modified":"2025-08-22T14:34:32","modified_gmt":"2025-08-22T14:34:32","slug":"cuba-recibe-mas-de-2-5-millones-de-turistas-mas-de-un-tercio-del-canada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20131228\/cuba-recibe-mas-de-2-5-millones-de-turistas-mas-de-un-tercio-del-canada\/","title":{"rendered":"Cuba recibe m\u00e1s de 2.5 millones de turistas, m\u00e1s de un tercio del Canad\u00e1"},"content":{"rendered":"<p>La Habana &#8211; Cuba recibi\u00f3 entre enero y noviembre \u00faltimo la visita de m\u00e1s de 2.5 millones de turistas extranjeros, seg\u00fan datos publicados el viernes por la Oficina Nacional de Estad\u00edsticas e Informaci\u00f3n (ONEI).<\/p>\n<p>El reporte precis\u00f3 que fueron 2,546,851 los turistas que arribaron a la isla en once meses de 2013 y 234,266 de ellos en noviembre.<\/p>\n<p>Cuba no podr\u00e1 llegar este a\u00f1o a sus previsiones tur\u00edsticas que buscaban recibir unos 3 millones de visitantes y, seg\u00fan han informado directivos del sector, se espera que el ejercicio cerrar\u00e1 con 2.8 millones de viajeros extranjeros, cifra similar a la del a\u00f1o anterior.<\/p><div class=\"notic-content-middle\" id=\"notic-2484769132\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Entre los principales factores que han incidido en el incumplimiento del plan, las autoridades tur\u00edsticas cubanas han referido las situaciones de los mercados emisores, debido a la crisis econ\u00f3mica internacional, y otras dificultades.<\/p>\n<p>Canad\u00e1, con un 38.9 por ciento, conserva el liderazgo como principal emisor de turistas a Cuba, y ya super\u00f3 el mill\u00f3n de visitantes a la isla caribe\u00f1a este a\u00f1o, de acuerdo con datos de la ONEI.<\/p>\n<p>A Canad\u00e1 le siguen el Reino Unido, Alemania, Francia y Argentina, Italia, M\u00e9xico, Espa\u00f1a, Venezuela, Chile, Colombia, Holanda, Suiza, China, Per\u00fa y Brasil, detall\u00f3 el organismo gubernamental cubano.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Habana &#8211; Cuba recibi\u00f3 entre enero y noviembre \u00faltimo la visita de m\u00e1s de 2.5 millones de turistas extranjeros, seg\u00fan datos publicados el viernes por la Oficina Nacional de Estad\u00edsticas e Informaci\u00f3n (ONEI). El reporte precis\u00f3 que fueron 2,546,851 los turistas que arribaron a la isla en once meses de 2013 y 234,266 de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":891584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-51949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51949"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51949\/revisions"}],"predecessor-version":[{"id":891602,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51949\/revisions\/891602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/891584"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}