{"id":51769,"date":"2014-03-11T00:00:00","date_gmt":"2014-03-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20140311\/latinoamerica-ha-tenido-seis-presidentas-electas\/"},"modified":"2025-08-20T07:30:48","modified_gmt":"2025-08-20T07:30:48","slug":"latinoamerica-ha-tenido-seis-presidentas-electas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140311\/latinoamerica-ha-tenido-seis-presidentas-electas\/","title":{"rendered":"Latinoam\u00e9rica ha tenido seis presidentas electas"},"content":{"rendered":"<p>Cuatro a\u00f1os despues de haber finalizado un primer mandato, Michelle Bachelet volver\u00e1 ma\u00f1ana a la Presidencia de Chile, uno de los seis pa\u00edses latinoamericanos cuyos electores han confiado en una mujer para dirigir su naci\u00f3n.<\/p>\n<p>Nicaragua, Panam\u00e1, Chile, Argentina, Costa Rica y Brasil son los \u00fanicos pa\u00edses de Am\u00e9rica Latina que han tenido presidentas elegidas en las urnas, aunque otras mujeres latinoamericanas han ejercido el cargo en sus pa\u00edses por sucesi\u00f3n constitucional o por encargo del Parlamento o reg\u00edmenes de facto en transici\u00f3n.<\/p>\n<p>Sin embargo, ninguna mujer ha sido dictadora en Am\u00e9rica Latina, donde, sobre todo en los a\u00f1os 70 y 80, abundaron los reg\u00edmenes autoritarios.<\/p>\n<p>Con la socialista Bachelet de nuevo en La Moneda, a partir de ma\u00f1ana y hasta mayo pr\u00f3ximo se dar\u00e1 la circunstancia de que por primera vez habr\u00e1 cuatro mujeres gobernando a la vez en la regi\u00f3n.<\/p>\n<p>La otras tres son Cristina Fern\u00e1ndez, en Argentina, Dilma Rousseff, en Brasil, y Laura Chinchilla, en Costa Rica. Esta \u00faltima dejar\u00e1 el poder en mayo a quien gane la segunda vuelta de las elecciones presidenciales el pr\u00f3ximo 6 de abril.<\/p>\n<p>La primera mujer latinoamericana que fue elegida presidenta, en 1990, fue la nicarag\u00fcense Violeta Barrios, m\u00e1s conocida como Violeta Chamorro, por el apellido del que fue su esposo, el periodista Pedro Joaqu\u00edn Chamarro, asesinado por la dictadura somocista.<\/p>\n<p>Argentina, sin embargo, fue el primer pa\u00eds del mundo gobernado por una mujer: Isabel Mart\u00ednez, quien era vicepresidenta en 1974 cuando su esposo, el presidente Juan Domingo Per\u00f3n, falleci\u00f3 y, de acuerdo con la Constituci\u00f3n, le correspondi\u00f3 ocupar su lugar.<\/p>\n<p>La actual presidenta argentina, Cristina Fern\u00e1ndez, tambi\u00e9n estuvo casada con un presidente, N\u00e9stor Kirchner, ya fallecido, y, como Bachelet, fue reelegida para el cargo, aunque en su caso de manera consecutiva. Su primer mandato fue de 2007 a 2011 y el segundo concluir\u00e1 en 2015.<\/p>\n<p>Fern\u00e1ndez no puede presentarse nuevamente a la reelecci\u00f3n, pues la Constituci\u00f3n argentina solo lo permite por una vez.<\/p>\n<p>S\u00ed puede hacerlo Rousseff en Brasil y aunque aun no se ha oficializado su candidatura, pero sus correligionarios en el Partido de los Trabajadores dan por seguro que competir\u00e1 en las elecciones previstas para fines de este a\u00f1o.<\/p>\n<p>Panam\u00e1 tuvo de presidenta a Mireya Moscoso (1999-2004), quien tambi\u00e9n fue esposa de un presidente, Arnulfo Arias Madrid, aunque cuando gan\u00f3 las elecciones ya era viuda.<\/p>\n<p>Colombia no se ha estrenado con una mujer presidente, pero las condiciones parecen dadas a tenor del n\u00famero de candidatas que competir\u00e1n en las elecciones presidenciales del 25 de mayo, por ahora mayor que el de candidatos varones.<\/p>\n<p>A falta de que el Partido Verde elija su candidato o candidata en unas primarias, solo dos varones buscan la Presidencia colombiana: el actual presidente Juan Manuel Santos y el uribista Oscar Iv\u00e1n Zuluaga.<\/p>\n<p>Las mujeres son Martha Luc\u00eda Ram\u00edrez, Claudia Avela y Claudia L\u00f3pez, la primera conservadora y las otras dos izquierdistas, pero las encuestas de intenci\u00f3n de voto no indican que los colombianos vayan a poner a una mujer en la Presidencia.<\/p><div class=\"notic-content-middle\" id=\"notic-1687259159\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>En Per\u00fa, la &#8216;primera dama&#8217;, Nadine Heredia, m\u00e1s popular que su marido, el presidente Ollanta Humala, es objeto de toda clase de especulaciones acerca de si quiere y si puede ser candidata en las pr\u00f3ximas elecciones.<\/p>\n<p>Poder, en teor\u00eda, no puede, pues la legislaci\u00f3n peruana proh\u00edbe ser candidatos presidenciales a familiares directos, incluidos el c\u00f3nyuge, del presidente.<\/p>\n<p>Bachelet, que entre su primera y segunda presidencia fue la jefa de ONU Mujeres, gan\u00f3 en enero pasado la segunda vuelta de las elecciones, en las que compiti\u00f3 con otra mujer, Evelyn Matthei.<\/p>\n<p>Fue el primer duelo electoral femenino de la historia de Chile y de Am\u00e9rica Latina, y se dio la circunstancia de que tanto Bachelet como Matthei son hijas de generales de la Fuerza A\u00e9rea.<\/p>\n<p>En Honduras Xiomara Castro, esposa del expresidente Manuel Zelaya, qued\u00f3 segunda en las \u00faltimas elecciones de ese pa\u00eds, en 2013.<\/p>\n<p>De las cuatro jefas de Estado que a partir de ma\u00f1ana tendr\u00e1 Am\u00e9rica Latina una es casada (Chinchilla), otra viuda (Fern\u00e1ndez), y dos divorciadas (Bachelet y Rousseff).<\/p>\n<p>Las cuatro son madres, pero la que m\u00e1s hijos tiene (un hijo y dos hijas) es Bachelet. Chinchilla tiene un hijo, Rousseff, una hija, y Fern\u00e1ndez, un hijo y una hija.<\/p>\n<p>Sin pasar por unas elecciones fue presidenta la boliviana Lidia Gueiler Tejada, quien accedi\u00f3 a la jefatura de Estado desde la presidencia de la C\u00e1mara de Diputados en 1979 y solo ocho meses despu\u00e9s fue v\u00edctima de un golpe de Estado y obligada al exilio.<\/p>\n<p>Rosal\u00eda Arteaga gobern\u00f3 Ecuador por 48 horas en febrero de 1997, tras el derrocamiento de Abdal\u00e1 Bucaram, de quien era vicepresidenta y tras ser nombrada jefa de Estado &#8216;temporal&#8217;.<\/p>\n<p>La haitiana Ertha Pascal-Trouillot era jueza suprema cuando los militares que hab\u00edan dado un golpe de Estado le entregaron la Presidencia en 1990 con el fin de que convocara elecciones.<\/p>\n<p>Once meses despu\u00e9s traspas\u00f3 el poder a Jean Bertrand Aristide, el ganador de los comicios.<\/p>\n<p>En Guyana, Janet Jagan, ex primera dama y ex primera ministra, fue elegida y gobern\u00f3 de 1997 a 1999.<\/p>\n<p>En el Caribe, adem\u00e1s, son varias las mujeres que han llegado al cargo de primer ministro.<\/p>\n<p>La primera fue Dame Eugenia Charles, de Dominica, en 1980, y actualmente tanto Jamaica, con Portia Simpson Miller, como Trinidad y Tobago, con Kamla Persad-Bissessar, son pa\u00edses con mujeres al frente de sus gobiernos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cuatro a\u00f1os despues de haber finalizado un primer mandato, Michelle Bachelet volver\u00e1 ma\u00f1ana a la Presidencia de Chile, uno de los seis pa\u00edses latinoamericanos cuyos electores han confiado en una mujer para dirigir su naci\u00f3n. Nicaragua, Panam\u00e1, Chile, Argentina, Costa Rica y Brasil son los \u00fanicos pa\u00edses de Am\u00e9rica Latina que han tenido presidentas elegidas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":880471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-51769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51769"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51769\/revisions"}],"predecessor-version":[{"id":880505,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51769\/revisions\/880505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/880471"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}