{"id":51576,"date":"2016-12-11T00:00:00","date_gmt":"2016-12-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20161211\/trump-no-quiero-que-china-me-dicte-lo-que-tengo-que-hacer\/"},"modified":"2025-07-18T08:36:45","modified_gmt":"2025-07-18T08:36:45","slug":"trump-no-quiero-que-china-me-dicte-lo-que-tengo-que-hacer","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20161211\/trump-no-quiero-que-china-me-dicte-lo-que-tengo-que-hacer\/","title":{"rendered":"Trump: &#8216;No quiero que China me dicte lo que tengo que hacer&#8217;"},"content":{"rendered":"<p>Washington &#8211; El presidente electo de EE.UU., Donald Trump, puso hoy en duda que sea necesario seguir con la pol\u00edtica de &#8216;una sola China&#8217; que ha supuesto la base de las relaciones bilaterales desde 1972 y asegur\u00f3 que no permitir\u00e1 que el gigante asi\u00e1tico le &#8216;dicte&#8217; lo que debe hacer.<\/p>\n<p>&#8216;No s\u00e9 por qu\u00e9 tenemos que estar ligados por una pol\u00edtica de &#8216;una sola China&#8217; a no ser que lleguemos a un acuerdo con China que tenga que ver con otras cosas, incluido el comercio&#8217;, dijo Trump en una entrevista emitida hoy en la cadena de televisi\u00f3n Fox News.<\/p>\n<p>Durante m\u00e1s de cuatro d\u00e9cadas, Estados Unidos ha basado sus relaciones con el gigante asi\u00e1tico en el principio de una &#8216;sola China&#8217;, por el que el \u00fanico Gobierno chino al que reconoce Washington es el de Pek\u00edn, lo que le aleja de las aspiraciones independentistas de Taiw\u00e1n.<\/p>\n<p>Trump gener\u00f3 tensiones en China al aceptar recientemente una llamada de la presidenta de Taiw\u00e1n, Tsai Ing-wen, quien le telefone\u00f3 para felicitarle por su victoria en las elecciones presidenciales de noviembre.<\/p>\n<p>&#8216;No quiero que China me dicte (lo que tengo que hacer) y esta fue una llamada que me pasaron, yo no inici\u00e9 la llamada, y fue una llamada muy corta que dec\u00eda &#8216;felicidades por su victoria\u00bb, subray\u00f3 hoy Trump al asegurar que habr\u00eda sido &#8216;irrespetuoso&#8217; rechazar la llamada.<\/p><div class=\"notic-content-middle\" id=\"notic-3286381159\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Trump argument\u00f3 que a Estados Unidos le est\u00e1 &#8216;da\u00f1ando muy profundamente China con su devaluaci\u00f3n (de su divisa), con sus fuertes impuestos en las fronteras cuando nosotros no les ponemos tasas, con la construcci\u00f3n de una enorme fortaleza en medio del Mar de China Meridional, lo que no deber\u00edan hacer&#8217;.<\/p>\n<p>Argument\u00f3, adem\u00e1s, que Pek\u00edn &#8216;no est\u00e1 ayudando en absoluto con Corea del Norte&#8217; y su programa nuclear, un problema &#8216;que ellos podr\u00edan resolver&#8217;.<\/p>\n<p>El Gobierno chino advirti\u00f3 este mes a Trump de que la \u00fanica manera de mantener la actual cooperaci\u00f3n entre ambos pa\u00edses es el respeto de Washington al principio de una &#8216;sola China&#8217;, dado que el gigante asi\u00e1tico considera a la isla de Taiw\u00e1n como una provincia &#8216;rebelde&#8217; y parte del territorio bajo su soberan\u00eda.<\/p>\n<p>Esa pol\u00edtica ha guiado las relaciones entre EE.UU. y China desde 1972, siete a\u00f1os antes de que restablecieran por completo sus lazos diplom\u00e1ticos, y la actual Casa Blanca de Barack Obama ha advertido de que ese principio es esencial para la estabilidad del di\u00e1logo con Pek\u00edn.<\/p>","protected":false},"excerpt":{"rendered":"<p>Washington &#8211; El presidente electo de EE.UU., Donald Trump, puso hoy en duda que sea necesario seguir con la pol\u00edtica de &#8216;una sola China&#8217; que ha supuesto la base de las relaciones bilaterales desde 1972 y asegur\u00f3 que no permitir\u00e1 que el gigante asi\u00e1tico le &#8216;dicte&#8217; lo que debe hacer. &#8216;No s\u00e9 por qu\u00e9 tenemos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-51576","post","type-post","status-publish","format-standard","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51576"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51576\/revisions"}],"predecessor-version":[{"id":500249,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51576\/revisions\/500249"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}