{"id":51434,"date":"2016-04-20T00:00:00","date_gmt":"2016-04-20T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20160420\/hacienda-anuncia-mayor-control-sobre-iglesias\/"},"modified":"2025-07-26T12:40:27","modified_gmt":"2025-07-26T12:40:27","slug":"hacienda-anuncia-mayor-control-sobre-iglesias","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20160420\/hacienda-anuncia-mayor-control-sobre-iglesias\/","title":{"rendered":"Hacienda anuncia mayor control sobre iglesias"},"content":{"rendered":"<p>El secretario del Departamento de Hacienda de Puerto Rico, Juan Zaragoza, anunci\u00f3 mayor control fiscal sobre las miles de iglesias que operan en la isla con amplias exenciones tributarias, para detectar posibles actividades lucrativas impropias de su condici\u00f3n.<\/p>\n<p>El anuncio de Zaragoza, que dio a entender que algunas iglesias realizan actividades lucrativas de forma enmascarada, fue respondido hoy, mi\u00e9rcoles, con cierta indignaci\u00f3n por el presidente de la iglesia Ministerio Clamor de Dios Internacional, Jorge Raschke, quien dijo a Efe que las palabras del funcionario molestaron por generalizar.<\/p>\n<p>&#8216;Si hay alguna iglesia en particular de la que tiene evidencia -de funcionar como entidad con \u00e1nimo de lucro- que lo diga, pero que no generalice&#8217;, indic\u00f3 el reverendo, que tambi\u00e9n es ministro del Concilio Asambleas de Dios en su cap\u00edtulo de Puerto Rico, organizaci\u00f3n de fe pentecostal que agrupa a iglesias evang\u00e9licas.<\/p>\n<p>El tema gan\u00f3 actualidad cuando la semana pasada acab\u00f3 el plazo para la presentaci\u00f3n de la declaraci\u00f3n sobre ingresos a Hacienda, entidad que debido a los problemas de liquideztrata de que ning\u00fan contribuyente escape sin pagar lo que debe.<\/p>\n<p>Desde hace a\u00f1os, la presencia de miles de iglesias en Puerto Rico levanta sospechas sobre si realmente estas instituciones tiene un fin espiritual, ya que hay miles en la isla y muchas gozan de beneficios tributarios y subvenciones muy ventajosos.<\/p>\n<p>El C\u00f3digo de Rentas Internas establece que las organizaciones religiosas est\u00e1n exentas de contribuciones sobre ingresos, siempre que ninguna de cuyas actividades redunde en beneficio de alg\u00fan accionista o individuo particular.<\/p>\n<p>&#8216;No se puede sembrar la duda por tres malandros -delincuentes-&#8216;, indic\u00f3 Raschke, tras apuntar que con la decisi\u00f3n de fiscalizar a las iglesias Hacienda se mete con un sector que &#8216;ayuda al pa\u00eds&#8217; por medio de su labor social.<\/p>\n<p>Raschke aprovech\u00f3 adem\u00e1s para pedir &#8216;igualdad con la Iglesia Cat\u00f3lica&#8217;, dando a entender que los Gobiernos puertorrique\u00f1os han favorecido tradicionalmente a esa confesi\u00f3n.<\/p>\n<p>El portavoz del colectivo Dios le debe a Hacienda, Amado Mart\u00ednez, dijo hoy a Efe que en Puerto Rico hay m\u00e1s de 6,000 organizaciones que dicen llevar a cabo una actividad de naturaleza religiosa y que se benefician de exenciones fiscales.<\/p><div class=\"notic-content-middle\" id=\"notic-303600985\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Mart\u00ednez record\u00f3 que estas instituciones supuestamente religiosas no pagan impuestos por no llevar a cabo actividades econ\u00f3micas, cuando realmente algunas se montan con el objetivo de obtener beneficios.<\/p>\n<p>Adem\u00e1s, no rinden a Hacienda ning\u00fan tipo de informe de sus cuentas, y gozan de subsidios en el pago de luz y agua, o a la hora de tributar por la adquisici\u00f3n de bienes inmuebles, as\u00ed como por la compra de veh\u00edculos.<\/p>\n<p>&#8216;Las iglesias se benefician de la aportaci\u00f3n -por parte de sus fieles- de donativos a cambio de la salvaci\u00f3n&#8217;, dijo Mart\u00ednez para poner un ejemplo de c\u00f3mo estas instituciones se lucran con ingresos que no repercuten en Hacienda.<\/p>\n<p>Mart\u00ednez subray\u00f3 que una de los posibles motivos de la gran proliferaci\u00f3n de iglesias en la isla es que estas instituciones pueden ponerse a funcionar sin ni siquiera tener que solicitar un permiso para ejercer su actividad.<\/p>\n<p>Dijo que en la pr\u00e1ctica cualquier persona, sin tener que pasar por un seminario o recibir formaci\u00f3n espec\u00edfica, puede comenzar a ejercer en Puerto Rico como pastor.<\/p>\n<p>Record\u00f3 que las organizaciones sin fines de lucro no religiosas tienen que rendir un informe con datos de ingresos y gastos, entre otros detalles financieros, al Departamento de Hacienda, mientras que las iglesias est\u00e1n exentas.<\/p>\n<p>Uno de los mejores ejemplos de lucro de estas organizaciones, seg\u00fan la informaci\u00f3n aportada por Mart\u00ednez, es que centros de tratamiento asociados a las instituciones religiosas prestan servicios a enfermos usando como terapia la oraci\u00f3n a cambio de dinero, recibido en forma de donaciones.<\/p>\n<p>La organizaci\u00f3n Dios le debe a Hacienda calcula que si las iglesias tributasen por su actividad cada a\u00f1o se recaudar\u00edan cerca de 200 millones de d\u00f3lares.<\/p>\n<p>De las cr\u00edticas tampoco se escapa la Iglesia cat\u00f3lica, que seg\u00fan denuncia la organizaci\u00f3n, cuenta con innumerables propiedades que gozan del beneficio tributario por su condici\u00f3n pero que son alquiladas a terceros generando un beneficio por el que no tributan.<\/p>","protected":false},"excerpt":{"rendered":"<p>El secretario del Departamento de Hacienda de Puerto Rico, Juan Zaragoza, anunci\u00f3 mayor control fiscal sobre las miles de iglesias que operan en la isla con amplias exenciones tributarias, para detectar posibles actividades lucrativas impropias de su condici\u00f3n. El anuncio de Zaragoza, que dio a entender que algunas iglesias realizan actividades lucrativas de forma enmascarada, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":582627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-51434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51434"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51434\/revisions"}],"predecessor-version":[{"id":582645,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51434\/revisions\/582645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/582627"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}