{"id":51341,"date":"2015-02-16T00:00:00","date_gmt":"2015-02-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20150216\/enrique-iglesias-y-pitbull-culminaran-su-gira-en-el-choliseo\/"},"modified":"2025-08-17T16:00:51","modified_gmt":"2025-08-17T16:00:51","slug":"enrique-iglesias-y-pitbull-culminaran-su-gira-en-el-choliseo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20150216\/enrique-iglesias-y-pitbull-culminaran-su-gira-en-el-choliseo\/","title":{"rendered":"Enrique Iglesias y Pitbull culminar\u00e1n su gira en el &#8216;Choliseo&#8217;"},"content":{"rendered":"<p>La gira del cantante espa\u00f1ol Enrique Iglesias junto al cantante cubanoamericano Pitbull se ampli\u00f3 a 24 conciertos, que culminar\u00e1 en Puerto Rico en el coliseo Jose Miguel Agrelot.<\/p>\n<p>El concierto se celebrar\u00e1 los d\u00edas viernes, 6 de marzo y s\u00e1bado 7 de marzo de 2015 a las 8:30 p.m. en el Coliseo Jos\u00e9 Miguel Agrelot.<\/p>\n<p>El tema &#8216;Bailando&#8217; de Enrique Iglesias, junto a Gente de Zona y Descemer Bueno, ha logrado mantenerse durante m\u00e1s de nueve meses en el n\u00famero uno de la lista &#8216;Hot Latin Songs&#8217; de Billboard, y Pitbull lanz\u00f3 en noviembre su octavo \u00e1lbum, &#8216;Globalization&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-1590011342\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Mientras, el nuevo sencillo de Pitbull junto a Ne-Yo, tambi\u00e9n continua ocupando los primeros lugares en la radio internacional. El artista se ha convertido en un fen\u00f3meno musical destac\u00e1ndose por sus colaboraciones musicales con las m\u00e1s grandes estrellas del mundo incluyendo a Enrique Iglesias.<\/p>\n<p>El concierto de Enrique Iglesias y Pitbull cuenta con la participaci\u00f3n de bailarines y un grupo de primer\u00edsimos m\u00fasicos. La energ\u00eda y la m\u00fasica de estos cantantes provocar\u00e1 en el Coliseo Jos\u00e9 Miguel Agrelot uno de los mejores espect\u00e1culos del a\u00f1o producido por SBS Entertainment. Con estas presentaciones, su gira concluir\u00e1 en Puerto Rico.<\/p>\n<p>Para boletos acceda www.ticketpop.com.<\/p>","protected":false},"excerpt":{"rendered":"<p>La gira del cantante espa\u00f1ol Enrique Iglesias junto al cantante cubanoamericano Pitbull se ampli\u00f3 a 24 conciertos, que culminar\u00e1 en Puerto Rico en el coliseo Jose Miguel Agrelot. El concierto se celebrar\u00e1 los d\u00edas viernes, 6 de marzo y s\u00e1bado 7 de marzo de 2015 a las 8:30 p.m. en el Coliseo Jos\u00e9 Miguel Agrelot. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":859856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-51341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51341"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51341\/revisions"}],"predecessor-version":[{"id":859921,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51341\/revisions\/859921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/859856"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}