{"id":51049,"date":"2012-07-20T00:00:00","date_gmt":"2012-07-20T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120720\/tren-urbano-interrumpe-servicio-por-agresion-a-nino-y-embarazada\/"},"modified":"2025-08-27T04:45:19","modified_gmt":"2025-08-27T04:45:19","slug":"tren-urbano-interrumpe-servicio-por-agresion-a-nino-y-embarazada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120720\/tren-urbano-interrumpe-servicio-por-agresion-a-nino-y-embarazada\/","title":{"rendered":"Tren Urbano interrumpe servicio por agresi\u00f3n a ni\u00f1o y embarazada"},"content":{"rendered":"<p>El servicio a los pasajeros en la Estaci\u00f3n del Centro M\u00e9dico del Tren Urbano (TU) ser\u00eda restablecido alrededor de la 1:00 pm despu\u00e9s de que fue suspendido temporalmente al resultar herido un individuo que amenaz\u00f3 a un ni\u00f1o de 5 a\u00f1os, quien estaba acompa\u00f1ado por su madre embarazada, en la estaci\u00f3n, inform\u00f3 la directora ejecutiva auxiliar para Transporte de la Autoridad de Carreteras y Transportaci\u00f3n (ACT), Mar\u00eda Elena Cristy.<\/p>\n<p>&#8216;La estaci\u00f3n fue cerrada debido al incidente ocurrido a las 9:30 AM, cuando un individuo amenaz\u00f3 con un arma blanca a un ni\u00f1o de 5 a\u00f1os. En cuesti\u00f3n de segundos el individuo fue neutralizado por Agentes de la Polic\u00eda estatal logrando liberar al ni\u00f1o. Al no someterse al arresto y continuar en actitud descontrolada y amenazante hacia los pasajeros del tren el agente dispar\u00f3 hiri\u00e9ndole en un brazo y logrando el arresto&#8217;, inform\u00f3 Cristy quien indic\u00f3 que la persona recibe atenci\u00f3n en el Centro M\u00e9dico, la cual est\u00e1 consciente y su condici\u00f3n es estable.<\/p>\n<p>&#8216;Para garantizar el servicio a los pasajeros del TU se activ\u00f3 el \u2018Bus Bridge&#8217;, un servicio expreso con autobuses de la AMA entre las estaciones de Cupey y San Francisco&#8217;, a\u00f1adi\u00f3 la ejecutiva.<\/p><div class=\"notic-content-middle\" id=\"notic-1705972152\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Seg\u00fan el parte policial, el agresor herido fue identificado como \u00c1ngel Gabriel Cintr\u00f3n, de 44 a\u00f1os.<\/p>\n<p>La Polic\u00eda inform\u00f3 que Cintr\u00f3n &#8216;se puso agresivo contra una mujer embarazada identificada como Edna Berr\u00edos Otero que se encontraba saliendo de dicha estaci\u00f3n de transporte colectivo&#8217;.<\/p>\n<p>Al lugar lleg\u00f3 Emergencias Medicas Estatal para brindarle los primeros auxilios tanto a la mujer como al asaltante herido, quines fueron transportados posteriormente al hospital Centro M\u00e9dico de R\u00edo Piedras en condici\u00f3n estable.<\/p>","protected":false},"excerpt":{"rendered":"<p>El servicio a los pasajeros en la Estaci\u00f3n del Centro M\u00e9dico del Tren Urbano (TU) ser\u00eda restablecido alrededor de la 1:00 pm despu\u00e9s de que fue suspendido temporalmente al resultar herido un individuo que amenaz\u00f3 a un ni\u00f1o de 5 a\u00f1os, quien estaba acompa\u00f1ado por su madre embarazada, en la estaci\u00f3n, inform\u00f3 la directora ejecutiva [&hellip;]<\/p>","protected":false},"author":0,"featured_media":916070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-51049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=51049"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51049\/revisions"}],"predecessor-version":[{"id":916090,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/51049\/revisions\/916090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/916070"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=51049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=51049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=51049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}