{"id":50906,"date":"2016-11-17T00:00:00","date_gmt":"2016-11-17T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20161117\/apelan-a-la-union-y-resistencia-ante-trump-en-celebracion-de-los-grammy-lat\/"},"modified":"2025-07-18T09:36:24","modified_gmt":"2025-07-18T09:36:24","slug":"apelan-a-la-union-y-resistencia-ante-trump-en-celebracion-de-los-grammy-lat","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20161117\/apelan-a-la-union-y-resistencia-ante-trump-en-celebracion-de-los-grammy-lat\/","title":{"rendered":"Apelan a la uni\u00f3n y resistencia ante Trump en celebraci\u00f3n de los Grammy Lat"},"content":{"rendered":"<p>Artistas nominados a los Grammy Latino y otros m\u00fasicos que participar\u00e1n en los eventos de estos galardones apelaron a la uni\u00f3n y la resistencia de la comunidad hispana tras el triunfo del republicano Donald Trump en las elecciones a la Casa Blanca.<\/p>\n<p>La inesperada victoria del pol\u00e9mico magnate, que propone deportar a millones de inmigrantes hispanos y levantar un muro en la frontera con M\u00e9xico, fue de lo m\u00e1s comentado entre las celebridades que pasaron por la alfombra roja del evento en el que se reconoci\u00f3 a Marc Anthony como Persona del A\u00f1o 2016 de la Academia Latina de Grabaci\u00f3n.<\/p>\n<p>&#8216;Quiz\u00e1 no fue el resultado que nos hubiera encantado escuchar, pero pensamos que ahora vienen los momentos en los que tenemos que demostrar la casta y de que estamos hechos, demostrar como nos podemos unir&#8217;, dijeron los mexicanos Jesse &lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&amp; Joy, que ma\u00f1ana jueves parten en la gala de los Grammy Latino como grandes aspirantes con cuatro nominaciones.\/p<\/p>\n<p>p<\/p>\n<p>Se\u00f1alaron adem\u00e1s que las minor\u00edas, como la latina o la asi\u00e1tica, hacen &#8216;una mayor\u00eda en su conjunto&#8217; en Estados Unidos y defendieron el poder de la m\u00fasica para traspasar fronteras e idiomas y para vencer &#8216;al odio&#8217;.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Trataremos (en el futuro) de dar m\u00e1s amor y sobre todo de unir m\u00e1s que dividir&#8217;, afirmaron.\/p<\/p>\n<p>p<\/p>\n<p>El colombiano Andr\u00e9s Cepeda, por su parte, declar\u00f3: &#8216;Yo creo que (la victoria de Trump) no nos ha gustado mucho a nadie. Pero tengo fe en que una cosa es lo que se dice en campa\u00f1a y otra lo que se puede hacer en una naci\u00f3n como \u00e9sta&#8217;.\/p<\/p>\n<p>p<\/p>\n<p>El m\u00fasico opin\u00f3 que durante las campa\u00f1as electorales se lanzan argumentos &#8216;contundentes&#8217; y &#8216;radicales&#8217; que en la pr\u00e1ctica quiz\u00e1 no sean posibles.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Esperemos que sea as\u00ed. De todas formas, Trump tiene que considerar la importancia de nuestra comunidad en este pa\u00eds. Somos un grupo importante el de los inmigrantes que ha venido conformando esta sociedad as\u00ed que nos merecemos ese respeto&#8217;, a\u00f1adi\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>Por su parte, el d\u00fao mexicano-argentino Sin Bandera indic\u00f3 que ahora &#8216;la incertidumbre es el peor enemigo&#8217;.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;No se saben las medidas que se van a tomar realmente. Por un lado se habla de que est\u00e1 reafirmando sus convicciones, por otro lado se dice que est\u00e1 suavizando este discurso y la informaci\u00f3n encontrada termina por preocupar m\u00e1s a la gente&#8217;, dijo Leonel Garc\u00eda, de Sin Bandera.\/p<\/p>\n<p>p<\/p>\n<p>La dominicana Milly Quezada busc\u00f3 un \u00e1ngulo m\u00e1s optimista y dijo que de la victoria de Trump los latinos deben &#8216;aprender las lecciones&#8217; y &#8216;prepararse mejor&#8217;, dado que tienen el &#8216;poder del cambio de rumbo&#8217; de Estados Unidos.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Todav\u00eda no llegamos a conocer lo que eso significa, pero lo vamos a ir aprendiendo&#8217;, afirm\u00f3.\/p<\/p>\n<p>p<\/p>\n<p>La cantante guatemalteca Gaby Moreno abog\u00f3 por transmitir &#8216;buena energ\u00eda&#8217;, &#8216;positivismo&#8217; y &#8216;esperanza&#8217; para pensar que las cosas &#8216;van a ir bien&#8217;.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Los Grammy Latino es un momento muy especial porque nos une a todos en la m\u00fasica, que es algo tan fuerte, y es un momento para celebrar, para estar juntos y decir que unidos vamos a seguir adelante&#8217;, expuso.\/p<\/p>\n<p>p<\/p>\n<p>Por \u00faltimo, el espa\u00f1ol El Guincho dijo que el momento para la comunidad hispana en Estados Unidos es &#8216;terrible, pero precisamente por eso habr\u00e1 que sacar el orgullo&#8217;.\/p<\/p>\n<p>p<\/p>\n<p>&#8216;Cuando las cosas se ponen feas, es cuando salimos adelante&#8217;, asegur\u00f3.\/p<\/p>","protected":false},"excerpt":{"rendered":"<p>Artistas nominados a los Grammy Latino y otros m\u00fasicos que participar\u00e1n en los eventos de estos galardones apelaron a la uni\u00f3n y la resistencia de la comunidad hispana tras el triunfo del republicano Donald Trump en las elecciones a la Casa Blanca. La inesperada victoria del pol\u00e9mico magnate, que propone deportar a millones de inmigrantes [&hellip;]<\/p>","protected":false},"author":0,"featured_media":509008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-50906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=50906"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50906\/revisions"}],"predecessor-version":[{"id":509017,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50906\/revisions\/509017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/509008"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=50906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=50906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=50906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}