{"id":50811,"date":"2013-10-28T00:00:00","date_gmt":"2013-10-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20131028\/precio-de-leche-no-aumentara-al-menos-por-este-ano-segun-agricultura\/"},"modified":"2025-07-24T07:04:50","modified_gmt":"2025-07-24T07:04:50","slug":"precio-de-leche-no-aumentara-al-menos-por-este-ano-segun-agricultura","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20131028\/precio-de-leche-no-aumentara-al-menos-por-este-ano-segun-agricultura\/","title":{"rendered":"Precio de leche no aumentar\u00e1, al menos por este a\u00f1o, seg\u00fan Agricultura"},"content":{"rendered":"<p>El acuerdo entre el gobierno y las plantas elaboradoras de leche que permitir\u00e1 la paralizaci\u00f3n del aumento en el precio del producto y, a su vez, asegurar los beneficios que estas empresas han solicitado ser\u00e1 presentado ma\u00f1ana, martes, en la sala del juez federal, Daniel Dom\u00ednguez, de acuerdo a la secretaria de Agricultura, Myrna Comas Pag\u00e1n.<\/p>\n<p>No obstante, esa resoluci\u00f3n no garantiza que el costo no aumente el pr\u00f3ximo a\u00f1o. &#8216;En este a\u00f1o no va aumentar el precio de la leche&#8217;, manifest\u00f3 la titular a su salida del Tribunal Federal, donde hoy se celebr\u00f3 una vista de seguimiento en el pleito que lleva casi unos diez a\u00f1os.<\/p>\n<p>El documento debe ponerle fin a una controversia presentada en los tribunales en el 2004 por parte de Suiza Dairy y Tres Monjitas, quienes afirman han perdido millones de d\u00f3lares en la elaboraci\u00f3n del producto. El mismo garantizar\u00eda, adem\u00e1s, que el gobierno deje de invertir miles de d\u00f3lares en el pleito que seg\u00fan Comas Pag\u00e1n, el a\u00f1o pasado el estado pag\u00f3 sobre 800 mil d\u00f3lares.<\/p>\n<p>La titular de Agricultura sostuvo que el Fondo de Eficiencia para la Industria Lechera, creado para mejorar las plantas privadas, se nutrir\u00e1 del Fondo General y neg\u00f3 que se imponga un cargo a los consumidores para allegar capital al mismo. Indic\u00f3 que la cantidad que se transferir\u00e1 al fondo especial este primer a\u00f1o son 58.8 millones que promover\u00e1n la inversi\u00f3n en la elaboraci\u00f3n de leche en la Isla y otra parte ir\u00e1 a incentivos para ganaderos y sus costos de producci\u00f3n de alimentos concentrados.<\/p><div class=\"notic-content-middle\" id=\"notic-2624281618\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Eso es parte del acuerdo. Es una forma de compensar la ganancia dejada de devengar por parte de las plantas&#8217;, contest\u00f3 la secretaria a preguntas de la prensa sobre la subvenci\u00f3n de la administraci\u00f3n de turno a empresas privadas. Seg\u00fan Comas, ORIL estim\u00f3 en 150 millones las p\u00e9rdidas de las plantas elaboradoras, aunque estas certificaron que son 100 millones de d\u00f3lares m\u00e1s.<\/p>\n<p>Por su parte, Francisco P\u00e9rez, gerente general de Suiza, se\u00f1al\u00f3 que la empresa que representa har\u00e1 lo posible para cumplir ese acuerdo, que hasta el momento &#8216;no se ha logrado por asuntos t\u00e9cnicos&#8217;, apunt\u00f3.<\/p>\n<p>&#8216;Si las variables se mantienen constantes, se va a hacer todo lo posible para no aumentar el precio de la leche. Vamos a tener todos los procedimientos eficientes para que la leche no suba&#8217;, a\u00f1adi\u00f3 P\u00e9rez.<\/p>","protected":false},"excerpt":{"rendered":"<p>El acuerdo entre el gobierno y las plantas elaboradoras de leche que permitir\u00e1 la paralizaci\u00f3n del aumento en el precio del producto y, a su vez, asegurar los beneficios que estas empresas han solicitado ser\u00e1 presentado ma\u00f1ana, martes, en la sala del juez federal, Daniel Dom\u00ednguez, de acuerdo a la secretaria de Agricultura, Myrna Comas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":569332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-50811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=50811"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50811\/revisions"}],"predecessor-version":[{"id":569335,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50811\/revisions\/569335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/569332"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=50811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=50811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=50811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}