{"id":50168,"date":"2011-06-18T00:00:00","date_gmt":"2011-06-18T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20110618\/cae-de-nuevo-la-seleccion-en-canada\/"},"modified":"2025-08-29T09:36:22","modified_gmt":"2025-08-29T09:36:22","slug":"cae-de-nuevo-la-seleccion-en-canada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20110618\/cae-de-nuevo-la-seleccion-en-canada\/","title":{"rendered":"Cae de nuevo la selecci\u00f3n en Canad\u00e1"},"content":{"rendered":"<p>Nuevamente, la selecci\u00f3n nacional de voleibol sufri\u00f3 un rev\u00e9s en el voleibol internacional. Esta vez, fue en tres sets.<\/p>\n<p>Luego de un luchado primer parcial, la selecci\u00f3n nacional B no pudo mantener el ritmo y fue superada en parciales consecutivo por Estados Unidos en la semifinal de la VI Copa Panamericana Masculina que se juega en Gatineau, Canad\u00e1.<\/p>\n<p>Los marcadores del partido fueron 25-18, 25-17, 25-14.<\/p><div class=\"notic-content-middle\" id=\"notic-2250403087\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Ezequiel Cruz y Ulises Maldonado fueron los mejores a la ofensiva con 10 puntos cada uno, mientras por los estadounidenses, Jayson Jablonsky que ha jugado en la Isla logro 10 tantos.<\/p>\n<p>La escuadra patria jugara ma\u00f1ana s\u00e1bado 18 de junio el partido por el tercer lugar ante la selecci\u00f3n anfitriona de Canad\u00e1.<\/p>\n<p>Ambos equipos se enfrentaron en la fase preliminar donde los canadienses dominaron en tres parciales (25-17, 25-17, 25-17).<\/p>","protected":false},"excerpt":{"rendered":"<p>Nuevamente, la selecci\u00f3n nacional de voleibol sufri\u00f3 un rev\u00e9s en el voleibol internacional. Esta vez, fue en tres sets. Luego de un luchado primer parcial, la selecci\u00f3n nacional B no pudo mantener el ritmo y fue superada en parciales consecutivo por Estados Unidos en la semifinal de la VI Copa Panamericana Masculina que se juega [&hellip;]<\/p>","protected":false},"author":0,"featured_media":934387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-50168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=50168"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50168\/revisions"}],"predecessor-version":[{"id":934396,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/50168\/revisions\/934396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/934387"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=50168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=50168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=50168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}