{"id":49739,"date":"2016-03-08T00:00:00","date_gmt":"2016-03-08T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20160308\/senado-investigara-discrimen-de-precios-por-genero\/"},"modified":"2025-07-25T22:01:12","modified_gmt":"2025-07-25T22:01:12","slug":"senado-investigara-discrimen-de-precios-por-genero","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20160308\/senado-investigara-discrimen-de-precios-por-genero\/","title":{"rendered":"Senado investigar\u00e1 discrimen de precios por g\u00e9nero"},"content":{"rendered":"<p>Los senadores Jose Nadal Power, Mari Tere Gonz\u00e1lez L\u00f3pez y Luis Daniel Rivera Filomeno, radicaron el martes la Resoluci\u00f3n del Senado 1346, con el prop\u00f3sito de investigar si en Puerto Rico existe discriminaci\u00f3n de precios en los art\u00edculos y servicios dependiendo del genero del consumidor al que van dirigidos.<\/p>\n<p>&#8216;Es precisamente en esta Semana de la Mujer que le presentamos al Pa\u00eds esta propuesta que busca aportar a la lucha por la equidad. Ya tenemos referencias confiables de la injusticia que se comete contra la mujer hasta en los precios de los art\u00edculos de uso general. Desde el 1996, el estado de California estudi\u00f3 el tema y radic\u00f3 legislaci\u00f3n para prohibir el discrimen por precio a base de g\u00e9nero. La ciudad de Nueva York y el condado de Miami-Dade en la Florida tambi\u00e9n han dado ese paso&#8217;, asegur\u00f3 Gonz\u00e1lez L\u00f3pez.<\/p>\n<p>Mientras, el senador Nadal Power expres\u00f3 su apoyo a la medida pues ante investigaciones llevadas a cabo en otros lugares, &#8216;nos sentimos obligados a asegurarnos de que tales pr\u00e1cticas no se den en Puerto Rico. Con esta investigaci\u00f3n buscamos averiguar si en nuestro Pa\u00eds existe un patr\u00f3n de discrimen de precio a base de g\u00e9nero. Este estudio no se ha realizado todav\u00eda y es esencial conocer c\u00f3mo se comportan los precios en este aspecto.&#8217;<\/p><div class=\"notic-content-middle\" id=\"notic-3888560165\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Por su parte, el senador Rivera Filomeno, catalog\u00f3 que ins\u00f3lito que &#8216;un desodorante sea 30 por ciento m\u00e1s caro en su versi\u00f3n femenina versus la versi\u00f3n masculina. Estos son datos de un reporte de la Universidad de la Florida Central. Las mujeres no tienen que pagar m\u00e1s por el mero hecho de ser mujeres. Aqu\u00ed no estamos hablando de productos distintos, son ciertamente las mismas versiones, en algunos casos con diferencias de color o de dise\u00f1o de empaque. En la Comisi\u00f3n de Relaciones Laborales, Asuntos del Consumidor y Creaci\u00f3n de Empleos, recibimos esta Resoluci\u00f3n del Senado 1346 con mucho sentido de responsabilidad y justicia&#8217;.<\/p>\n<p>&#8216;Hoy que se celebra el d\u00eda Internacional de la Mujer, nosotros en la asamblea legislativa tenemos una obligaci\u00f3n moral de reiterar nuestro compromiso por la igualdad y la equidad de todas las personas en nuestro Pa\u00eds. Si a trav\u00e9s de las vistas p\u00fablicas descubrimos que hay un patr\u00f3n de discrimen de precio por parte de negocios en Puerto Rico, vamos a legislar. Vivimos en el Siglo 21, definitivamente no hay espacio para este tipo de comportamiento&#8217;, concluyeron los funcionarios.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los senadores Jose Nadal Power, Mari Tere Gonz\u00e1lez L\u00f3pez y Luis Daniel Rivera Filomeno, radicaron el martes la Resoluci\u00f3n del Senado 1346, con el prop\u00f3sito de investigar si en Puerto Rico existe discriminaci\u00f3n de precios en los art\u00edculos y servicios dependiendo del genero del consumidor al que van dirigidos. &#8216;Es precisamente en esta Semana de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":577346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-49739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=49739"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49739\/revisions"}],"predecessor-version":[{"id":577365,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49739\/revisions\/577365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/577346"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=49739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=49739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=49739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}