{"id":496829,"date":"2025-04-14T15:34:45","date_gmt":"2025-04-14T19:34:45","guid":{"rendered":"https:\/\/www.noticel.com\/estados-unidos\/20250414\/en-agenda-la-seleccion-del-jurado-para-el-nuevo-juicio-contra-weinstein\/"},"modified":"2025-07-19T08:32:11","modified_gmt":"2025-07-19T08:32:11","slug":"en-agenda-la-seleccion-del-jurado-para-el-nuevo-juicio-contra-weinstein","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/estados-unidos\/20250414\/en-agenda-la-seleccion-del-jurado-para-el-nuevo-juicio-contra-weinstein\/","title":{"rendered":"En agenda la selecci\u00f3n del jurado para el nuevo juicio contra Weinstein"},"content":{"rendered":"<h3>Su defensa anul\u00f3 la sentencia de 23 a\u00f1os en apelaci\u00f3n al argumentar errores procesales.<\/h3>\n<p>El nuevo juicio contra el productor de cine Harvey Weinstein comienza ma\u00f1ana, martes, en Nueva York, con la selecci\u00f3n del jurado que examinar\u00e1 los elementos que podr\u00edan suponer una nueva condena en esta ciudad que se sume a la que cumple por otro caso abierto en California.<\/p>\n<p>En el juicio celebrado en 2020 en el que se le acus\u00f3 de violaci\u00f3n y agresi\u00f3n sexual, Weistein fue condenado a 23 a\u00f1os de prisi\u00f3n, pero en abril de 2024 su defensa logr\u00f3 anular la sentencia en apelaci\u00f3n al argumentar errores procesales y el juez orden\u00f3 un nuevo juicio.<\/p>\n<p>Ahora, sus abogados esperan que un cambio de juez y el clima pol\u00edtico actual puedan beneficiar al acusado.<\/p>\n<p>\u00abVa a ser un juicio muy diferente. La mentalidad de mafia que fue tan pronunciada en su primer juicio, creo, ha remitido&#8230; Va a tener el juicio que deber\u00eda haber tenido desde el principio\u00bb, asegur\u00f3 una de sus letradas, Jennifer Bonjean, seg\u00fan recoge Variety.<\/p>\n<p>La selecci\u00f3n del jurado se espera que dure varios d\u00edas, en el que se tendr\u00e1n en cuenta los posibles sesgos y el conocimiento de los miembros de este grupo sobre el acusado de alto perfil, convertido en un s\u00edmbolo de las denuncias de mujeres en la industria del cine, que dieron lugar al movimiento #MeToo.<\/p>\n<p>Los alegatos iniciales est\u00e1n fijados provisionalmente para el pr\u00f3ximo 22 de abril y el juicio podr\u00eda durar entre cuatro y cinco semanas.<\/p>\n<p>El pasado septiembre, la Fiscal\u00eda de Manhattan acus\u00f3 a Weinstein de un nuevo delito sexual contra una mujer supuestamente cometido en 2006 y el juez Curtis Farber accedi\u00f3 a sumar esa acusaci\u00f3n a las del juicio por el caso original que fue anulado, en lugar de establecer dos procesos separados.<\/p><div class=\"notic-content-middle\" id=\"notic-2449645831\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La principal diferencia respecto al anterior juicio es el n\u00famero de acusados, puesto que en el primero seis mujeres testificaron -tres cuyas alegaciones era la base de los cargos judiciales y tres para dar credibilidad-, mientras que decenas m\u00e1s presentaron acusaciones p\u00fablicas contra \u00e9l.<\/p>\n<p>Sin embargo, el Tribunal de Apelaciones dictamin\u00f3 que los testigos adicionales sesgaban el caso, por lo que s\u00f3lo llamar\u00e1 a tres mujeres a testificar: Miriam Haley, Jessica Mann y una mujer conocida hasta ahora como &#8216;CW-3&#8217;. Haley y Mann ya expusieron sus alegaciones en 2020.<\/p>\n<p>Se trata as\u00ed del tercer juicio penal en contra de Weinstein, de 73 a\u00f1os, quien permanece encarcelado en la prisi\u00f3n de Rikers (Nueva York) desde que fue declarado culpable por otra condena de 16 a\u00f1os por delitos sexuales cometidos en California, aunque el pasado diciembre fue trasladado a un hospital para una cirug\u00eda card\u00edaca de emergencia.<\/p>\n<p>La salud del exproductor se agrav\u00f3 recientemente puesto que est\u00e1 recibiendo tratamiento por un c\u00e1ncer de m\u00e9dula \u00f3sea, por lo que acudi\u00f3 en silla de ruedas a la m\u00e1s reciente audiencia del tribunal y sugiri\u00f3 que podr\u00eda morir pronto.<\/p>\n<p>\u00abNo voy a estar ah\u00ed en abril. No puedo esperar a ma\u00f1ana. No puedo aguantar m\u00e1s. Estoy aguantando porque quiero justicia, quiero que esto se acabe\u00bb, implor\u00f3 Weinstein en aquel momento.<\/p>\n<p>El productor de &#8216;Pulp Fiction&#8217; y de otras pel\u00edculas ic\u00f3nicas se ha declarado no culpable del nuevo delito del que se le acus\u00f3 en septiembre, igual que de las acusaciones previas por las que fue juzgado en 2020.<\/p>","protected":false},"excerpt":{"rendered":"<p>Su defensa anul\u00f3 la sentencia de 23 a\u00f1os en apelaci\u00f3n al argumentar errores procesales. El nuevo juicio contra el productor de cine Harvey Weinstein comienza ma\u00f1ana, martes, en Nueva York, con la selecci\u00f3n del jurado que examinar\u00e1 los elementos que podr\u00edan suponer una nueva condena en esta ciudad que se sume a la que cumple [&hellip;]<\/p>","protected":false},"author":0,"featured_media":526510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-496829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados-unidos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/496829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=496829"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/496829\/revisions"}],"predecessor-version":[{"id":526511,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/496829\/revisions\/526511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/526510"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=496829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=496829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=496829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}