{"id":495646,"date":"2025-03-06T11:44:20","date_gmt":"2025-03-06T15:44:20","guid":{"rendered":"https:\/\/www.noticel.com\/pop\/vida\/20250306\/feria-de-artesanias-de-ponce-celebrara-medio-siglo-de-historia\/"},"modified":"2025-07-19T12:48:08","modified_gmt":"2025-07-19T12:48:08","slug":"feria-de-artesanias-de-ponce-celebrara-medio-siglo-de-historia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20250306\/feria-de-artesanias-de-ponce-celebrara-medio-siglo-de-historia\/","title":{"rendered":"Feria de Artesan\u00edas de Ponce celebrar\u00e1 medio siglo de historia"},"content":{"rendered":"<h3>Se llevar\u00e1 a cabo del viernes 14 al domingo 16 de marzo en la Plaza Las Delicias.<\/h3>\n<p>La tradicional Feria de Artesan\u00edas del Centro Cultural Carmen Sol\u00e1 de Pereira celebrar\u00e1 medio siglo de historia y tradici\u00f3n a trav\u00e9s de un multitudinario evento que se llevar\u00e1 a cabo del viernes 14 al domingo 16 de marzo en la Plaza Las Delicias de esta ciudad, a donde tambi\u00e9n se realizar\u00e1 la 39na Muestra de Arte.<\/p>\n<p>All\u00ed se juntar\u00e1n unos 150 artesanos y cerca de 30 artistas pl\u00e1sticos quienes presentar\u00e1n lo mejor de sus respectivas obras para el deleite de los asistentes, adem\u00e1s de talleres gratuitos, buena m\u00fasica y lo mejor de nuestra gastronom\u00eda puertorrique\u00f1a.<\/p>\n<p>De acuerdo con la presidenta de la Junta de Directores, Ana Iris Torres, \u201cestamos muy contentos del respaldo del pueblo a nuestro evento m\u00e1s importante pues, a\u00f1o tras a\u00f1o se allegan al casco urbano de Ponce para compartir nuestras costumbres y tradiciones, en un ambiente sano y familiar\u201d.<\/p>\n<p>\u201cLa Feria de Artesan\u00edas es nuestro homenaje a los hacedores del arte popular que se esmeran en promover sus piezas hechas con amor y respeto a nuestros valores culturales. Son hombres y mujeres que, d\u00eda a d\u00eda se levantan contra viento y marea y, con el talento moldeado por sus manos, materializan la cotidianeidad de nuestro amado archipi\u00e9lago\u201d, se\u00f1al\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-2000806003\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El evento se dedicar\u00e1 a los artesanos Guillermo Vidr\u00f3 Echevarr\u00eda (estampas t\u00edpicas, casitas y pilones a mano), Wilfredo P\u00e9rez Gonz\u00e1lez (talla de carretas en madera), Pablo Maysonet V\u00e1zquez, (serigraf\u00eda en tela) y Yadira Gonz\u00e1lez P\u00e9rez (carteras en saco, pintura y petate).<\/p>\n<p>Adem\u00e1s, se reconocer\u00e1 la labor de Wilmer Jobeth Fern\u00e1ndez y Mikeyla Jerian Maldonado Mel\u00e9ndez, de la industria creativa Sal\u00f3n Boricua.<\/p>\n<p>De otra parte, la oferta musical estar\u00e1 a cargo de Pleneros de la Cresta, Atabal, Grupo Esencia, Juan Riestra y Los Bohiques, Saz\u00f3n Criollo, Pleneros de Ponce, Lucy Nev\u00e1rez, Cuarteto Tabonuco, Ricardo Jes\u00fas, Carlos Cruz y su grupo y el trovador Guersom B\u00e1ez con el grupo Alambique.<\/p>\n<p>Igualmente, subir\u00e1n a tarima los grupos de bomba puertorrique\u00f1a El escuadr\u00f3n y Cunyabe, y los j\u00f3venes del Instituto de M\u00fasica Juan Morel Campos y la Escuela Libre de M\u00fasica de Ponce, entre otros talentos que se unir\u00e1n a esta gran celebraci\u00f3n a donde habr\u00e1 talleres de chiringas para ni\u00f1os y adultos, cester\u00eda y dibujo, entre otros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Se llevar\u00e1 a cabo del viernes 14 al domingo 16 de marzo en la Plaza Las Delicias. La tradicional Feria de Artesan\u00edas del Centro Cultural Carmen Sol\u00e1 de Pereira celebrar\u00e1 medio siglo de historia y tradici\u00f3n a trav\u00e9s de un multitudinario evento que se llevar\u00e1 a cabo del viernes 14 al domingo 16 de marzo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":528808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-495646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/495646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=495646"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/495646\/revisions"}],"predecessor-version":[{"id":528810,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/495646\/revisions\/528810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/528808"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=495646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=495646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=495646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}