{"id":49313,"date":"2015-12-19T00:00:00","date_gmt":"2015-12-19T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20151219\/cortometraje-sobre-una-nina-en-contra-del-machismo-conmueve-a-millones\/"},"modified":"2025-07-29T14:37:54","modified_gmt":"2025-07-29T14:37:54","slug":"cortometraje-sobre-una-nina-en-contra-del-machismo-conmueve-a-millones","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20151219\/cortometraje-sobre-una-nina-en-contra-del-machismo-conmueve-a-millones\/","title":{"rendered":"Cortometraje sobre una ni\u00f1a en contra del machismo conmueve a millones"},"content":{"rendered":"<p>Una organizaci\u00f3n Noruega ha creado un cortometraje para concienciar a la comunidad sobre la subliminalidad y el impacto del machismo hasta en sus primeras expresiones.<\/p>\n<p>En el video se puede ver el desarrollo de una joven. Ella le habla a su padre y le cuenta c\u00f3mo ser\u00e1 tratada por los hombres que ir\u00e1n apareciendo en su vida.M\u00e1s de dos millones de personas han visto este video. El mensaje que entrega es relevante y necesita ser difundido a gran escala.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una organizaci\u00f3n Noruega ha creado un cortometraje para concienciar a la comunidad sobre la subliminalidad y el impacto del machismo hasta en sus primeras expresiones. En el video se puede ver el desarrollo de una joven. Ella le habla a su padre y le cuenta c\u00f3mo ser\u00e1 tratada por los hombres que ir\u00e1n apareciendo en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":609128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-49313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=49313"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49313\/revisions"}],"predecessor-version":[{"id":609153,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/49313\/revisions\/609153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/609128"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=49313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=49313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=49313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}