{"id":48561,"date":"2016-04-11T00:00:00","date_gmt":"2016-04-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20160411\/angel-rosa-habla-de-los-errores-de-borrador-de-junta-de-control\/"},"modified":"2025-07-28T05:00:26","modified_gmt":"2025-07-28T05:00:26","slug":"angel-rosa-habla-de-los-errores-de-borrador-de-junta-de-control","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160411\/angel-rosa-habla-de-los-errores-de-borrador-de-junta-de-control\/","title":{"rendered":"\u00c1ngel Rosa habla de los &#8216;errores&#8217; de borrador de Junta de Control"},"content":{"rendered":"<p>El senador y candidato a comisionado residente del Partido Popular Democr\u00e1tico (PPD), \u00c1ngel Rosa, dijo el lunes que ning\u00fan congresista podr\u00eda aceptar lo propuesto en el borrador de proyecto de Junta de Control Fiscal federal.<\/p>\n<p>&#8216;El Plan Republicano del Congreso tiene dos problemas fundamentales: no incluye nada que promueva el desarrollo econ\u00f3mico para Puerto Rico y violenta los derechos democr\u00e1ticos de los puertorrique\u00f1os. Eso no es aceptable tal como fue publicado y ning\u00fan Congresista aceptar\u00eda una propuesta como esa para su estado. Considero que cualquier reestructuraci\u00f3n federal de la deuda tiene que venir acompa\u00f1ada de supervisi\u00f3n federal, pero lo que se propone actualmente es totalmente contrario a las practicas b\u00e1sicas de la democracia&#8217; dijo Rosa en comunicado de prensa.<\/p>\n<p>Seg\u00fan el senador, la Junta de Control propuesta en el borrador del proyecto congresional republicano, no tendr\u00eda ninguna legitimidad democr\u00e1tica en la medida en que sus miembros ser\u00edan nombrados a trav\u00e9s de un proceso pol\u00edtico en el cual Puerto Rico no tiene ninguna participaci\u00f3n. Indica adem\u00e1s, que el borrador, viola el principio democr\u00e1tico b\u00e1sico de no impuestos sin representaci\u00f3n (no taxation without representation), ya que el mismo le permite a la Junta de Control Federal aumentar los impuestos unilateralmente sin que haya evaluaci\u00f3n alguna del pueblo puertorrique\u00f1o.<\/p><div class=\"notic-content-middle\" id=\"notic-1235599959\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;La mejor alternativa para salir de la crisis es una colaboraci\u00f3n entre el pueblo de Puerto Rico y los Estados Unidos para poder darle continuidad a las reformas que Puerto Rico necesita. Hemos hecho un an\u00e1lisis serio de la propuesta republicana y planteamos posibles soluciones que toman en consideraci\u00f3n el ambiente pol\u00edtico que hay en Washington,&#8217; expres\u00f3.<\/p>\n<p>Rosa partir\u00e1 a Washington D.C., para discutir su an\u00e1lisis con miembros del comit\u00e9 de Recursos Naturales del Congreso.<\/p>","protected":false},"excerpt":{"rendered":"<p>El senador y candidato a comisionado residente del Partido Popular Democr\u00e1tico (PPD), \u00c1ngel Rosa, dijo el lunes que ning\u00fan congresista podr\u00eda aceptar lo propuesto en el borrador de proyecto de Junta de Control Fiscal federal. &#8216;El Plan Republicano del Congreso tiene dos problemas fundamentales: no incluye nada que promueva el desarrollo econ\u00f3mico para Puerto Rico [&hellip;]<\/p>","protected":false},"author":0,"featured_media":597280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-48561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/48561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=48561"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/48561\/revisions"}],"predecessor-version":[{"id":597302,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/48561\/revisions\/597302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/597280"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=48561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=48561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=48561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}