{"id":47462,"date":"2015-11-28T00:00:00","date_gmt":"2015-11-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20151128\/la-gioconda-o-el-beso-en-bloques-lego\/"},"modified":"2025-07-26T22:10:36","modified_gmt":"2025-07-26T22:10:36","slug":"la-gioconda-o-el-beso-en-bloques-lego","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20151128\/la-gioconda-o-el-beso-en-bloques-lego\/","title":{"rendered":"La Gioconda o &#8216;El beso&#8217; en bloques Lego"},"content":{"rendered":"<p>La capital italiana acoge la muestra itinerante &#8216;The Art of The Brick&#8217;, que expone m\u00e1s de ochenta obras de arte, entre ellas la Gioconda o la escultura del emperador Augusto, construidas a partir de bloques de Lego.<\/p>\n<p>Estas singulares esculturas son obra de Nathan Sawaya, un neoyorquino que abandon\u00f3 su profesi\u00f3n de abogado para dar rienda suelta a su pasi\u00f3n infantil: la construcci\u00f3n de figuras a partir de estos populares ladrillos de pl\u00e1stico.<\/p>\n<p>Est\u00e1n construidas con casi un mill\u00f3n de bloques de Lego de todos los colores y en ellas el artista recrea los planetas, las obras de arte de la antig\u00fcedad y reflexiona sobre los problemas del hombre contempor\u00e1neo.<\/p>\n<p>Entre las esculturas cl\u00e1sicas, los visitantes podr\u00e1n contemplar una esfinge, un Buda sentado tailand\u00e9s, la c\u00e9lebre Venus de Milo o una imponente representaci\u00f3n del primer emperador romano, Augusto.<\/p>\n<p>Para la elaboraci\u00f3n de esta \u00faltima emple\u00f3 dos d\u00edas \u00fanicamente para realizar la peana y los pies y se\u00f1al\u00f3 que &#8216;la escala utilizada para esta versi\u00f3n representa el mayor reto de esta escultura&#8217;, seg\u00fan consta en el cat\u00e1logo de la muestra.<\/p>\n<p>Adem\u00e1s, tambi\u00e9n se podr\u00e1n ver en esta edici\u00f3n una reproducci\u00f3n a gran tama\u00f1o del Parten\u00f3n de Atenas, el Disc\u00f3bolo o el Pensador de Auguste Rodin, creados todos ellos con piezas monocrom\u00e1ticas.<\/p>\n<p>En otra de las salas se exponen varias versiones de obras como la &#8216;Mona Lisa&#8217;, la &#8216;Creaci\u00f3n de Ad\u00e1n&#8217;, presente en los frescos de la Capilla Sixtina del Vaticano, o las versiones tridimensionales de &#8216;El grito&#8217; de Edvard Munch o &#8216;El beso&#8217; de Gustav Klimt.<\/p><div class=\"notic-content-middle\" id=\"notic-1998570114\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Sawaya, quien busca reflexionar sobre el arte y la creatividad en nuestra \u00e9poca, tambi\u00e9n ha creado, siempre con bloques, numerosas piezas propias como &#8216;Yellow&#8217;, una de sus esculturas m\u00e1s famosas en las que un hombre se abre el pecho, desbordado de bloques amarillos.<\/p>\n<p>El comisario de la exposici\u00f3n Fabio Di Gioia, explic\u00f3 a Efe que aunque Italia es &#8216;un pa\u00eds de mucha fantas\u00eda, color y optimismo&#8217; se &#8216;concibe el arte de una manera tradicional&#8217;, as\u00ed que cuando acuden a esta exposici\u00f3n los italianos se sorprenden.<\/p>\n<p>&#8216;Esta expresi\u00f3n contempor\u00e1nea es una superaci\u00f3n, se quedan sorprendidos&#8217;, afirm\u00f3 Di Gioia.<\/p>\n<p>En su opini\u00f3n, el estilo de Sawaya es un &#8216;arte democr\u00e1tico&#8217;, porque cualquiera puede crearlo.<\/p>\n<p>Y las palabras de Sawaya, reproducidas en varias pantallas de la sala de exposiciones, le dan la raz\u00f3n: &#8216;El arte se nutre de pensamiento. Est\u00e9 hecho de creta, de pintura, de madera o de juguetes modernos&#8217;.<\/p>\n<p>La exposici\u00f3n podr\u00e1 apreciarse en el romano Spazio Eventi SET hasta el 14 de febrero, informaron los organizadores.<\/p>","protected":false},"excerpt":{"rendered":"<p>La capital italiana acoge la muestra itinerante &#8216;The Art of The Brick&#8217;, que expone m\u00e1s de ochenta obras de arte, entre ellas la Gioconda o la escultura del emperador Augusto, construidas a partir de bloques de Lego. Estas singulares esculturas son obra de Nathan Sawaya, un neoyorquino que abandon\u00f3 su profesi\u00f3n de abogado para dar [&hellip;]<\/p>","protected":false},"author":0,"featured_media":586028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-47462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/47462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=47462"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/47462\/revisions"}],"predecessor-version":[{"id":586048,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/47462\/revisions\/586048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/586028"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=47462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=47462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=47462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}