{"id":45212,"date":"2013-12-23T00:00:00","date_gmt":"2013-12-23T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20131223\/obama-solicitara-un-nuevo-seguro-medico\/"},"modified":"2025-08-22T15:11:10","modified_gmt":"2025-08-22T15:11:10","slug":"obama-solicitara-un-nuevo-seguro-medico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20131223\/obama-solicitara-un-nuevo-seguro-medico\/","title":{"rendered":"Obama solicitar\u00e1 un nuevo seguro m\u00e9dico"},"content":{"rendered":"<p>El presidente estadounidense, Barack Obama, no ser\u00e1 una excepci\u00f3n y como un estadounidense m\u00e1s se inscribir\u00e1 antes de que termine el d\u00eda de hoy para poder tener cobertura medica desde el 1 de enero bajo las nuevas condiciones de la reforma que el mismo promovi\u00f3.<\/p>\n<p>Hoy, 23 de diciembre, finaliza el plazo para aquellos que deban contratar una nueva p\u00f3liza de seguro y quieran estar cubiertos desde el 1 de enero.<\/p>\n<p>Seg\u00fan indic\u00f3 la asesora de la Casa Blanca Valerie Jarrett en una entrevista de radio, el presidente, que se encuentra de vacaciones en Hawai, contratar\u00e1 su seguro m\u00e9dico en la web p\u00fablica Healthcare.gov a fin de cumplir con los plazos de la reforma sanitaria.<\/p>\n<p>Los congresistas republicanos han pedido a la administraci\u00f3n de Barack Obama que d\u00e9 ejemplo inscribi\u00e9ndose en las nuevas p\u00f3lizas de seguros.<\/p>\n<p>La Casa Blanca ha reiterado en varias ocasiones que el presidente se iba a inscribir a trav\u00e9s de la nueva web, pero no especific\u00f3 la fecha.<\/p><div class=\"notic-content-middle\" id=\"notic-1636202654\"><div class=\"notic-adlabel\">Advertisements<\/div><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/div>\n<p>El presidente y su familia no ten\u00edan necesidad de inscribirse en el nuevo mercado online de seguros m\u00e9dicos, ya que tienen garantizado tratamiento gratuito de por vida en hospitales militares estadounidenses.<\/p>\n<p>Debido a los problemas de puesta en marcha de la reforma sanitaria el plazo inicial de registro, fijado para el 15 de diciembre, se extendi\u00f3 hasta el d\u00eda 23 y millones de estadounidenses est\u00e1n exentos incluso de este \u00faltimo plazo debido a los problemas t\u00e9cnicos que se registraron en el lanzamiento.<\/p>\n<p>Aquellos que demuestren de buena fe que no han podido contratar un seguro m\u00e9dico por los constantes problemas del portal de contrataci\u00f3n de seguros entre octubre y comienzos de diciembre, tendr\u00e1n hasta el 31 de marzo.<\/p>\n<p>Asimismo, aquellos que tengan un seguro m\u00e9dico privado que no cumpla los requisitos de la reforma sanitaria y est\u00e9n en riesgo de ver su p\u00f3liza cancelada no ser\u00e1n multados durante 2014, si no han conseguido contratar un nuevo seguro.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente estadounidense, Barack Obama, no ser\u00e1 una excepci\u00f3n y como un estadounidense m\u00e1s se inscribir\u00e1 antes de que termine el d\u00eda de hoy para poder tener cobertura medica desde el 1 de enero bajo las nuevas condiciones de la reforma que el mismo promovi\u00f3. Hoy, 23 de diciembre, finaliza el plazo para aquellos que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":891878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-45212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=45212"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45212\/revisions"}],"predecessor-version":[{"id":891915,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45212\/revisions\/891915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/891878"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=45212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=45212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=45212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}