{"id":45183,"date":"2014-12-05T00:00:00","date_gmt":"2014-12-05T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20141205\/arresto-en-caguas-por-agresion-sexual-y-maltrato-de-menores\/"},"modified":"2025-08-18T02:42:19","modified_gmt":"2025-08-18T02:42:19","slug":"arresto-en-caguas-por-agresion-sexual-y-maltrato-de-menores","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20141205\/arresto-en-caguas-por-agresion-sexual-y-maltrato-de-menores\/","title":{"rendered":"Arresto en Caguas por agresi\u00f3n sexual y maltrato de menores"},"content":{"rendered":"<p>Como Xiomara Merced Cartagena, de 36 a\u00f1os, y vecina del residencial Jardines de Condado Moderno, fue identificada una mujer que fue arrestada por los delitos de maltrato de menores y agresi\u00f3n sexual.<\/p>\n<p>De acuerdo con la agente Migdalia D\u00e1vila, adscrita a la Divisi\u00f3n de Delitos Sexuales de Caguas, la mujer permiti\u00f3 que Rafael De Jes\u00fas Pereira, de 46 a\u00f1os, y residente de la urbanizaci\u00f3n Villa Guadalupe, contra quien se radicaron denuncias en ausencia, cometiera un patr\u00f3n de agresi\u00f3n sexual contra su hija de 13 a\u00f1os desde que \u00e9sta ten\u00eda la edad de 10 a\u00f1os.<\/p>\n<p>De Jes\u00fas Pereira era padrastro de la menor, a la que mantuvo bajo amenaza hasta este a\u00f1o, cuando \u00e9sta qued\u00f3 embarazada de \u00e9l.<\/p>\n<p>La fiscal Melissa V\u00e1zquez ordeno la radicaci\u00f3n de cargos contra ambos. A De Jes\u00fas Pereira se le sometieron estos cargos en ausencia, ya que este fue citado y no compareci\u00f3. Un magistrado del Centro Judicial de Caguas encontr\u00f3 causa para arresto contra la pareja, imponi\u00e9ndole una fianza de 3,000 d\u00f3lares a la mujer, la que prest\u00f3; mientras que contra el sujeto expidi\u00f3 una orden de arresto con 100,000 d\u00f3lares de fianza.<\/p>","protected":false},"excerpt":{"rendered":"<p>Como Xiomara Merced Cartagena, de 36 a\u00f1os, y vecina del residencial Jardines de Condado Moderno, fue identificada una mujer que fue arrestada por los delitos de maltrato de menores y agresi\u00f3n sexual. De acuerdo con la agente Migdalia D\u00e1vila, adscrita a la Divisi\u00f3n de Delitos Sexuales de Caguas, la mujer permiti\u00f3 que Rafael De Jes\u00fas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":865164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-45183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=45183"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45183\/revisions"}],"predecessor-version":[{"id":865209,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45183\/revisions\/865209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/865164"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=45183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=45183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=45183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}