{"id":45156,"date":"2014-08-05T00:00:00","date_gmt":"2014-08-05T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20140805\/cangrejeras-le-arrebatan-el-campeonato-de-softbol-a-las-jueyeras\/"},"modified":"2025-08-18T07:25:25","modified_gmt":"2025-08-18T07:25:25","slug":"cangrejeras-le-arrebatan-el-campeonato-de-softbol-a-las-jueyeras","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20140805\/cangrejeras-le-arrebatan-el-campeonato-de-softbol-a-las-jueyeras\/","title":{"rendered":"Cangrejeras le arrebatan el campeonato de s\u00f3ftbol a las Jueyeras"},"content":{"rendered":"<p>Al borde de la eliminaci\u00f3n, 0-2, la superhero\u00edna de las Cangrejeras de Roosevelt, Karla &#8216;Super Girl&#8217; Claudio, se puso la capa y gan\u00f3 los siguientes tres encuentros para que las crust\u00e1ceas se coronaran como las nuevas campeonas de la Liga Superior Femenina de la Federaci\u00f3n de S\u00f3ftbol de Puerto Rico.<\/p>\n<p>Roosevelt venci\u00f3 en el quinto y decisivo choque, 7-6, a las Jueyeras de Maunabo, deteniendo la racha de cinco t\u00edtulos consecutivos del conjunto representativo de la ciudad de los t\u00faneles.<\/p>\n<p>Con el juego 2-0 a favor de Maunabo, Claudio peg\u00f3 cuadrangular de dos carreras para nivelar la pizarra en la parte alta de la sexta entrada. Acto seguido, Angie Nieves consigui\u00f3 un hit dentro del cuadro, Erika Col\u00f3n se embas\u00f3 por error a Galis Lozada, Mitchell Flores adelant\u00f3 a Nieves y a Col\u00f3n con un toque, y Yariam Rivera conect\u00f3 el sencillo que impuls\u00f3 a Nieves y a Col\u00f3n para las carreras de la ventaja definitiva, 4-2.<\/p>\n<p>Las Cangrejeras aumentaron su ventaja en el s\u00e9ptimo episodio, 7-2, con otras tres vueltas. Dichas anotaciones tambi\u00e9n fueron clave, ya que las Jueyeras no se iban a rendir tan f\u00e1cilmente y sacaron su cr\u00eda de campeonas en la tanda baja, donde marcaron en cuatro ocasiones, pero sin ser suficiente para evitar ver a la novena sanjuanera celebrar sobre el terreno del parque de Peque\u00f1as Ligas de Maunabo.<\/p>\n<p>Claudio, quien fue galardonada como la Jugadora M\u00e1s Valiosa, lanz\u00f3 las siete entradas, permitiendo 11 imparables, seis carreras, dos de ellas sucias y abanic\u00f3 a tres. Jocelyn De Le\u00f3n carg\u00f3 con el rev\u00e9s.<\/p><div class=\"notic-content-middle\" id=\"notic-3103993779\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Me quito el sombrero ante ella (Karla Claudio). Carg\u00f3 a la tropa anaranjada al t\u00edtulo. Hist\u00f3rico por dem\u00e1s&#8217;, manifest\u00f3 Carlos \u2018Cuso&#8217; Claudio, dirigente de las Cangrejeras en el primer cetro alcanzado por la franquicia en sus ocho a\u00f1os de existencia.<\/p>\n<p>Durante el primer doble choque, Maunabo logr\u00f3 defender con \u00e9xito su casa, tras triunfos de 4-2 y 13-10, coloc\u00e1ndose a tan solo una victoria adicional para repetir como campeonas, pero nunca lleg\u00f3.<\/p>\n<p>Roosevelt finaliz\u00f3 la serie regular con marca de 10-5, luego domin\u00f3 por el m\u00ednimo a las Bucaneras de Arroyo, 2-0, en los cuartos de final, y a las Capitanas de Arecibo, 3-0, en la semifinal.<\/p>\n<p>Su apoderada es Denise Cruz y Jos\u00e9 Otero su coapoderado.<\/p>\n<p>Las nuevas campeonas del s\u00f3ftbol superior recibir\u00e1n un homenaje este jueves, 7 de agosto, por parte de las Cangrejeras de Santurce del Baloncesto Superior Nacional Femenino (BSNF), previo al choque contra las Atenienses de Manat\u00ed en el coliseo Roberto Clemente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Al borde de la eliminaci\u00f3n, 0-2, la superhero\u00edna de las Cangrejeras de Roosevelt, Karla &#8216;Super Girl&#8217; Claudio, se puso la capa y gan\u00f3 los siguientes tres encuentros para que las crust\u00e1ceas se coronaran como las nuevas campeonas de la Liga Superior Femenina de la Federaci\u00f3n de S\u00f3ftbol de Puerto Rico. Roosevelt venci\u00f3 en el quinto [&hellip;]<\/p>","protected":false},"author":0,"featured_media":867141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-45156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=45156"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45156\/revisions"}],"predecessor-version":[{"id":867162,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/45156\/revisions\/867162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/867141"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=45156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=45156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=45156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}