{"id":44920,"date":"2012-05-15T00:00:00","date_gmt":"2012-05-15T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120515\/camion-volcado-en-la-kennedy-y-enormes-tapones\/"},"modified":"2025-08-27T07:46:19","modified_gmt":"2025-08-27T07:46:19","slug":"camion-volcado-en-la-kennedy-y-enormes-tapones","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120515\/camion-volcado-en-la-kennedy-y-enormes-tapones\/","title":{"rendered":"Cami\u00f3n volcado en la Kennedy y enormes tapones"},"content":{"rendered":"<p>Usuarios de Transito PR reportaron que un cami\u00f3n se volc\u00f3 a la altura del Parque Central en la Avenida Kennedy en direcci\u00f3n de San Juan a Bayam\u00f3n. La Avenida Kennedy ha sido cerrada y esto ha causado tapones gigantescos en las v\u00edas alternas.<\/p>\n<p>El accidente y cierre de la v\u00eda ha causado que el tr\u00e1fico est\u00e9 detenido enla salida de San Juan hacia la Kennedy, en direcci\u00f3n a Guaynabo, el expreso de las Am\u00e9ricas en ambas direcciones, pero con mayor congesti\u00f3n en la salida hacia Bayam\u00f3n, y la Mu\u00f1oz Rivera hacia Hato Rey.<\/p><div class=\"notic-content-middle\" id=\"notic-3253306119\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El tr\u00e1fico detenido incluye hasta la avenida Baldorioty de Castro, en ambas direcciones pero con mayor congesti\u00f3n en la salida al t\u00fanel Minillas hacia el expreso Las Am\u00e9ricas<\/p>\n<p>Los testigos indican que el conductor del cami\u00f3n est\u00e1 estable.<\/p>","protected":false},"excerpt":{"rendered":"<p>Usuarios de Transito PR reportaron que un cami\u00f3n se volc\u00f3 a la altura del Parque Central en la Avenida Kennedy en direcci\u00f3n de San Juan a Bayam\u00f3n. La Avenida Kennedy ha sido cerrada y esto ha causado tapones gigantescos en las v\u00edas alternas. El accidente y cierre de la v\u00eda ha causado que el tr\u00e1fico [&hellip;]<\/p>","protected":false},"author":0,"featured_media":917617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-44920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=44920"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44920\/revisions"}],"predecessor-version":[{"id":917623,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44920\/revisions\/917623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/917617"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=44920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=44920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=44920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}