{"id":44423,"date":"2013-11-12T00:00:00","date_gmt":"2013-11-12T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20131112\/telefonos-inteligentes-se-triplicaran-en-2019\/"},"modified":"2025-07-18T10:15:19","modified_gmt":"2025-07-18T10:15:19","slug":"telefonos-inteligentes-se-triplicaran-en-2019","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20131112\/telefonos-inteligentes-se-triplicaran-en-2019\/","title":{"rendered":"Tel\u00e9fonos inteligentes se triplicar\u00e1n en 2019"},"content":{"rendered":"<p>De acuerdo a las proyecciones, se espera que para el 2019 la cantidad de telefonos inteligentes se triplique para alcanzar los 5.6 billones a nivel mundial.<\/p>\n<p>Seg\u00fan un estudio de la compa\u00f1\u00eda de redes de telecomunicaciones m\u00e1s grande del mundo, Ericsson AB, la expectativa de crecimiento de estos aparatos seguir\u00e1 creciendo 10 veces en los pr\u00f3ximos 6 a\u00f1os.<\/p>\n<p>Ericsson asegur\u00f3 que el tr\u00e1fico anual de los m\u00f3viles inteligentes alcanzar\u00eda los 10 billones de gigabytes para 2019, con los videos representando el 50% de toda la data. Las redes sociales y servicios web alcanzar\u00edan un 10% de tr\u00e1fico.<\/p>\n<p>Seg\u00fan la compa\u00f1\u00eda rese\u00f1ada por <a href=\"http:\/\/www.usatoday.com\/story\/tech\/2013\/11\/11\/smartphones-forecast\/3496169\/\">USA Today<\/a>, los \u2018smartphones&#8217; representan el 55% de los celulares vendidos actualmente, pero son solo el 25 a 30% de las suscripciones m\u00f3viles.<\/p>","protected":false},"excerpt":{"rendered":"<p>De acuerdo a las proyecciones, se espera que para el 2019 la cantidad de telefonos inteligentes se triplique para alcanzar los 5.6 billones a nivel mundial. Seg\u00fan un estudio de la compa\u00f1\u00eda de redes de telecomunicaciones m\u00e1s grande del mundo, Ericsson AB, la expectativa de crecimiento de estos aparatos seguir\u00e1 creciendo 10 veces en los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-44423","post","type-post","status-publish","format-standard","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=44423"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44423\/revisions"}],"predecessor-version":[{"id":515534,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/44423\/revisions\/515534"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=44423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=44423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=44423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}