{"id":43327,"date":"2016-09-16T00:00:00","date_gmt":"2016-09-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20160916\/victor-mucho-mas-que-otra-pelicula-cristiana\/"},"modified":"2025-07-27T01:41:56","modified_gmt":"2025-07-27T01:41:56","slug":"victor-mucho-mas-que-otra-pelicula-cristiana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160916\/victor-mucho-mas-que-otra-pelicula-cristiana\/","title":{"rendered":"&#8216;V\u00edctor&#8217;, mucho m\u00e1s que otra pel\u00edcula cristiana"},"content":{"rendered":"<p>En pocas ocasiones podemos ver en la pantalla grande producciones de Hollywood con historias sobre la comunidad latina en los Estados Unidos en especial sobre puertorrique\u00f1os. Este es el caso con la pel\u00edcula V\u00edctor, debido a que nos brinda un vistazo a la lucha que ocurre cuando llegamos a un nuevo lugar, lleno de retos y decepciones, pero por medio de la familia y la fe, podemos conquistar el mundo.<\/p>\n<p>Esta nueva propuesta est\u00e1 basada en la vida del pastor puertorrique\u00f1o, V\u00edctor Torres, quien se muda a Brooklyn, Nueva York en los a\u00f1os sesenta con su familia en la b\u00fasqueda del sue\u00f1o americano. En este proceso entra al mundo de las pandillas y drogas a una joven edad, pareciendo ser el final de su vida.<\/p>\n<p>Dirigida por Brandon Dickerson nos lleva a Nueva York en unos tiempos fuertes, donde hacer de una vida honesta es dif\u00edcil. La producci\u00f3n es muy buena, en particular la m\u00fasica ya que son de los artistas originales.<\/p>\n<p>El elenco de V\u00edctor cuenta con la participaci\u00f3n de Patrick Davis (Secret in Their Eyes), Rick Gonz\u00e1lez (Old School), Lisa Vidal (Star Trek), Nick Eversman (Wild), Josh Pence (La La Land) y Jos\u00e9 Z\u00fa\u00f1iga (Twilight). Ellos hacen una excelente labor de brindar la alegr\u00eda y dolor de los hechos, adem\u00e1s de darle una oportunidad a esta nueva cepa de actores.<\/p><div class=\"notic-content-middle\" id=\"notic-1681556843\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Muchos al ver la promoci\u00f3n que se le est\u00e1 dando van a pensar que es otra pel\u00edcula cristiana, con el mismo mensaje, pero no se deje llevar por la etiqueta de pel\u00edcula cristiana ya que es un mensaje universal de amor y fe, que todos debemos aprender de esta lecci\u00f3n de vida y cualquiera puede caer, lo importante es levantarse y aprender de estas historias. En especial en estos tiempos, cuando la situaci\u00f3n econ\u00f3mica de la Isla no es la mejor y muchos han recurrido a irse en la b\u00fasqueda de un mejor futuro para la familia.<\/p>\n<p>V\u00edctor es tremenda pel\u00edcula para verla en familia. As\u00ed que aproveche para verla en la pantalla grande, para que sigan llegando propuestas con latinos como protagonistas.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre videojuegos y pel\u00edculas puedes visitar el portal <a href=\"http:\/\/pr-gamer.com\" target=\"_blank\">PR Gamer<\/a>y en las redes socialesFacebook y Twitter.<\/p>","protected":false},"excerpt":{"rendered":"<p>En pocas ocasiones podemos ver en la pantalla grande producciones de Hollywood con historias sobre la comunidad latina en los Estados Unidos en especial sobre puertorrique\u00f1os. Este es el caso con la pel\u00edcula V\u00edctor, debido a que nos brinda un vistazo a la lucha que ocurre cuando llegamos a un nuevo lugar, lleno de retos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":587278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-43327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/43327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=43327"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/43327\/revisions"}],"predecessor-version":[{"id":587294,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/43327\/revisions\/587294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/587278"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=43327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=43327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=43327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}