{"id":42664,"date":"2012-07-31T00:00:00","date_gmt":"2012-07-31T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120731\/desempleo-se-estabiliza-en-ue-pero-sigue-arriba-en-espana\/"},"modified":"2025-08-27T05:52:36","modified_gmt":"2025-08-27T05:52:36","slug":"desempleo-se-estabiliza-en-ue-pero-sigue-arriba-en-espana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120731\/desempleo-se-estabiliza-en-ue-pero-sigue-arriba-en-espana\/","title":{"rendered":"Desempleo se estabiliza en UE, pero sigue arriba en Espa\u00f1a"},"content":{"rendered":"<p>Bruselas &#8211; El desempleo se mantuvo en junio en sus niveles m\u00e1ximos hist\u00f3ricos tanto en la zona del euro como en el conjunto de la Uni\u00f3n Europea (UE), mientras que en Espa\u00f1a continu\u00f3 su escalada y alcanz\u00f3 el 24.8 %, la mayor tasa de los Veintisiete.<\/p>\n<p>El paro permaneci\u00f3 sin cambios en la zona del euro y en la UE con respecto a mayo, cuando lleg\u00f3 respectivamente al 11.2 % y al 10.4 %, las mayores cifras desde que en 1995 se empez\u00f3 a contabilizar la estad\u00edstica para los socios del euro, y desde 2000 para toda la Uni\u00f3n.<\/p>\n<p>La estabilizaci\u00f3n de la tasa de desempleo tiene lugar tras once meses de subidas continuadas en ambas zonas, seg\u00fan los datos difundidos hoy por la oficina comunitaria de estad\u00edstica, Eurostat, y que han sido corregidos seg\u00fan las variaciones estacionales y de calendario.<\/p>\n<p>En Espa\u00f1a, sin embargo, el paro mantuvo su tendencia al alza al crecer una d\u00e9cima y alcanzar el 24.8 %, la cifra m\u00e1s alta de los Veintisiete por delante de Grecia (22.5 %, seg\u00fan los \u00faltimos datos disponibles de abril).<\/p>\n<p>El paro afectaba en junio a unos 17.8 millones de personas en la zona del euro y a unos 25.1 millones en los Veintisiete, seg\u00fan los c\u00e1lculos de la oficina estad\u00edstica.<\/p>\n<p>En comparaci\u00f3n con el mes precedente, el desempleo aument\u00f3 en 123.000 personas en los pa\u00edses de la moneda \u00fanica y en 127,000 en el conjunto de la Uni\u00f3n.<\/p>\n<p>Un a\u00f1o antes, en junio de 2011, la tasa de desempleo era del 10 % en la zona euro y del 9.5 % en la UE.<\/p>\n<p>Durante los \u00faltimos doce meses, el n\u00famero de parados ha aumentado en 2.02 millones de personas en los pa\u00edses del euro y en 2.16 millones en los Veintisiete.<\/p>\n<p>Los pa\u00edses con menores tasas de desempleo fueron Austria, con el 4.5 %, Holanda (5.1 %), y Alemania y Luxemburgo (ambos con el 5.4 %).<\/p><div class=\"notic-content-middle\" id=\"notic-214170148\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>En comparaci\u00f3n con junio del a\u00f1o pasado, el desempleo cay\u00f3 en siete Estados miembros, subi\u00f3 en diecinueve y se mantuvo estable s\u00f3lo en uno, Suecia.<\/p>\n<p>Las mayores bajadas se dieron en los pa\u00edses b\u00e1lticos: Estonia, del 13.6 % al 10.9 % (seg\u00fan datos del primer trimestre), Letonia (del 17.1 % al 15.3 %), y Lituania (del 15.4 % al 13.7 %).<\/p>\n<p>Los aumentos m\u00e1s fuertes se observaron en Grecia (del 16.2 % al 22.5 %, seg\u00fan datos de abril), Espa\u00f1a (del 21.2 % al 24.8 %) y Chipre (del 7.6 % al 10.5 %).<\/p>\n<p>Por sexos, el desempleo entre los hombres subi\u00f3 1.5 puntos en con respecto a junio de 2011 y alcanz\u00f3 el 11.2 % en la zona del euro, mientras que en la UE aument\u00f3 un punto y alcanz\u00f3 el 10.4 % en la UE.<\/p>\n<p>Entre las mujeres, el paro registr\u00f3 una subida m\u00e1s moderada y alcanz\u00f3 el 11.3 % en los pa\u00edses de la moneda \u00fanica (un punto m\u00e1s que hace un a\u00f1o) y el 10.4 % en los Veintisiete (0.7 puntos m\u00e1s).<\/p>\n<p>En cuanto al paro juvenil, la tasa de desempleo entre los menores de 25 a\u00f1os descendi\u00f3 en junio una d\u00e9cima hasta el 22.4 % en la zona del euro, y baj\u00f3 en la misma medida en el conjunto de la UE, hasta el 22.6 %.<\/p>\n<p>Con respecto a junio de 2011, el desempleo juvenil aument\u00f3 1.9 puntos en los pa\u00edses de la moneda \u00fanica y 1.4 puntos en toda la Uni\u00f3n.<\/p>\n<p>Grecia registr\u00f3 la cifra m\u00e1s alta de los Veintisiete, con el 52.8 % (seg\u00fan datos de abril), mientras que Espa\u00f1a pas\u00f3 a ocupar la segunda posici\u00f3n con el 52.7 %, pese a su aumento de una d\u00e9cima sobre el mes precedente.<\/p>\n<p>Las tasas m\u00e1s bajas de desempleo juvenil se observaron en Alemania (7.9 %), Austria (8.8 %) y Holanda (9.3 %).<\/p>","protected":false},"excerpt":{"rendered":"<p>Bruselas &#8211; El desempleo se mantuvo en junio en sus niveles m\u00e1ximos hist\u00f3ricos tanto en la zona del euro como en el conjunto de la Uni\u00f3n Europea (UE), mientras que en Espa\u00f1a continu\u00f3 su escalada y alcanz\u00f3 el 24.8 %, la mayor tasa de los Veintisiete. El paro permaneci\u00f3 sin cambios en la zona del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":916622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-42664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/42664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=42664"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/42664\/revisions"}],"predecessor-version":[{"id":916653,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/42664\/revisions\/916653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/916622"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=42664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=42664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=42664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}