{"id":41663,"date":"2014-01-21T00:00:00","date_gmt":"2014-01-21T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/retiro\/20140121\/maestros-escucharan-hoy-las-razones-del-bgf-para-reformar-su-sistema-de-ret\/"},"modified":"2025-08-21T08:00:04","modified_gmt":"2025-08-21T08:00:04","slug":"maestros-escucharan-hoy-las-razones-del-bgf-para-reformar-su-sistema-de-ret","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140121\/maestros-escucharan-hoy-las-razones-del-bgf-para-reformar-su-sistema-de-ret\/","title":{"rendered":"Maestros escuchar\u00e1n hoy las razones del BGF para reformar su sistema de ret"},"content":{"rendered":"<p>Los l\u00edderes magisteriales y el gobierno se reunir\u00e1n hoy para escuchar una presentaci\u00f3n del Banco Gubernamental de Fomento (BGF) sobre todo el aspecto econ\u00f3mico del sistema de pensiones de los maestros, informaci\u00f3n que los maestros hab\u00edan solicitado desde antes que se aprobara la reforma y que se les deneg\u00f3.<\/p>\n<p>Esto, en medio de presuntas expresiones de los portavoces de la mayor\u00eda en el Senado y la C\u00e1mara de Representantes, An\u00edbal Jose Torres y Charlie Hern\u00e1ndez, durante el fin de semana en el sentido de que no le ven posibilidades a las enmiendas propuestas. La presidenta de la Asociaci\u00f3n de Maestros, Aida D\u00edaz, anticip\u00f3 hoy en la ma\u00f1ana que, ante dicha postura, que si no se logran los cambios los maestros podr\u00edan volver al paro.<\/p>\n<p>En la reuni\u00f3n le corresponde al sector gubernamental presentar toda la documentaci\u00f3n que han solicitado los maestros sobre la situaci\u00f3n fiscal y del Sistema de Retiro. Eso incluye un listado de maestros por preparaci\u00f3n y a\u00f1os de servicio y un informe del impacto de las medidas que se iban a tomar.<\/p>\n<p>Tambi\u00e9n los maestros solicitaron datos de cu\u00e1nto implicar\u00eda la recaudaci\u00f3n de un impuesto del 10% a los juegos de azar, propuesta que el magisterio present\u00f3 al gobierno, para capitalizar el sistema.<\/p>\n<p>&#8216;Despu\u00e9s nos toca a nosotros hacer una presentaci\u00f3n que incluya la importancia del retiro&#8217;, dijo la l\u00edder del grupo Educamos, Eva Ayala.<\/p>\n<p>Posteriormente, se har\u00e1 un an\u00e1lisis y se llegar\u00e1n a actuaciones y conclusiones.<\/p>\n<p>El Comit\u00e9 de Dialogo sobre el Sistema de Retiro de Maestros tuvo su primera reuni\u00f3n a dos d\u00edas luego de que el Tribunal Supremo emitiera un interdicto para paralizar la reforma del sistema de pensiones y tras dos d\u00edas de huelga magisterial. El gobernador Alejandro Garc\u00eda Padilla dijo que considerar\u00eda enmendar la ley, pero no revocarla.<\/p>\n<p>Seg\u00fan Ayala, el secretario de Estado, David Bernier, quien fuera designado como el mediador oficial del Gobierno en el comit\u00e9, uso la palabra &#8216;di\u00e1logo&#8217; todo el tiempo.<\/p>\n<p>&#8216;Tienen que negociar, sino que no nos hagan perder el tiempo&#8217;, sostuvo la l\u00edder.<\/p>\n<p>De otra parte, el l\u00edder de Educadores Puertorrique\u00f1os en Acci\u00f3n, Domingo Madera, se mostr\u00f3 confiado en que sean finalmente escuchados por el gobierno y que las reuniones culminen con una nueva ley y en la derogaci\u00f3n de la Ley 162. &#8216;Nosotros no estamos cerrados en llegar a un punto medio pero no puede ser a costa de los pobres maestros. Tambi\u00e9n queremos una soluci\u00f3n que no afecte al sistema educativo porque 7,000 maestros se pueden ir con la nueva ley&#8217;, dijo Madera.<\/p>\n<p>En el encuentro, se estableci\u00f3 una agenda de trabajo utilizando la metodolog\u00eda pedag\u00f3gica de Paulo Freyre de &#8216;ver, juzgar y escuchar&#8217;, algo propuesto por el Arzobispo de San Juan, Roberto Gonz\u00e1lez Nieves.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los l\u00edderes magisteriales y el gobierno se reunir\u00e1n hoy para escuchar una presentaci\u00f3n del Banco Gubernamental de Fomento (BGF) sobre todo el aspecto econ\u00f3mico del sistema de pensiones de los maestros, informaci\u00f3n que los maestros hab\u00edan solicitado desde antes que se aprobara la reforma y que se les deneg\u00f3. Esto, en medio de presuntas expresiones [&hellip;]<\/p>","protected":false},"author":0,"featured_media":884609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[78,2],"tags":[],"class_list":["post-41663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-retiro","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=41663"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41663\/revisions"}],"predecessor-version":[{"id":884642,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41663\/revisions\/884642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/884609"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=41663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=41663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=41663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}