{"id":41138,"date":"2012-05-28T00:00:00","date_gmt":"2012-05-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20120528\/con-nueva-presidenta-la-federacion-de-maestros\/"},"modified":"2025-08-27T09:58:14","modified_gmt":"2025-08-27T09:58:14","slug":"con-nueva-presidenta-la-federacion-de-maestros","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20120528\/con-nueva-presidenta-la-federacion-de-maestros\/","title":{"rendered":"Con nueva presidenta la Federaci\u00f3n de Maestros"},"content":{"rendered":"<p>La asamblea de miembros de la Federaci\u00f3n de Maestros de Puerto Rico confirm\u00f3 ayer a un nuevo Comit\u00e9 Ejecutivo que liderar\u00e1 al sindicato a partir del pr\u00f3ximo 1 de agosto. La nueva directiva est\u00e1 encabezada por la maestra de Artes Industriales de la Escuela Rafael Hern\u00e1ndez de Guaynabo, Elena Lara, quien sustituye a Rafael Feliciano en la presidencia.<\/p>\n<p>La reuni\u00f3n, que se realiz\u00f3 con la participaci\u00f3n de cerca de 300 miembros en el local de la Uni\u00f3n Independiente Aut\u00e9ntica (UIA), tambi\u00e9n ratific\u00f3 la selecci\u00f3n de Mar\u00eda Mel\u00e9ndez, para la vicepresidencia, Kathy Rivera Cardec, como secretaria tesorera, Miguel B\u00e1ez, como secretario de organizaci\u00f3n, y Luis \u00c1ngel Torres, como secretario de educaci\u00f3n sindical.<\/p>\n<p>Asimismo, se confirmaron 11 de los 13 funcionarios de \u00e1rea.<\/p>\n<p>Lara, educadora a nivel intermedio, esboz\u00f3 los tres asuntos principales a atender por el organismo. &#8216;En primer lugar, exigir justicia salarial para el magisterio. Los maestros estamos muy mal pagados en Puerto Rico y vamos a exigir un aumento. Seguiremos llevando nuestra propuesta de un aumento escalonado en el salario b\u00e1sico hasta llegar a $3,000&#8217;, indic\u00f3 en entrevista con NotiCel.<\/p>\n<p>En segundo lugar, mencion\u00f3 que busca reforzar la resistencia y la lucha por evitar el establecimiento de las escuelas charter en Puerto Rico, as\u00ed como cualquier intento de privatizaci\u00f3n de la educaci\u00f3n p\u00fablica.<\/p>\n<p>El tercer asunto que ocupar\u00e1 con mayor relevancia la agenda, ser\u00e1 la recuperaci\u00f3n de la representaci\u00f3n exclusiva de los maestros.<\/p><div class=\"notic-content-middle\" id=\"notic-787883196\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>La Federaci\u00f3n ya hab\u00eda presentado los endosos requeridos para competir con la Asociaci\u00f3n de Maestros en la elecci\u00f3n de la representaci\u00f3n exclusiva, sin embargo estos fueron rechazados.<\/p>\n<p>Presentaron entonces endosos a nombre de una filial denominada Federaci\u00f3n de Maestras y Maestros, los cuales tambi\u00e9n fueron rechazados por la Comisi\u00f3n a cargo de organizar el proceso, que se mantiene detenido mientras se eval\u00faan querellas presentadas por maestras federadas.<\/p>\n<p>Estas sostienen en sus alegaciones que en las pasadas elecciones sindicales, a la Federaci\u00f3n no se le permiti\u00f3 competir porque hab\u00eda sido descertificada por haber hecho un llamado a huelga, por lo que la misma reglamentaci\u00f3n deber\u00eda aplic\u00e1rsele a la Asociaci\u00f3n, que recientemente hizo un llamado al paro durante la pasada visita a la Isla del secretario de Educaci\u00f3n de Estados Unidos, Arne Duncan.<\/p>\n<p>Esas alegaciones se deber\u00e1n considerar en junio.<\/p>\n<p>El nuevo Comit\u00e9 Ejecutivo de la Federaci\u00f3n de Maestros de Puerto Rico entrar\u00e1 en funciones el 1 de agosto pr\u00f3ximo.<\/p>","protected":false},"excerpt":{"rendered":"<p>La asamblea de miembros de la Federaci\u00f3n de Maestros de Puerto Rico confirm\u00f3 ayer a un nuevo Comit\u00e9 Ejecutivo que liderar\u00e1 al sindicato a partir del pr\u00f3ximo 1 de agosto. La nueva directiva est\u00e1 encabezada por la maestra de Artes Industriales de la Escuela Rafael Hern\u00e1ndez de Guaynabo, Elena Lara, quien sustituye a Rafael Feliciano [&hellip;]<\/p>","protected":false},"author":0,"featured_media":918654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-41138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=41138"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41138\/revisions"}],"predecessor-version":[{"id":918695,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/41138\/revisions\/918695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/918654"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=41138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=41138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=41138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}