{"id":40779,"date":"2014-04-29T00:00:00","date_gmt":"2014-04-29T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140429\/benicio-se-une-a-campana-de-la-casa-blanca-contra-el-abuso-sexual\/"},"modified":"2025-08-19T07:01:09","modified_gmt":"2025-08-19T07:01:09","slug":"benicio-se-une-a-campana-de-la-casa-blanca-contra-el-abuso-sexual","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140429\/benicio-se-une-a-campana-de-la-casa-blanca-contra-el-abuso-sexual\/","title":{"rendered":"Benicio se une a campa\u00f1a de la Casa Blanca contra el abuso sexual"},"content":{"rendered":"<p>Los actores Benicio del Toro, Daniel Craig, Steve Carell, Seth Meyers y Dule Hill se convirtieron el martes en los rostros masculinos con los que la Casa Blanca busca cambiar la forma en la que EE.UU. afronta los abusos sexuales, al pedir en un v\u00eddeo a los hombres del pa\u00eds que sean &#8216;parte de la soluci\u00f3n&#8217;.<\/p>\n<p>El vicepresidente de EE.UU., Joe Biden, present\u00f3 durante un acto en la Casa Blanca el anuncio que se emitir\u00e1 a partir de mayo en cines de todo el pa\u00eds, como parte de una campa\u00f1a para &#8216;alentar a los hombres a decir algo y actuar si ven a alguien en peligro de sufrir asalto sexual&#8217;, indic\u00f3 la residencia presidencial en un comunicado.<\/p>\n<p>&#8216;Si ella no consiente (el acto sexual), o si no puede consentir, es una violaci\u00f3n, es un asalto&#8217;, dice el puertorrique\u00f1o Del Toro en el v\u00eddeo de 60 segundos publicado en la red YouTube.<\/p>\n<p>&#8216;Es un crimen, y est\u00e1 mal&#8217;, a\u00f1ade Carell, conocido por protagonizar la versi\u00f3n estadounidense de la serie televisiva &#8216;The Office&#8217;.<\/p>\n<p>Del Toro asegura entonces que, si viera c\u00f3mo sucede, &#8216;dir\u00eda algo&#8217;, mientras que el brit\u00e1nico Daniel Craig, famoso por su papel de James Bond en las \u00faltimas pel\u00edculas de la saga 007, agrega que, si presenciara un asalto sexual, &#8216;no la culpar\u00eda a ella, sino que la ayudar\u00eda&#8217;.<\/p>\n<p>&#8216;Depende de todos nosotros poner fin al asalto sexual. Y eso empieza con usted&#8217;, dice el presidente estadounidense, Barack Obama, al concluir el v\u00eddeo, en el que tambi\u00e9n aparece Biden.<\/p><div class=\"notic-content-middle\" id=\"notic-2826977357\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El anuncio forma parte de la campa\u00f1a &#8216;1 is 2 many&#8217; (&#8216;Una (v\u00edctima) son demasiadas&#8217;, que busca concienciar sobre un problema que provoca que una de cada cinco j\u00f3venes universitarias sufran abusos sexuales a lo largo de sus a\u00f1os de estudios o que una de cada nueve adolescentes del pa\u00eds sean violadas en su vida.<\/p>\n<p>&#8216;El mensaje es claro y simple: todo el mundo tiene una responsabilidad. No hay excepciones; no hay excusas. Por favor, vean este v\u00eddeo y dif\u00fandanlo&#8217;, dijo Craig en un comunicado.<\/p>\n<p>Para Del Toro, la campa\u00f1a consiste en &#8216;proteger y respetar a nuestros seres queridos: nuestras madres, hermanas, hijas, esposas y novias&#8217;.<\/p>\n<p>La Casa Blanca cre\u00f3 en enero un grupo de trabajo para proteger a los estudiantes de las agresiones sexuales, y hoy ese colectivo present\u00f3 un conjunto de recomendaciones dirigidas a combatir el problema en las universidades y una p\u00e1gina web, notalone.gov, para proporcionar apoyo a las v\u00edctimas e informaci\u00f3n a los estudiantes.<\/p>\n<p>&#8216;Las universidades no pueden seguir cerrando los ojos o fingir que las violaciones o los abusos sexuales no existen en sus campus&#8217;, sentenci\u00f3 hoy Biden en el acto en la Casa Blanca.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los actores Benicio del Toro, Daniel Craig, Steve Carell, Seth Meyers y Dule Hill se convirtieron el martes en los rostros masculinos con los que la Casa Blanca busca cambiar la forma en la que EE.UU. afronta los abusos sexuales, al pedir en un v\u00eddeo a los hombres del pa\u00eds que sean &#8216;parte de la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":871528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-40779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/40779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=40779"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/40779\/revisions"}],"predecessor-version":[{"id":871542,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/40779\/revisions\/871542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/871528"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=40779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=40779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=40779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}