{"id":39917,"date":"2011-03-29T00:00:00","date_gmt":"2011-03-29T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20110329\/cibercriminales-apuntan-a-secretos-empresariales\/"},"modified":"2025-07-15T05:01:14","modified_gmt":"2025-07-15T05:01:14","slug":"cibercriminales-apuntan-a-secretos-empresariales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20110329\/cibercriminales-apuntan-a-secretos-empresariales\/","title":{"rendered":"Cibercriminales apuntan a secretos empresariales"},"content":{"rendered":"<p>La propiedad intelectual y los secretos empresariales se est\u00e1n convirtiendo r\u00e1pidamente en el blanco de los cibercriminales, advierte un estudio. La investigaci\u00f3n de la empresa de seguridad McAfee encontr\u00f3 que algunos hackers maliciosos (o de sombrero negro) est\u00e1n comenzando a especializarse en datos robados de redes corporativas.<\/p>\n<p>McAfee dice que los criminales est\u00e1n vendiendo secretos de las empresas, planes de mercadotecnia, informes de investigaci\u00f3n y desarrollo, y c\u00f3digos fuente de programaci\u00f3n, publica BBC Tecnolog\u00eda.<\/p>\n<p>La firma pidi\u00f3 a las compa\u00f1\u00edas que vigilen qui\u00e9nes tienen acceso a sus datos cuando estos son trasladados a servicios en la nube (computadoras en internet) o a centros de almacenamiento digital de terceras compa\u00f1\u00edas.<\/p>\n<p>&#8216;Los cibercriminales tienen como objetivo la informaci\u00f3n que sus clientes les est\u00e1n pidiendo robar&#8217;, afirm\u00f3 Raj Samani, director de tecnolog\u00eda de McAfee en Europa.<\/p>\n<p>Samani asegur\u00f3 que los datos empresariales se han visto comprometidos desde hace tiempo dado que los criminales de la red utilizan virus y troyanos para buscar claves de acceso o informaci\u00f3n de tarjetas de cr\u00e9dito.<\/p>\n<p>La diferencia es que ahora existe un mercado \u00e1vido de comprar la informaci\u00f3n que ellos roban. En algunos casos, dijo Sumani, los ladrones realizan campa\u00f1as para infiltrarse en compa\u00f1\u00edas espec\u00edficas o conseguir determinado tipo de informaci\u00f3n.<\/p>\n<p>Los ladrones de propiedad intelectual o documentos clave pueden ser m\u00e1s dif\u00edciles de detectar, advirti\u00f3 el especialista.<\/p>\n<p>&#8216;Podr\u00edas no darte cuenta de que fue robado, porque a veces s\u00f3lo realizan copias&#8217;, afirm\u00f3.<\/p>\n<p>Defenderse de estas amenazas es cada vez m\u00e1s dif\u00edcil, asegur\u00f3 Samani, porque los empleados clave, con acceso a la informaci\u00f3n m\u00e1s valiosa, est\u00e1n en movimiento constante y utilizan dispositivos m\u00f3viles que se encuentran lejos de las defensas de las que disponen en su oficina.<\/p>\n<p>&#8216;Los tel\u00e9fonos inteligentes y las laptops est\u00e1n cruzado el per\u00edmetro de seguridad&#8217;, dijo.<\/p>\n<p>El informe de McAfee se difunde en un momento en el que han ocurrido una serie de incidentes que revelan c\u00f3mo los cibercriminales est\u00e1n adentr\u00e1ndose en nuevos territorios m\u00e1s all\u00e1 de los virus y los mensajes no deseados o spam.<\/p>","protected":false},"excerpt":{"rendered":"<p>La propiedad intelectual y los secretos empresariales se est\u00e1n convirtiendo r\u00e1pidamente en el blanco de los cibercriminales, advierte un estudio. La investigaci\u00f3n de la empresa de seguridad McAfee encontr\u00f3 que algunos hackers maliciosos (o de sombrero negro) est\u00e1n comenzando a especializarse en datos robados de redes corporativas. McAfee dice que los criminales est\u00e1n vendiendo secretos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":305395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-39917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=39917"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39917\/revisions"}],"predecessor-version":[{"id":305396,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39917\/revisions\/305396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/305395"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=39917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=39917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=39917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}