{"id":39895,"date":"2013-12-08T00:00:00","date_gmt":"2013-12-08T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/baloncesto\/deportes\/nba\/20131208\/nba-historica-humillacion-de-los-celtics-a-los-knicks-en-el-msg\/"},"modified":"2025-07-15T05:04:09","modified_gmt":"2025-07-15T05:04:09","slug":"nba-historica-humillacion-de-los-celtics-a-los-knicks-en-el-msg","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20131208\/nba-historica-humillacion-de-los-celtics-a-los-knicks-en-el-msg\/","title":{"rendered":"NBA: Hist\u00f3rica humillaci\u00f3n de los Celtics a los Knicks en el MSG"},"content":{"rendered":"<p>El alero Jordan Crawford anot\u00f3 23 puntos y volvi\u00f3 a ser hoy el l\u00edder del ataque balanceado de los Celtics de Boston que llegaron al Madison Square Garden y se impusieron por una aliza hist\u00f3rica de 73-114 a los Knicks de Nueva York.<\/p>\n<p>La derrota es la peor que han sufrido los Knicks en lo que va de temporada, la tercera m\u00e1s grave en la historia del equipo y la octava en su campo en lo que va de liga, despu\u00e9s que hab\u00edan conseguido salir moment\u00e1neamente de la crisis tras haber ganado dos partidos consecutivos.<\/p>\n<p>Los rumores de despido del entrenador de los Knicks, Mike Woodson, volvieron a surgir con fuerza, mientras que los Celtics, equipo en plena fase de reconstrucci\u00f3n, mejoran en su juego y son lideres destacados en la Divisi\u00f3n Atl\u00e1ntico aunque tengan marca perdedora de 10-12.<\/p>\n<p>Crawford, que anot\u00f3 seis triples y encabez\u00f3 una lista de seis jugadores que tuvieron n\u00fameros de dos d\u00edgitos, incluidos los cinco titulares, recibi\u00f3 el apoyo del ala-p\u00edvot Jared Sullinger, que logr\u00f3 21 puntos.<\/p>\n<p>Mientras que el ala-p\u00edvot Brandon Bass y el escolta-alero Jeff Green anotaron 16 puntos cada uno y el base-escolta Avery Bradley consigui\u00f3 un doble-doble de 13 puntos, 10 rebotes, dos asistencias y recuper\u00f3 un bal\u00f3n.<\/p>\n<p>El p\u00edvot novato brasile\u00f1o Vitor Faverani jug\u00f3 siete minutos en los que no hizo ning\u00fan tiro a canasta y captur\u00f3 dos rebotes.<\/p>\n<p>Los Celtics dominaron de principio a fin el partido al comenzarlo con parciales de 12-0, 18-1 y 25-3, respectivamente, en el primer periodo que dejaron sin opci\u00f3n a los Knicks que s\u00f3lo pudieron anotar 11 puntos por 34 del equipo de Boston.<\/p><div class=\"notic-content-middle\" id=\"notic-1207246697\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>En el resto del partido, los Knicks tampoco pudieron reaccionar y perdieron los parciales de los tres \u00faltimos periodos, incluido el segundo con el que llegaron al descanso con la ventaja de 27 puntos (31-58).<\/p>\n<p>El entrenador novato de los Celtics, Brad Stevens, reconoci\u00f3 que el gran triunfo de su equipo fue el salir en la segunda parte y mantener el mismo nivel de intensidad y concentraci\u00f3n en el juego.<\/p>\n<p>Los Celtics llegaron a tener hasta 45 puntos de ventaja y los 41 de diferencia en el marcador final es la mayor que se ha dado esta temporada en la NBA al superar los 38 que lograron los Clippers contra los Bulls de Chicago.<\/p>\n<p>El alero Carmelo Anthony aport\u00f3 19 puntos como m\u00e1ximo encestador de los Knicks, que siguen en el \u00faltimo lugar de la Divisi\u00f3n Atl\u00e1ntico.<\/p>\n<p>Mientras que el ala-p\u00edvot Amare Stoudemire como reserva logr\u00f3 17 puntos y el alero Metta World Peace, que sali\u00f3 tambi\u00e9n del banquillo, aport\u00f3 12 tantos.<\/p>\n<p>El base argentino Pablo Prigioni jug\u00f3 17 minutos y aport\u00f3 tres puntos al anotar el \u00fanico tiro que hizo a canasta, que fue un triple, reparti\u00f3 cuatro asistencias, captur\u00f3 un rebote y recuper\u00f3 un bal\u00f3n.<\/p>\n<p>Los Knicks concluyeron el partido con un 34 por ciento de acierto en los tiros de campo, comparados al 54 que tuvieron los Celtics.<\/p>","protected":false},"excerpt":{"rendered":"<p>El alero Jordan Crawford anot\u00f3 23 puntos y volvi\u00f3 a ser hoy el l\u00edder del ataque balanceado de los Celtics de Boston que llegaron al Madison Square Garden y se impusieron por una aliza hist\u00f3rica de 73-114 a los Knicks de Nueva York. La derrota es la peor que han sufrido los Knicks en lo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":305637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-39895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=39895"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39895\/revisions"}],"predecessor-version":[{"id":305640,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39895\/revisions\/305640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/305637"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=39895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=39895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=39895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}