{"id":39857,"date":"2014-12-22T00:00:00","date_gmt":"2014-12-22T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20141222\/la-infanta-cristina-sera-juzgada-en-caso-de-corrupcion\/"},"modified":"2025-07-15T05:07:38","modified_gmt":"2025-07-15T05:07:38","slug":"la-infanta-cristina-sera-juzgada-en-caso-de-corrupcion","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20141222\/la-infanta-cristina-sera-juzgada-en-caso-de-corrupcion\/","title":{"rendered":"La infanta Cristina ser\u00e1 juzgada en caso de corrupci\u00f3n"},"content":{"rendered":"<p>La infanta Cristina, hermana del rey Felipe VI de Espa\u00f1a, ser\u00e1 juzgada como presunta cooperadora en dos delitos fiscales de los que se acusa a su marido, I\u00f1aki Urdangarin.<\/p>\n<p>El juez instructor del llamado &#8216;caso N\u00f3os&#8217;, Jos\u00e9 Castro, la ha incluido como acusada en el auto de apertura de juicio oral que ha dictado hoy.<\/p>\n<p>En contra de los argumentos de la defensa de Cristina de Borb\u00f3n, la Fiscal\u00eda y la Abogac\u00eda del Estado, Castro consider\u00f3 que la acusaci\u00f3n popular que ejerce el sindicato Manos Limpias est\u00e1 legitimada para llevar a juicio en solitario a la hermana del Rey, para la que reclama ocho a\u00f1os de prisi\u00f3n.<\/p>\n<p>El caso, abierto en la Audiencia de Palma de Mallorca (Islas Baleares) investiga al Instituto N\u00f3os, una fundaci\u00f3n sin \u00e1nimo de lucro que presidi\u00f3 Urdangar\u00edn, a la que supuestamente se desviaron 6.1 millones de euros (unos 7.5 millones de d\u00f3lares) de fondos p\u00fablicos entre 2004 y 2007.<\/p>\n<p>La infanta Cristina y su esposo crearon la sociedad Aizoon, que compart\u00edan al 50 %, a la que presuntamente se desviaron los fondos il\u00edcitos, defraudando as\u00ed a la hacienda p\u00fablica.<\/p><div class=\"notic-content-middle\" id=\"notic-2506576937\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El juez instructor, en un auto contra el que seg\u00fan su criterio no cabe recurso, fija para Cristina de Borb\u00f3n una fianza por responsabilidad pecuniaria de 2.6 millones de euros (3.1 millones de d\u00f3lares).<\/p>\n<p>Castro rebate los argumentos de la defensa de la infanta, particularmente, los de la Fiscal\u00eda Anticorrupci\u00f3n, que presentaron escritos reclamando el sobreseimiento de la causa respecto a ella en aplicaci\u00f3n de la llamada doctrina Bot\u00edn, por la que no se llev\u00f3 a juicio al entonces presidente del Banco Santander, Emilio Bot\u00edn.<\/p>\n<p>Una de las razones esenciales del instructor es que en el caso en el que el Tribunal Supremo decret\u00f3 que la acusaci\u00f3n popular no estaba legitimada por s\u00ed sola para llevar a juicio al presidente del Banco de Santander, la Fiscal\u00eda y la Abogac\u00eda del Estado reclamaban el sobreseimiento de la causa, mientras que en el caso N\u00f3os s\u00f3lo lo solicitan para la infanta, no para otros acusados.<\/p>\n<p>En respuesta a los reproches del fiscal del caso, Pedro Horrach, sobre la supuesta indefensi\u00f3n de la infanta ante la actuaci\u00f3n de Castro, el juez asegura que &#8216;ninguna imputaci\u00f3n ha sido tan profusamente fundamentada&#8217;, y que de haber diferencia de trato ser\u00eda por haber sido con ella &#8216;incluso aun m\u00e1s garante que con los dem\u00e1s imputados.<\/p>\n<p>Adem\u00e1s de la infanta Cristina, otras 16 personas ser\u00e1n juzgadas por diferentes delitos en este proceso, ente ellas su esposo, I\u00f1aki Urdangar\u00edn, el socio de \u00e9ste, Diego Torres, y su esposa, y Jaume Matas, que fue presidente del gobierno regional de las Islas baleares y ministro de Medio Ambiente con Jos\u00e9 Mar\u00eda Aznar.<\/p>","protected":false},"excerpt":{"rendered":"<p>La infanta Cristina, hermana del rey Felipe VI de Espa\u00f1a, ser\u00e1 juzgada como presunta cooperadora en dos delitos fiscales de los que se acusa a su marido, I\u00f1aki Urdangarin. El juez instructor del llamado &#8216;caso N\u00f3os&#8217;, Jos\u00e9 Castro, la ha incluido como acusada en el auto de apertura de juicio oral que ha dictado hoy. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":305921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-39857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=39857"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39857\/revisions"}],"predecessor-version":[{"id":305922,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/39857\/revisions\/305922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/305921"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=39857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=39857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=39857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}