{"id":38095,"date":"2014-07-09T00:00:00","date_gmt":"2014-07-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140709\/arrestan-sujeto-por-caso-de-violencia-domestica-ocurrido-en-2005\/"},"modified":"2025-07-15T08:35:42","modified_gmt":"2025-07-15T08:35:42","slug":"arrestan-sujeto-por-caso-de-violencia-domestica-ocurrido-en-2005","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140709\/arrestan-sujeto-por-caso-de-violencia-domestica-ocurrido-en-2005\/","title":{"rendered":"Arrestan sujeto por caso de violencia dom\u00e9stica ocurrido en 2005"},"content":{"rendered":"<p>Agentes de la Unidad de Arrestos especiales del Cuerpo de Investigaciones Criminales (CIC) de Guayama arrestaron la ma\u00f1ana del martes en la urbanizaci\u00f3n Arroyo del Mar en Arroyo a un sujeto contra quien pesaba una orden de arresto por un incidente de violencia domestica ocurrido en julio de 2005.<\/p>\n<p>El informe policiaco indica que el arrestado fue identificado como Miguel Santiago Cora de 44 a\u00f1os y residente de la citada urbanizaci\u00f3n por haber cometido el art\u00edculo 3.2 de la Ley 54 de maltrato psicol\u00f3gico.<\/p>\n<p>La orden de arresto que enfrentaba el sujeto fue expedida en 2005 por el juez Francisco Ocasio con 20,000 d\u00f3lares de fianza, seg\u00fan indica el parte policiaco.<\/p><div class=\"notic-content-middle\" id=\"notic-2669968776\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Por otro lado, las autoridades detallaron que el d\u00eda de los hechos, Santiago Cora, destruy\u00f3 propiedad que era muy apreciada por la perjudicad, que no fue identificada. Estos hechos ocurrieron mientras exist\u00eda una orden de protecci\u00f3n en contra del imputado.<\/p>\n<p>La Polic\u00eda detall\u00f3 que Santiago Cora ser\u00eda llevado ante el juez de turno para leerle las advertencias y tomar la determinaci\u00f3n correspondiente. De prestar la fianza impuesta, quedar\u00eda en libertad y de lo contrario ser\u00eda llevado a una instituci\u00f3n carcelaria.<\/p>","protected":false},"excerpt":{"rendered":"<p>Agentes de la Unidad de Arrestos especiales del Cuerpo de Investigaciones Criminales (CIC) de Guayama arrestaron la ma\u00f1ana del martes en la urbanizaci\u00f3n Arroyo del Mar en Arroyo a un sujeto contra quien pesaba una orden de arresto por un incidente de violencia domestica ocurrido en julio de 2005. El informe policiaco indica que el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":319727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-38095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=38095"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38095\/revisions"}],"predecessor-version":[{"id":319729,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38095\/revisions\/319729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/319727"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=38095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=38095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=38095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}