{"id":38011,"date":"2014-03-14T00:00:00","date_gmt":"2014-03-14T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20140314\/obama-confia-en-solucion-diplomatica-a-la-crisis-en-ucrania\/"},"modified":"2025-07-15T08:43:14","modified_gmt":"2025-07-15T08:43:14","slug":"obama-confia-en-solucion-diplomatica-a-la-crisis-en-ucrania","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140314\/obama-confia-en-solucion-diplomatica-a-la-crisis-en-ucrania\/","title":{"rendered":"Obama conf\u00eda en soluci\u00f3n diplom\u00e1tica a la crisis en Ucrania"},"content":{"rendered":"<p>El presidente de EEUU, Barack Obama, dijo hoy que todav\u00eda conf\u00eda en una soluci\u00f3n diplom\u00e1tica a la crisis en Ucrania, a solo dos d\u00edas de que la rep\u00fablica aut\u00f3noma de Crimea celebre un polemico referendo sobre su incorporaci\u00f3n a Rusia.<\/p><div class=\"notic-content-middle\" id=\"notic-3804431224\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Obama habl\u00f3 al respecto tras recibir en la Casa Blanca al primer ministro irland\u00e9s, Enda Kenny, y volvi\u00f3 a advertir a Rusia de que habr\u00e1 &#8216;consecuencias&#8217; si &#8216;sigue violando&#8217; la soberan\u00eda de Ucrania.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de EEUU, Barack Obama, dijo hoy que todav\u00eda conf\u00eda en una soluci\u00f3n diplom\u00e1tica a la crisis en Ucrania, a solo dos d\u00edas de que la rep\u00fablica aut\u00f3noma de Crimea celebre un polemico referendo sobre su incorporaci\u00f3n a Rusia. Obama habl\u00f3 al respecto tras recibir en la Casa Blanca al primer ministro irland\u00e9s, Enda [&hellip;]<\/p>","protected":false},"author":0,"featured_media":320283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-38011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=38011"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38011\/revisions"}],"predecessor-version":[{"id":320285,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/38011\/revisions\/320285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/320283"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=38011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=38011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=38011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}