{"id":37573,"date":"2012-02-16T00:00:00","date_gmt":"2012-02-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20120216\/cosmonautas-rusos-pasean-por-el-espacio\/"},"modified":"2025-07-15T09:31:44","modified_gmt":"2025-07-15T09:31:44","slug":"cosmonautas-rusos-pasean-por-el-espacio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20120216\/cosmonautas-rusos-pasean-por-el-espacio\/","title":{"rendered":"Cosmonautas rusos pasean por el espacio"},"content":{"rendered":"<p>Mosc\u00fa &#8211; Los cosmonautas rusos Oleg Kononenko y Ant\u00f3n Shk\u00e1plerov, tripulantes de la Estaci\u00f3n Espacial Internacional (EEI), realizar\u00e1n hoy la primera caminata espacial del a\u00f1o, en el curso de la cual instalar\u00e1n paneles antimicrometeoritos adicionales en el casco de la plataforma.<\/p>\n<p>La apertura de la escotilla del m\u00f3dulo Pirs est\u00e1 prevista para las 14.15 GMT, informaron a Efe en el Centro de Control de Vuelos Espaciales (CCVE) de Rusia, que precis\u00f3 que los trabajos en el exterior de la EEI tendr\u00e1n una duraci\u00f3n de seis horas y tres minutos.<\/p>\n<p>Seg\u00fan el CCVE, los paneles antimicrometeoritos ser\u00e1n instalados en el exterior de un compartimento de trabajo del modulo de servicio ruso Zvezd\u00e1.<\/p><div class=\"notic-content-middle\" id=\"notic-3108353205\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El programa de labores de los cosmonautas incluye tambi\u00e9n el traslado de una gr\u00faa desde el m\u00f3dulo Pirs hasta el Poisk, ambos en el segmento ruso de la EEI.<\/p>\n<p>Adem\u00e1s, en caso de que el cumplimiento de las dos tareas principales deje tiempo suficiente, Kononeko y Shk\u00e1plerov realizar\u00e1n varios experimentos para estudiar el impacto de las condiciones espaciales y la radiaci\u00f3n c\u00f3smica tanto en el casco de la plataforma como en distintos materiales.<\/p>\n<p>Kononenko y Shk\u00e1plerov son miembros de la 30 expedici\u00f3n la misi\u00f3n permanente en la EEI, que integran tambi\u00e9n los estadounidenses Daniel Burbank y Donald Pettit y el holand\u00e9s Andr\u00e9 Kuipers, de la Agencia Espacial Europea.EFE<\/p>","protected":false},"excerpt":{"rendered":"<p>Mosc\u00fa &#8211; Los cosmonautas rusos Oleg Kononenko y Ant\u00f3n Shk\u00e1plerov, tripulantes de la Estaci\u00f3n Espacial Internacional (EEI), realizar\u00e1n hoy la primera caminata espacial del a\u00f1o, en el curso de la cual instalar\u00e1n paneles antimicrometeoritos adicionales en el casco de la plataforma. La apertura de la escotilla del m\u00f3dulo Pirs est\u00e1 prevista para las 14.15 GMT, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":323562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-37573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=37573"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37573\/revisions"}],"predecessor-version":[{"id":323564,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37573\/revisions\/323564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/323562"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=37573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=37573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=37573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}