{"id":37403,"date":"2016-08-26T00:00:00","date_gmt":"2016-08-26T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20160826\/anuncian-contrincante-de-monica-puig-para-inicio-del-us-open\/"},"modified":"2025-07-15T09:49:54","modified_gmt":"2025-07-15T09:49:54","slug":"anuncian-contrincante-de-monica-puig-para-inicio-del-us-open","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20160826\/anuncian-contrincante-de-monica-puig-para-inicio-del-us-open\/","title":{"rendered":"Anuncian contrincante de M\u00f3nica Puig para inicio del US Open"},"content":{"rendered":"<p>La tenista puertorrique\u00f1a M\u00f3nica Puig se enfrentar\u00e1 a la china Saisai Zheng en la primera ronda del Abierto de Estados Unidos.<\/p>\n<p>Puig entra al torneo en la posici\u00f3n 32 en la clasificaci\u00f3n de este Grand Slam, mientras que en el escalaf\u00f3n mundial se encuentra n\u00famero 34.<\/p>\n<p>El US Open comienza este lunes, 29 de agosto en Nueva York.<\/p>\n<p>El mejor resultado de Puig en el US Open fue en el 2014, al llegar a la segunda ronda, mientras que Zhengtambi\u00e9n lleg\u00f3 a la segunda ronda ese mismo a\u00f1o.<\/p>\n<p>Puig entra al torneo luego de lograr la primera medalla de oro en unas olimpiadas para el equipo dePuerto Rico. En su ruta a la victoria, la tenista boricuaelimin\u00f3 a jugadoras ganadoras de Grand Slams como Garbi\u00f1e Muguruza y Angelique Kerber.<\/p>\n<p>De ganar las primeras dos rondas, Puig pudiera enfrentarse en la tercera ronda con Muguruza, que en este torneo es clasificada como la n\u00famero tres.<\/p>","protected":false},"excerpt":{"rendered":"<p>La tenista puertorrique\u00f1a M\u00f3nica Puig se enfrentar\u00e1 a la china Saisai Zheng en la primera ronda del Abierto de Estados Unidos. Puig entra al torneo en la posici\u00f3n 32 en la clasificaci\u00f3n de este Grand Slam, mientras que en el escalaf\u00f3n mundial se encuentra n\u00famero 34. El US Open comienza este lunes, 29 de agosto [&hellip;]<\/p>","protected":false},"author":0,"featured_media":324677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-37403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=37403"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37403\/revisions"}],"predecessor-version":[{"id":324679,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/37403\/revisions\/324679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/324677"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=37403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=37403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=37403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}