{"id":35234,"date":"2014-02-10T00:00:00","date_gmt":"2014-02-10T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140210\/apelativo-confirma-sentencias-de-exalcalde-de-vega-baja-e-incendiario-de-fl\/"},"modified":"2025-07-15T12:48:20","modified_gmt":"2025-07-15T12:48:20","slug":"apelativo-confirma-sentencias-de-exalcalde-de-vega-baja-e-incendiario-de-fl","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140210\/apelativo-confirma-sentencias-de-exalcalde-de-vega-baja-e-incendiario-de-fl\/","title":{"rendered":"Apelativo confirma sentencias de exalcalde de Vega Baja e incendiario de Fl"},"content":{"rendered":"<p>Mediante resoluciones separadas de paneles distintos, el Tribunal de Apelaciones confirm\u00f3 las sentencias por corrupci\u00f3n del exalcalde de Vega Baja, Edgar Santana, y del asesino m\u00faltiple, Justino S\u00e1nchez D\u00edaz.<\/p>\n<p>Santana, representado por el licenciado Harry Padilla, defensor tambi\u00e9n del convicto por asesinato Pablo Casellas Toro, hab\u00eda alegado en su apelaci\u00f3n la comisi\u00f3n de varios errores. Pero el panel presidido por la jueza Emmalind Garc\u00eda Garc\u00eda, determin\u00f3 que los errores no fueron cometidos y que la prueba fue suficiente.<\/p>\n<p>&#8216;Considerados los testimonios resumidos al incio de este recurso y toda la prueba presentada en contra del se\u00f1or Santana, incluyendo la evidencia documental, no hallamos raz\u00f3n para intervenir con la apreciaci\u00f3n de la prueba efectuada por el jurado. En repetidas ocasiones hemos dicho que las determinaciones hechas por el juzgador de los hechos, en este caso un jurado, merecen deferencia a nivel apelativo&#8217;, dijo el panel.<\/p>\n<p>Santana cumple 18 a\u00f1os por un esquema de soborno mediante el que recibi\u00f3 $50,000.<\/p>\n<p>En el caso de S\u00e1nchez, \u00e9ste enfrenta 198 a\u00f1os de c\u00e1rcel por asesinar a seis familiares al incendiarlos durante una cena familiar el D\u00eda de A\u00f1o Nuevo de 2010 en el barrio Maldonado de Florida.<\/p><div class=\"notic-content-middle\" id=\"notic-2767391384\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Vea tambi\u00e9n:<\/p>\n<p><a href=\"http:\/\/noticel.com\/en\/noticia\/114927\/dictan-18-anos-de-carcel-a-santana.html\/\">Dictan 18 a\u00f1os de c\u00e1rcel a Santana<\/a><\/p>\n<p><a href=\"http:\/\/noticel.com\/en\/noticia\/110603\/dos-siglos-en-cemento-frio-para-el-incendiario-de-florida.html\/\">Dos siglos en cemento fr\u00edo para el incendiario de Florida<\/a><\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/23\/76fbfbb4f1f62394fa114785b60931d2_8213026_ver1.0.pdf\" target=\"_blank\"> Resoluci\u00f3n del Apelativo Pueblo v. Justino S\u00e1nchez &#8211; NotiCel_5586<\/a><\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2017\/08\/23\/aca509857a4fa355112c7af2b15bc4ad_8213028_ver1.0.pdf\" target=\"_blank\"> Resoluci\u00f3n del Apelativo Pueblo v. Edgar Santana &#8211; NotiCel_5587<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mediante resoluciones separadas de paneles distintos, el Tribunal de Apelaciones confirm\u00f3 las sentencias por corrupci\u00f3n del exalcalde de Vega Baja, Edgar Santana, y del asesino m\u00faltiple, Justino S\u00e1nchez D\u00edaz. Santana, representado por el licenciado Harry Padilla, defensor tambi\u00e9n del convicto por asesinato Pablo Casellas Toro, hab\u00eda alegado en su apelaci\u00f3n la comisi\u00f3n de varios errores. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":337890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-35234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/35234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=35234"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/35234\/revisions"}],"predecessor-version":[{"id":337891,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/35234\/revisions\/337891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/337890"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=35234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=35234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=35234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}