{"id":34294,"date":"2012-08-25T00:00:00","date_gmt":"2012-08-25T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20120825\/centrada-las-esperanzas-en-del-potro\/"},"modified":"2025-07-15T14:19:05","modified_gmt":"2025-07-15T14:19:05","slug":"centrada-las-esperanzas-en-del-potro","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120825\/centrada-las-esperanzas-en-del-potro\/","title":{"rendered":"Centrada las esperanzas en Del Potro"},"content":{"rendered":"<p>El tenista Juan Mart\u00edn del Potro es la principal esperanza del tenis sudamericano en el Abierto de Estados Unidos, \u00faltimo Grand Slam de la temporada, aunque el argentino tendr\u00e1 un complicado debut ante su compatriota David Nalbandian.<\/p>\n<p>El tenista de Tandil, que se alz\u00f3 con el t\u00edtulo en 2009, ofreci\u00f3 un gran rendimiento en los recientes Juegos Ol\u00edmpicos de Londres, donde tuvo contra las cuerdas a Roger Federer y bati\u00f3 en la lucha por la medalla de bronce al serbio Novak Djokovic.<\/p>\n<p>La cita ol\u00edmpica ha permitido al argentino, s\u00e9ptimo favorito en Flushing Meadows, recuperar las sensaciones que tuvo en 2009 y verse capaz de derrotar a los mejores, tras el calvario que supuso su lesi\u00f3n en la mu\u00f1eca que le dej\u00f3 fuera de las pistas en casi todo el 2010.<\/p>\n<p>En el Masters 1.000 de Cincinnati, Del Potro estuvo aquejado de nuevo por dolores, esta vez en su mu\u00f1eca izquierda, pero sus dudas quedaron despejadas antes de viajar a Nueva York, tras pasar por la Mayo Clinic, donde se hab\u00eda operado de la derecha.<\/p>\n<p>All\u00ed, tras visitar al cirujano Richard Berger y hacer una rehabilitaci\u00f3n, le constataron que estaba en condiciones de participar en el US Open.<\/p>\n<p>Sin embargo, &#8216;Delpo&#8217; no tendr\u00e1 un inicio de torneo c\u00f3modo para recobrar confianza, ya que tendr\u00e1 un duelo exigente ante Nalbandian, semifinalista en 2003, quien le ha derrotado en tres de los cuatro enfrentamientos previos entre ambos.<\/p>\n<p>En el caso de ir superando eliminatorias, se podr\u00eda encontrar en los cuartos de final con Novak Djokovic, vigente campe\u00f3n del torneo, que junto al suizo Roger Federer parten como principales candidatos al t\u00edtulo tras la ausencia por lesi\u00f3n del espa\u00f1ol Rafael Nadal, quienes sus problemas en la rodilla izquierda le han dejado fuera.<\/p><div class=\"notic-content-middle\" id=\"notic-3883448709\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El otro gran referente ser\u00e1 el tambi\u00e9n argentino Juan M\u00f3naco, d\u00e9cimo cabeza de serie del torneo, que debutar\u00e1 ante el espa\u00f1ol Guillermo Garc\u00eda-L\u00f3pez. &#8216;Pico&#8217; esta firmando un gran a\u00f1o, sobre todo en los torneos de tierra batida donde gan\u00f3 tres t\u00edtulos, lo que le llev\u00f3 el pasado mes de julio a formar parte del &#8216;top ten&#8217; por primera vez en su carrera.<\/p>\n<p>La expedici\u00f3n argentina es la m\u00e1s nutrida del tenis sudamericano con siete representantes, ya que a Del Potro, Nalbandian, M\u00f3naco, Leo Mayer y Carlos Berlocq, se han unido tras superar la fase de clasificaci\u00f3n Guido Pella y Guido Andreozzi, que debutar\u00e1n en el cuadro principal del \u00faltimo Grand Slam de la temporada.<\/p>\n<p>Ambos tendr\u00e1n en primera ronda un rival complicado, ya que Pella se enfrentar\u00e1 al ruso Nikolay Davydenko; mientras que Andreozzi se medir\u00e1 con el japon\u00e9s Kei Nishikori (17).<\/p>\n<p>Los colombianos Alejandro Falla y Santiago Giraldo buscar\u00e1n mejorar sus anteriores actuaciones en el torneo. Giraldo tratar\u00e1 de superar por primera vez la primera ronda y para ello deber\u00e1 derrotar al eslovaco Martin Klizan; mientras que su compatriota, que nunca ha pasado de segunda ronda, tiene un duro rival en el canadiense Milos Raonic.<\/p>\n<p>El tercer pa\u00eds sudamericano con participaci\u00f3n en el torneo es Brasil, con tres tenistas. Thomaz Bellucci se medir\u00e1 con el espa\u00f1ol Pablo Andujar, mientras que su compatriota Rogerio Dutra Silva jugar\u00e1 ante el ruso Teymuraz Gabashvili, proveniente de la fase previa.<\/p>\n<p>El veterano Felipe Mello ha conseguido finalmente entrar en el cuadro principal tras superar la fase de clasificaci\u00f3n, y su rival en la primera ronda tambi\u00e9n ser\u00e1 un jugador salido de la previa, el esloveno Grega Zemlja.<\/p>\n<p>En el cuadro femenino, las molestias f\u00edsicas de la argentina Gisela Dulko han dejado el torneo hu\u00e9rfano de representantes sudamericanas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El tenista Juan Mart\u00edn del Potro es la principal esperanza del tenis sudamericano en el Abierto de Estados Unidos, \u00faltimo Grand Slam de la temporada, aunque el argentino tendr\u00e1 un complicado debut ante su compatriota David Nalbandian. El tenista de Tandil, que se alz\u00f3 con el t\u00edtulo en 2009, ofreci\u00f3 un gran rendimiento en los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":345214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-34294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/34294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=34294"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/34294\/revisions"}],"predecessor-version":[{"id":345216,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/34294\/revisions\/345216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/345214"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=34294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=34294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=34294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}